{"id":45396,"date":"2025-09-12T07:19:22","date_gmt":"2025-09-12T07:19:22","guid":{"rendered":"https:\/\/www.donbosco.press\/?p=45396"},"modified":"2025-09-19T15:41:43","modified_gmt":"2025-09-19T15:41:43","slug":"o-veneravel-mons-stefano-ferrando","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/pt-pt\/nossos-santos\/o-veneravel-mons-stefano-ferrando\/","title":{"rendered":"O Vener\u00e1vel Mons. Stefano Ferrando"},"content":{"rendered":"<p><em>Monsenhor Stefano Ferrando foi um exemplo extraordin\u00e1rio de dedica\u00e7\u00e3o mission\u00e1ria e servi\u00e7o episcopal, unindo o carisma salesiano a uma voca\u00e7\u00e3o profunda ao servi\u00e7o dos mais pobres. Nascido em 1895 no Piemonte, entrou jovem na Congrega\u00e7\u00e3o Salesiana e, ap\u00f3s servir no ex\u00e9rcito durante a Primeira Guerra Mundial, o que lhe valeu a medalha de prata por valor, dedicou-se ao apostolado na \u00cdndia. Bispo de Krishnagar e depois de Shillong por mais de trinta anos, caminhou incansavelmente entre as popula\u00e7\u00f5es, promovendo a evangeliza\u00e7\u00e3o com humildade e profundo amor pastoral. Fundou institui\u00e7\u00f5es, apoiou os catequistas leigos e encarnou em sua vida o lema \u201cAp\u00f3stolo de Cristo\u201d. Sua vida foi um exemplo de f\u00e9, entrega a Deus e doa\u00e7\u00e3o total, deixando um legado espiritual que continua a inspirar a miss\u00e3o salesiana no mundo.<\/em><\/p>\n<p>O Vener\u00e1vel Bispo Dom Est\u00eav\u00e3o Ferrando soube conjugar a voca\u00e7\u00e3o salesiana com o carisma mission\u00e1rio e o minist\u00e9rio episcopal. Nascido em 28 de setembro de 1895, em Rossiglione (G\u00eanova, diocese de Acqui), filho de Agostinho e Josefina Salvi, distinguiu-se por um ardente amor a Deus e uma terna devo\u00e7\u00e3o \u00e0 Sant\u00edssima Virgem Maria. Em 1904, ingressou nas escolas salesianas, primeiramente em Fossano e depois em Turim-Valdocco, onde conheceu os sucessores de Dom Bosco e a primeira gera\u00e7\u00e3o de salesianos, e iniciou seus estudos sacerdotais; nesse meio tempo, alimentou o desejo de partir como mission\u00e1rio. Em 13 de setembro de 1912, fez sua primeira profiss\u00e3o religiosa na Congrega\u00e7\u00e3o Salesiana de Foglizzo. Convocado \u00e0s armas em 1915, participou da Primeira Guerra Mundial. Por sua coragem, recebeu a medalha de prata por bravura. Voltou para casa em 1918; emitiu seus votos perp\u00e9tuos em 26 de dezembro de 1920.<br \/>\nFoi ordenado sacerdote no Bairro S\u00e3o Martinho (Alessandria) em 18 de mar\u00e7o de 1923. Em 2 de dezembro do mesmo ano, com nove companheiros, embarcou em Veneza como mission\u00e1rio para a \u00cdndia. Em 18 de dezembro, ap\u00f3s 16 dias de viagem, o grupo chegou a Bombaim e, em 23 de dezembro, a Shillong, local de seu novo apostolado. Como mestre de novi\u00e7os, ele educou os jovens salesianos no amor de Jesus e Maria e tinha um grande esp\u00edrito de apostolado.<br \/>\nEm 9 de agosto de 1934, o Papa Pio XI o nomeou Bispo de Krishnagar. Seu lema era \u201cAp\u00f3stolo de Cristo\u201d. Em 26 de novembro de 1935, foi transferido para Shillong, onde permaneceu como bispo por 34 anos. Enquanto trabalhava em uma situa\u00e7\u00e3o dif\u00edcil de impacto cultural, religioso e social, o Bispo Dom Ferrando trabalhou incansavelmente para estar perto das pessoas que lhe foram confiadas, trabalhando com zelo na vasta diocese que abrangia toda a regi\u00e3o do nordeste da \u00cdndia. Ele preferia viajar a p\u00e9 em vez do carro, que teria \u00e0 sua disposi\u00e7\u00e3o: isso lhe permitia conhecer as pessoas, parar e conversar com elas, envolver-se em suas vidas. Esse contato ao vivo com a vida das pessoas foi um dos principais motivos da fecundidade de sua proclama\u00e7\u00e3o evang\u00e9lica: a humildade, a simplicidade e o amor pelos pobres levaram muitos a se converterem e a pedir o batismo. Ele fundou um semin\u00e1rio para a forma\u00e7\u00e3o de jovens salesianos indianos, construiu um hospital, ergueu um santu\u00e1rio dedicado a Maria Auxiliadora e fundou a primeira congrega\u00e7\u00e3o de irm\u00e3s aut\u00f3ctones, a Congrega\u00e7\u00e3o das Irm\u00e3s Mission\u00e1rias de Maria Auxiliadora (1942).<\/p>\n<p>Homem de car\u00e1ter forte, ele n\u00e3o desanimou diante das in\u00fameras dificuldades, que enfrentou com um sorriso e a mansid\u00e3o. A perseveran\u00e7a diante dos obst\u00e1culos era uma de suas principais caracter\u00edsticas. Ele procurou unir a mensagem do Evangelho \u00e0 cultura local na qual ela deveria ser inserida. Era intr\u00e9pido em suas visitas pastorais, que fazia aos lugares mais remotos da diocese, a fim de recuperar a \u00faltima ovelha perdida. Mostrou sensibilidade e promo\u00e7\u00e3o especiais para com os catequistas leigos, que considerava complementares \u00e0 miss\u00e3o do bispo e dos quais dependia grande parte da fecundidade da proclama\u00e7\u00e3o do Evangelho e de sua penetra\u00e7\u00e3o no territ\u00f3rio. Sua aten\u00e7\u00e3o ao trabalho de pastoral familiar tamb\u00e9m era imensa. Apesar de seus in\u00fameros compromissos, o Vener\u00e1vel era um homem com uma rica vida interior, alimentada pela ora\u00e7\u00e3o e pelo recolhimento. Como pastor, era apreciado por suas irm\u00e3s, sacerdotes, irm\u00e3os salesianos e no episcopado, bem como pelo povo, que o sentia profundamente pr\u00f3ximo a eles. Ele se doou de forma criativa ao seu rebanho, cuidando dos pobres, defendendo os intoc\u00e1veis, cuidando dos doentes de c\u00f3lera.<br \/>\nAs pedras angulares de sua espiritualidade eram o v\u00ednculo filial com a Virgem Maria, o zelo mission\u00e1rio, a refer\u00eancia cont\u00ednua a Dom Bosco, como se depreende de seus escritos e de toda a sua atividade mission\u00e1ria. O momento mais luminoso e heroico de sua vida virtuosa foi sua partida da diocese de Shillong. Dom Ferrando teve que apresentar sua ren\u00fancia ao Santo Padre quando ainda estava na plenitude de suas faculdades f\u00edsicas e intelectuais, para permitir a nomea\u00e7\u00e3o de seu sucessor, que deveria ser escolhido, de acordo com as instru\u00e7\u00f5es superiores, entre os sacerdotes aut\u00f3ctones que ele havia formado. Foi um momento particularmente doloroso, vivido pelo grande bispo com humildade e obedi\u00eancia. Ele entendeu que era hora de se retirar em ora\u00e7\u00e3o, de acordo com a vontade do Senhor.<br \/>\nRetornou a G\u00eanova em 1969 e continuou sua atividade pastoral, presidindo as cerim\u00f4nias de confirma\u00e7\u00e3o e dedicando-se ao sacramento da penit\u00eancia.<br \/>\nFoi fiel \u00e0 vida religiosa salesiana at\u00e9 o fim, decidindo viver em comunidade e renunciando aos privil\u00e9gios que sua posi\u00e7\u00e3o como bispo poderia ter-lhe reservado. Continuou a ser \u201cum mission\u00e1rio\u201d na It\u00e1lia. N\u00e3o \u201cum mission\u00e1rio que se desloca, mas [\u2026] um mission\u00e1rio que \u00e9. Sua vida nessa \u00faltima temporada tornou-se uma vida \u201cirradiante\u201d. Ele se tornou um \u201cmission\u00e1rio da ora\u00e7\u00e3o\u201d que dizia: \u201cEstou feliz por ter vindo embora para que outros pudessem me substituir e fazer obras t\u00e3o maravilhosas\u201d.<br \/>\nDe G\u00eanova Quarto, ele continuou a animar a miss\u00e3o em Assam, aumentando a conscientiza\u00e7\u00e3o e enviando ajuda financeira. Viveu essa hora de purifica\u00e7\u00e3o com esp\u00edrito de f\u00e9, de abandono \u00e0 vontade de Deus e de obedi\u00eancia, tocando com as pr\u00f3prias m\u00e3os o pleno significado da express\u00e3o evang\u00e9lica \u201csomos apenas servos in\u00fateis\u201d, e confirmando com sua vida o\u00a0<em>caetera tolle<\/em>, o aspecto oblativo-sacrifical da voca\u00e7\u00e3o salesiana. Morreu em 20 de junho de 1978 e foi sepultado em Rossiglione, sua terra natal. Em 1987, seus restos mortais foram levados de volta \u00e0 \u00cdndia.<\/p>\n<p>Na docilidade ao Esp\u00edrito, desenvolveu uma fecunda a\u00e7\u00e3o pastoral, que se manifestou no grande amor aos pobres, na humildade de esp\u00edrito e na caridade fraterna, na alegria e no otimismo do esp\u00edrito salesiano.<br \/>\nJunto com muitos mission\u00e1rios que compartilharam com ele a aventura do Esp\u00edrito na terra da \u00cdndia, entre os quais os Servos de Deus Francisco Convertini, Constantino Vendrame e Orestes Marengo, Dom Ferrando inaugurou um novo m\u00e9todo mission\u00e1rio: ser mission\u00e1rio itinerante. Esse exemplo \u00e9 um incentivo providencial, especialmente para as congrega\u00e7\u00f5es religiosas tentadas por um processo de institucionaliza\u00e7\u00e3o e fechamento, para que n\u00e3o percam a paix\u00e3o de ir ao encontro das pessoas e das situa\u00e7\u00f5es de maior pobreza e mis\u00e9ria material e espiritual, indo aonde ningu\u00e9m quer ir e confiando, como ele fez. \u201cOlho para o futuro com confian\u00e7a, confiando em Maria Auxiliadora\u2026 Vou me confiar a Maria Auxiliadora, que j\u00e1 me salvou de tantos perigos\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Monsenhor Stefano Ferrando foi um exemplo extraordin\u00e1rio de dedica\u00e7\u00e3o mission\u00e1ria e servi\u00e7o episcopal, unindo o&#8230;<\/p>\n","protected":false},"author":2,"featured_media":45387,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":3,"footnotes":""},"categories":[167],"tags":[2565,2561,2557,2570,1893,1923,2226,2228,2619],"class_list":["post-45396","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nossos-santos","tag-caridade","tag-carisma-salesiano","tag-deus","tag-igreja","tag-missoes","tag-paises","tag-salesianos","tag-santos","tag-testemunhos"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/posts\/45396","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/comments?post=45396"}],"version-history":[{"count":1,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/posts\/45396\/revisions"}],"predecessor-version":[{"id":45397,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/posts\/45396\/revisions\/45397"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/media\/45387"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/media?parent=45396"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/categories?post=45396"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/tags?post=45396"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}