{"id":35532,"date":"2025-03-15T07:45:43","date_gmt":"2025-03-15T07:45:43","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=35532"},"modified":"2025-03-15T07:48:08","modified_gmt":"2025-03-15T07:48:08","slug":"vera-grita-peregrina-de-esperanca","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/pt-pt\/nossos-santos\/vera-grita-peregrina-de-esperanca\/","title":{"rendered":"Vera Grita, peregrina de esperan\u00e7a"},"content":{"rendered":"\n<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Vera Grita, filha de Hamlet e de Maria Anna Zacco da Pirrera, nasceu em Roma no dia 28 de janeiro de 1923; era a segunda de quatro irm\u00e3s. Viveu e estudou em Savona, onde obteve a habilita\u00e7\u00e3o para o magist\u00e9rio. Aos 21 anos, durante uma repentina incurs\u00e3o a\u00e9rea sobre a cidade (1944), foi atropelada e pisoteada pela multid\u00e3o em fuga, sofrendo graves consequ\u00eancias para seu corpo, que a partir de ent\u00e3o ficou marcado para sempre pelo sofrimento. Passou despercebida em sua breve vida terrena, ensinando nas escolas do interior da Lig\u00faria (Rialto, Erli, Alpicella, Deserto de Varazze), onde conquistou a estima e o afeto de todos por seu car\u00e1ter bondoso e manso.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Em Savona, na par\u00f3quia salesiana de Maria Auxiliadora, participava da Missa e era ass\u00eddua ao sacramento da Penit\u00eancia. Desde 1963, seu confessor era o salesiano P. Jo\u00e3o Bocchi. Salesiana Cooperadora desde 1967, realizou sua voca\u00e7\u00e3o no dom total de si ao Senhor, que de maneira extraordin\u00e1ria se doava a ela, no \u00edntimo de seu cora\u00e7\u00e3o, com a \u201cVoz\u201d, com a \u201cPalavra\u201d, para comunicar-lhe a Obra dos Tabern\u00e1culos Vivos. Submeteu todos os escritos ao diretor espiritual, o salesiano P. Gabriel Zucconi, e guardou no sil\u00eancio de seu cora\u00e7\u00e3o o segredo daquela voca\u00e7\u00e3o, guiada pelo divino Mestre e pela Virgem Maria que a acompanharam ao longo do caminho da vida oculta, do despojamento e do aniquilamento de si.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Sob o impulso da gra\u00e7a divina e acolhendo a media\u00e7\u00e3o dos guias espirituais, Vera Grita respondeu ao dom de Deus, testemunhando em sua vida, marcada pelo sofrimento da doen\u00e7a, o encontro com o Ressuscitado e dedicando-se com heroica generosidade ao ensino e \u00e0 educa\u00e7\u00e3o dos alunos, suprindo as necessidades da fam\u00edlia e testemunhando uma vida de pobreza evang\u00e9lica. Centrada e firme no Deus que ama e sustenta, com grande firmeza interior, foi capaz de suportar as provas e os sofrimentos da vida. Com base nessa solidez interior, deu testemunho de uma exist\u00eancia crist\u00e3 feita de paci\u00eancia e const\u00e2ncia no bem.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Morreu no dia 22 de dezembro de 1969, aos 46 anos, em um quartinho do hospital em Pietra L\u00edgure, onde havia passado os \u00faltimos seis meses de vida em um crescendo de sofrimentos aceitos e vividos em uni\u00e3o com Jesus Crucificado. \u201cA alma de Vera \u2013 escreveu o P. Borra, Salesiano, seu primeiro bi\u00f3grafo \u2013 com as mensagens e as cartas entra na fileira daquelas almas carism\u00e1ticas chamadas a enriquecer a Igreja com chamas de amor a Deus e a Jesus Eucar\u00edstico para a dilata\u00e7\u00e3o do Reino\u201d.<br><br><strong>Uma vida privada das esperan\u00e7as humanas<br><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Humanamente, a vida de Vera \u00e9 marcada desde a inf\u00e2ncia pela perda de um horizonte de esperan\u00e7a. A perda da autonomia econ\u00f4mica em seu n\u00facleo familiar, portanto, o afastamento dos pais para ir a M\u00f3dica, na Sic\u00edlia, com as tias e, sobretudo, a morte do pai em 1943, colocam Vera diante das consequ\u00eancias de eventos humanos particularmente sofridos. Ap\u00f3s o dia 4 de julho de 1944, dia do bombardeio sobre Savona que marcar\u00e1 toda a vida de Vera, suas condi\u00e7\u00f5es de sa\u00fade tamb\u00e9m estar\u00e3o comprometidas para sempre. Por isso, a Serva de Deus se viu jovem sem qualquer perspectiva de futuro e teve que, em v\u00e1rias ocasi\u00f5es, rever seus projetos e renunciar a muitos desejos: dos estudos universit\u00e1rios ao ensino e, sobretudo, a uma pr\u00f3pria fam\u00edlia com o jovem com quem estava namorando. Apesar do fim repentino de todas as suas esperan\u00e7as humanas entre 20 e 21 anos, a esperan\u00e7a est\u00e1 muito presente em Vera: tanto como uma virtude humana que acredita em uma mudan\u00e7a poss\u00edvel e se empenha para realiz\u00e1-la (mesmo muito doente, preparou e venceu o concurso para lecionar), quanto, sobretudo, como uma virtude teologal \u2013 ancorada na f\u00e9 \u2013 que lhe infunde energia e se torna um instrumento de consola\u00e7\u00e3o para os outros.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Quase todas as testemunhas que a conheceram ressaltam tal aparente contradi\u00e7\u00e3o entre condi\u00e7\u00f5es de sa\u00fade comprometidas e a capacidade de nunca se queixar, atestando, em vez disso, alegria, esperan\u00e7a e coragem mesmo em circunst\u00e2ncias humanamente desesperadoras. Vera se tornou \u201cportadora de alegria\u201d.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Uma sobrinha afirma<\/strong>: \u00abEla estava sempre doente e sofrendo, mas nunca a vi desanimada ou enraivecida por sua condi\u00e7\u00e3o; sempre tinha uma luz de esperan\u00e7a sustentada pela grande f\u00e9. [\u2026] Minha tia estava frequentemente internada no hospital, sofrida e fr\u00e1gil, mas sempre serena e cheia de esperan\u00e7a pelo grande Amor que tinha por Jesus\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Tamb\u00e9m a irm\u00e3 Liliana<\/strong> tirou, dos telefonemas vespertinos com ela, encorajamento, serenidade e esperan\u00e7a, embora a Serva de Deus estivesse ent\u00e3o sobrecarregada por numerosos problemas de sa\u00fade e por v\u00ednculos profissionais: \u00abela me infundia \u2013 diz \u2013 confian\u00e7a e esperan\u00e7a, fazendo-me refletir que Deus est\u00e1 sempre perto de n\u00f3s e nos conduz. Suas palavras me traziam de volta aos bra\u00e7os do Senhor e eu encontrava a paz\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 In\u00eas Zannino Tibirosa, cujo testemunho \u00e9 de particular valor pois visitou assiduamente Vera no hospital \u201cSanta Corona\u201d em seu \u00faltimo ano de vida, atesta: \u00abapesar das graves dores que a doen\u00e7a lhe causava, nunca a ouvi reclamar de seu estado. Ela aliviava e dava esperan\u00e7a a todos que se aproximavam e, quando falava de seu futuro, o fazia com entusiasmo e coragem\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 At\u00e9 o final, Vera Grita se manteve assim: mesmo na \u00faltima parte de seu caminho terreno, guardou um olhar para o futuro, esperava que com os tratamentos o tuberculoma pudesse ser reabsorvido, esperava poder ocupar a c\u00e1tedra nos Piani di Invrea no ano letivo de 1969-1970, assim como se dedicar \u00e0 sua miss\u00e3o espiritual, logo que sa\u00edsse do hospital.<br><br><strong>Educada na esperan\u00e7a e no caminho espiritual pelo confessor<br><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nesse sentido, a esperan\u00e7a atestada por Vera est\u00e1 enraizada em Deus e naquela leitura sapiencial dos eventos que seu guia espiritual, o P. Gabriel Zucconi, e, antes dele, o confessor, P. Jo\u00e3o Bocchi, lhe ensinaram. Precisamente o minist\u00e9rio do P. Bocchi \u2013 homem de alegria e esperan\u00e7a \u2013 exerceu uma influ\u00eancia positiva sobre Vera, que ele acolheu em sua condi\u00e7\u00e3o de doente e a quem ensinou a dar valor aos sofrimentos \u2013 n\u00e3o buscados \u2013 dos quais estava sobrecarregada. Antes de tudo, o P. Bocchi foi mestre de esperan\u00e7a; dele se disse: \u00abcom palavras sempre cordiais e cheias de esperan\u00e7a, ele abriu os cora\u00e7\u00f5es \u00e0 magnanimidade, ao perd\u00e3o, \u00e0 transpar\u00eancia nas rela\u00e7\u00f5es interpessoais; viveu as bem-aventuran\u00e7as com naturalidade e fidelidade di\u00e1ria\u00bb.<br>\u00abEsperando e tendo a certeza de que, como aconteceu com Cristo, tamb\u00e9m acontecer\u00e1 conosco: a Ressurrei\u00e7\u00e3o gloriosa\u00bb, o P. Bocchi realizava, atrav\u00e9s de seu minist\u00e9rio, um an\u00fancio da esperan\u00e7a crist\u00e3, fundamentada na onipot\u00eancia de Deus e na ressurrei\u00e7\u00e3o de Cristo. Mais tarde, da \u00c1frica, para onde partiu como mission\u00e1rio, dir\u00e1: \u00abestava l\u00e1 porque queria levar e doar a eles Jesus Vivo e presente na Sant\u00edssima Eucaristia com todos os dons de Seu Cora\u00e7\u00e3o: a Paz, a Miseric\u00f3rdia, a Alegria, o Amor, a Luz, a Uni\u00e3o, a Esperan\u00e7a, a Verdade, a Vida eterna\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Vera se tornou portadora de esperan\u00e7a e de alegria tamb\u00e9m em ambientes marcados pelo sofrimento f\u00edsico e moral, por limita\u00e7\u00f5es cognitivas (como entre seus pequenos alunos com defici\u00eancia auditiva) ou condi\u00e7\u00f5es familiares e sociais n\u00e3o ideais (como no \u201cclima escaldante\u201d de Erli).<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>A amiga Maria Mattalia<\/strong> recorda: \u00abVejo o doce sorriso de Vera, \u00e0s vezes cansado por tanto lutar e sofrer; lembrando sua for\u00e7a de vontade, busco seguir seu exemplo de bondade, de grande f\u00e9, esperan\u00e7a e amor [\u2026]\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Antonieta Fazio<\/strong> \u2013 ex-zeladora da escola de Casanova \u2013 testemunhou sobre ela: \u00abera muito querida por seus alunos, que amava muito, e em particular por aqueles com dificuldades intelectuais [\u2026]. Muito religiosa, transmitia a cada um f\u00e9 e esperan\u00e7a, embora ela mesma estivesse sofrendo muito fisicamente, mas n\u00e3o abatida moralmente\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nesses contextos, Vera trabalhava para fazer renascer as raz\u00f5es da esperan\u00e7a. Por exemplo, no hospital (onde a comida \u00e9 pouco satisfat\u00f3ria) ela se privou de um cacho especial de uvas para deixar uma parte no criado-mudo de todas as doentes do quarto, assim como sempre cuidou de sua apar\u00eancia para se apresentar bem, em ordem, com compostura e refinamento, contribuindo assim para combater o ambiente de sofrimento de uma cl\u00ednica, e \u00e0s vezes a perda da esperan\u00e7a em muitos doentes que correm o risco de \u201cse deixar levar\u201d.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Atrav\u00e9s das <strong>Mensagens da Obra dos Tabern\u00e1culos Vivos<\/strong>, o Senhor a educou a uma postura de espera, paci\u00eancia e confian\u00e7a nele. Incont\u00e1veis s\u00e3o, de fato, as exorta\u00e7\u00f5es sobre <em>esperar o Esposo ou o Esposo que espera sua esposa<\/em>:<br><br><em>\u201cEspere em seu Jesus sempre, sempre.<br><br>Que Ele venha \u00e0s nossas almas, venha \u00e0s nossas casas; venha conosco para compartilhar alegrias e tristezas, cansa\u00e7os e esperan\u00e7as.<br><br>Deixe meu Amor agir e aumente sua f\u00e9, sua esperan\u00e7a.<br><br>Siga-me na escurid\u00e3o, nas sombras porque voc\u00ea conhece o \u00abcaminho\u00bb.<br><br>Espere em Mim, espere em Jesus!<br><br>Ap\u00f3s o caminho da esperan\u00e7a e da espera, haver\u00e1 a vit\u00f3ria.<br><br>Para cham\u00e1-los \u00e0s coisas do C\u00e9u\u201d<\/em>.<br><br><strong>Portadora de esperan\u00e7a ao morrer e ao interceder<br><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mesmo na doen\u00e7a e na morte, Vera Grita testemunhou a esperan\u00e7a crist\u00e3.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Sabia que, quando sua miss\u00e3o estivesse cumprida, tamb\u00e9m a vida na terra teria terminado. \u00abEsta \u00e9 a sua tarefa e quando estiver terminada voc\u00ea se despedir\u00e1 da terra para os C\u00e9us\u00bb: por isso n\u00e3o se sentia \u201cpropriet\u00e1ria\u201d do tempo, mas buscava a obedi\u00eancia \u00e0 vontade de Deus.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nos \u00faltimos meses, apesar de uma condi\u00e7\u00e3o agravante e exposta a um piora do quadro cl\u00ednico, a Serva de Deus atestou serenidade, paz, percep\u00e7\u00e3o interior de um \u201ccumprimento\u201d de sua vida.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Nos \u00faltimos dias, embora estivesse naturalmente apegada \u00e0 vida, o P. Jos\u00e9 Formento a descreveu \u00abj\u00e1 em paz com o Senhor\u00bb. Nesse esp\u00edrito, p\u00f4de receber a Comunh\u00e3o at\u00e9 poucos dias antes de morrer, e receber a Un\u00e7\u00e3o dos Enfermos no dia 18 de dezembro.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Quando a irm\u00e3 Pina a visitou pouco antes da morte \u2013 Vera estava h\u00e1 cerca de tr\u00eas dias em coma \u2013 desobedecendo ao seu habitual recato, disse-lhe que havia visto muitas coisas, coisas bel\u00edssimas que, infelizmente, n\u00e3o tinha tempo de contar. Soube das ora\u00e7\u00f5es do Padre Pio e do Papa Bom por ela, al\u00e9m de acrescentar \u2013 referindo-se \u00e0 Vida eterna \u2013 \u00abTodos voc\u00eas vir\u00e3o para o para\u00edso comigo, tenham certeza disso\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <strong>Liliana Grita<\/strong> tamb\u00e9m testemunhou como, no \u00faltimo per\u00edodo, Vera \u00absabia mais do C\u00e9u do que da terra\u00bb. Da sua vida foi feito o seguinte balan\u00e7o: \u00abela, t\u00e3o sofredora, consolava os outros, infundindo-lhes esperan\u00e7a e n\u00e3o hesitava em ajud\u00e1-los\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Muitas gra\u00e7as atribu\u00eddas \u00e0 media\u00e7\u00e3o intercessora de Vera dizem respeito, por fim, \u00e0 esperan\u00e7a crist\u00e3. Vera \u2013 mesmo durante a Pandemia de Covid 19 \u2013 ajudou muitos a reencontrar as raz\u00f5es da esperan\u00e7a e foi para eles prote\u00e7\u00e3o, irm\u00e3 no esp\u00edrito, ajuda no sacerd\u00f3cio. Ajudou interiormente um sacerdote que, ap\u00f3s um AVC, havia esquecido as ora\u00e7\u00f5es, n\u00e3o conseguindo mais pronunci\u00e1-las com sua extrema dor e desorienta\u00e7\u00e3o. Fez com que muitos voltassem a rezar, pedindo a cura de um jovem pai atingido por uma hemorragia.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tamb\u00e9m a <strong>Irm\u00e3 Maria Hil\u00e1ria Bossi<\/strong>, Mestra das Novi\u00e7as das Beneditinas do Sant\u00edssimo Sacramento de Ghiffa, observa como Vera \u2013 irm\u00e3 no esp\u00edrito \u2013 \u00e9 uma alma que direciona ao C\u00e9u e acompanha em dire\u00e7\u00e3o ao C\u00e9u: \u00abSinto-a irm\u00e3 no caminho para o c\u00e9u\u2026 Muitos [\u2026] que se reconhecem nela, e a ela se referem, no caminho evang\u00e9lico, na corrida em dire\u00e7\u00e3o ao c\u00e9u\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Em s\u00edntese, compreende-se como toda a hist\u00f3ria de Vera Grita foi sustentada n\u00e3o por esperan\u00e7as humanas, pelo mero olhar para o \u201camanh\u00e3\u201d, esperando que fosse melhor que o presente, mas por uma verdadeira Esperan\u00e7a teologal: \u00abela era serena porque a f\u00e9 e a esperan\u00e7a sempre a sustentaram. Cristo estava no centro de sua vida, dele ela tirava a for\u00e7a. [\u2026] era uma pessoa serena porque tinha no cora\u00e7\u00e3o a Esperan\u00e7a teologal, n\u00e3o a esperan\u00e7a superficial [\u2026], mas aquela que deriva somente de Deus, que \u00e9 dom e nos prepara para o encontro com Ele\u00bb.<br><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Numa ora\u00e7\u00e3o a Maria da Obra dos Tabern\u00e1culos Vivos, l\u00ea-se: \u00abLevante-nos [Maria] da terra para que aqui vivamos e sejamos para o C\u00e9u, para o Reino do seu Filho\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00c9 bonito tamb\u00e9m lembrar que o <strong>P. Gabriel<\/strong> teve que peregrinar na esperan\u00e7a entre tantas provas e dificuldades, como escreve em uma carta a Vera de 4 de mar\u00e7o de 1968 de Floren\u00e7a: \u00abNo entanto, devemos sempre esperar. A presen\u00e7a das dificuldades n\u00e3o impede que, no final, o bem, o bom, o belo triunfem. A paz, a ordem, a alegria retornar\u00e3o. O homem filho de Deus recuperar\u00e1 toda a gl\u00f3ria que teve desde o princ\u00edpio. O homem ser\u00e1 salvo em Jesus e encontrar\u00e1 em Deus todo o bem. Ent\u00e3o, v\u00eam \u00e0 mente todas as coisas belas prometidas por Jesus e a alma nele encontra sua paz. Coragem: agora estamos como em combate. Vir\u00e1 o dia da vit\u00f3ria. Essa \u00e9 a certeza em Deus\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Na igreja de <em>Santa Corona<\/em> em Pietra L\u00edgure, Vera Grita participava da Missa e ia rezar durante os longos internamentos. Seu testemunho de f\u00e9 na presen\u00e7a viva de Jesus Eucar\u00edstico e da Virgem Maria em sua breve vida terrena \u00e9 um sinal de esperan\u00e7a e de conforto, para aqueles que neste lugar de cura pedirem sua ajuda e sua intercess\u00e3o junto ao Senhor para serem aliviados e libertados do sofrimento.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 O caminho de Vera Grita na cansativa labuta dos dias tamb\u00e9m oferece uma nova perspectiva leiga \u00e0 santidade, tornando-se exemplo de convers\u00e3o, aceita\u00e7\u00e3o e santifica\u00e7\u00e3o para os \u2018pobres\u2019, os \u2018fr\u00e1geis\u2019, os \u2018doentes\u2019 que nela podem se reconhecer e reencontrar esperan\u00e7a.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Escreve S\u00e3o Paulo, \u00abque os sofrimentos do momento presente n\u00e3o s\u00e3o compar\u00e1veis \u00e0 gl\u00f3ria futura que dever\u00e1 ser revelada em n\u00f3s\u00bb. Com \u00abimpaci\u00eancia\u00bb esperamos contemplar o rosto de Deus, pois \u00abna esperan\u00e7a fomos salvos\u00bb (Rom 8,18.24). Portanto, \u00e9 absolutamente necess\u00e1rio esperar contra toda esperan\u00e7a, \u00ab<em>Spes contra spem<\/em>\u00bb. Porque, como escreveu Carlos P\u00e9guy, a Esperan\u00e7a \u00e9 uma crian\u00e7a \u00abirredut\u00edvel\u00bb. Em rela\u00e7\u00e3o \u00e0 F\u00e9 que \u00ab\u00e9 uma esposa fiel\u00bb e \u00e0 Caridade que \u00ab\u00e9 uma M\u00e3e\u00bb, a Esperan\u00e7a parece, \u00e0 primeira vista, n\u00e3o valer nada. E, no entanto, \u00e9 exatamente o contr\u00e1rio: ser\u00e1 a Esperan\u00e7a, escreve P\u00e9guy, \u00abque veio ao mundo no dia de Natal\u00bb e que \u00abtrazendo as outras, atravessar\u00e1 os mundos\u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00abEscreva, Vera de Jesus, eu te darei luz. A \u00e1rvore florida na primavera deu seus frutos. Muitas \u00e1rvores dever\u00e3o florescer novamente na esta\u00e7\u00e3o oportuna para que os frutos sejam abundantes\u2026 Pe\u00e7o que aceite com f\u00e9 cada prova, cada dor por Mim. Voc\u00ea ver\u00e1 os frutos, os primeiros frutos da nova flora\u00e7\u00e3o\u00bb. (Santa Corona \u2013 26 de outubro de 1969 \u2013 Festa de Cristo Rei \u2013 Pen\u00faltima mensagem).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Vera Grita, filha de Hamlet e de Maria Anna Zacco da Pirrera, nasceu em&#8230;<\/p>\n","protected":false},"author":14,"featured_media":35526,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":15,"footnotes":""},"categories":[167],"tags":[2565,2557,2232,2592,2227,2228,2619,2025],"class_list":["post-35532","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nossos-santos","tag-caridade","tag-deus","tag-esperanca","tag-familia-salesiana","tag-salvacao","tag-santos","tag-testemunhos","tag-virtude"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/posts\/35532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/comments?post=35532"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/posts\/35532\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/media\/35526"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/media?parent=35532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/categories?post=35532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/tags?post=35532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}