{"id":5739,"date":"2022-11-09T15:09:40","date_gmt":"2022-11-09T15:09:40","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/cookie-policy-ue\/"},"modified":"2022-12-06T09:53:24","modified_gmt":"2022-12-06T09:53:24","slug":"cookie-policy-ue","status":"publish","type":"page","link":"https:\/\/www.donbosco.press\/pt-pt\/cookie-policy-ue\/","title":{"rendered":"Cookie Policy (UE)"},"content":{"rendered":"\n<!-- Legal document generated by Complianz | GDPR\/CCPA Cookie Consent https:\/\/wordpress.org\/plugins\/complianz-gdpr -->\n<div id=\"cmplz-document\" class=\"cmplz-document cookie-statement cmplz-document-eu\"><p><i>Esta Pol\u00edtica de Cookies foi atualizada pela \u00faltima vez em 5 de Novembro, 2025 e se aplica a cidad\u00e3os e residentes legais permanentes do Espa\u00e7o Econ\u00f3mico Europeu e Su\u00ed\u00e7a.<\/i><br><\/p><h2>1. Introdu\u00e7\u00e3o<\/h2><p>Nosso site, <a href=\"https:\/\/www.donbosco.press\/pt-pt\/\">https:\/\/www.donbosco.press\/pt-pt\/<\/a> (doravante: \"o site\") usa cookies e outras tecnologias relacionadas (por conveni\u00eancia todas as tecnologias s\u00e3o referidas como \"cookies\"). Os cookies tamb\u00e9m s\u00e3o inseridos por terceiros que contratamos. No documento abaixo informamos sobre o uso de cookies em nosso site.<\/p><h2>2. O que s\u00e3o cookies?<\/h2><p>Um cookie \u00e9 um arquivo pequeno e simples que \u00e9 enviado junto com p\u00e1ginas deste site e armazenado pelo seu browser no disco r\u00edgido do seu computador ou outro dispositivo. As informa\u00e7\u00f5es armazenadas podem ser enviadas de volta aos nossos servidores ou aos servidores dos terceiros relevantes durante uma visita subsequente.<\/p><h2>3. O que s\u00e3o scripts?<\/h2><p>Um script \u00e9 uma parte de c\u00f3digo de programa usado para fazer o nosso site funcionar de forma adequada e interativa. Este c\u00f3digo \u00e9 executado no nosso servidor ou no seu dispositivo.<\/p><h2>4. O que \u00e9 um web beacon?<\/h2><p>Um web beacon (ou uma tag pixel) \u00e9 um pequeno e texto invis\u00edvel ou imagem num site que \u00e9 usado para monitorizar o tr\u00e1fego num site. Para fazer isso, v\u00e1rios dados sobre si s\u00e3o armazenados utilizando web beacons.<\/p><h2>5. Cookies<\/h2><p class=\"cmplz-subtitle\">5.1 Cookies t\u00e9cnicos ou funcionais<\/p><p>Alguns cookies garantem que certas partes do site funcionem corretamente e que suas prefer\u00eancias de utilizador permane\u00e7am conhecidas. Ao inserir cookies funcionais, facilitamos a visita ao nosso site. Dessa forma, n\u00e3o precisa inserir repetidamente as mesmas informa\u00e7\u00f5es ao visitar o nosso site e, por exemplo, os itens permanecem no seu carrinho de compras at\u00e9 que tenha conclu\u00eddo a compra. Podemos inserir esses cookies sem o seu consentimento.<\/p><p class=\"cmplz-subtitle\">5.2 Cookies anal\u00edticos<\/p><p>Usamos cookies anal\u00edticos para otimizar a experi\u00eancia do site para nossos usu\u00e1rios. Com estes cookies anal\u00edticos, obtemos informa\u00e7\u00f5es sobre o uso de nosso site.&nbsp;Pedimos sua permiss\u00e3o para inserir cookies anal\u00edticos.<\/p><p class=\"cmplz-subtitle\">5.3 Cookies de marketing\/rastreio<\/p><p>Cookies de marketing\/rastreio s\u00e3o cookies ou qualquer outra forma de armazenamento local, usados para criar perfis de usu\u00e1rio para exibir publicidade ou para rastrear o utilizador neste site ou em v\u00e1rios sites para fins semelhantes de marketing .<\/p><p class=\"cmplz-subtitle\">5.4 Rede social<\/p><p>No nosso site, inclu\u00edmos conte\u00fado de Facebook e X (Formerly Twitter) para promover p\u00e1ginas da web (por exemplo, \"gosto\", \"pin\") ou partilhar (por exemplo, \"twittar\") em redes sociais como Facebook e X (Formerly Twitter). Este conte\u00fado \u00e9 incorporado com c\u00f3digo derivado de Facebook e X (Formerly Twitter) e coloca cookies. Esse conte\u00fado pode armazenar e processar determinadas informa\u00e7\u00f5es para publicidade personalizada.<\/p><p>Por favor leia a declara\u00e7\u00e3o de privacidade dessas redes sociais (que podem mudar regularmente) para saber o que eles fazem com seus dados (pessoais) que eles processam usando esses cookies. Os dados recuperados s\u00e3o anonimizados tanto quanto poss\u00edvel. Facebook e X (Formerly Twitter) est\u00e3o localizados nos Estados Unidos.<\/p><h2>6. Cookies inseridos<\/h2><div id=\"cmplz-cookies-overview\"><details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Complianz<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_complianz\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service complianz<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_complianz\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"complianz\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos Complianz para gerenciamento de consentimento de cookies.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.&nbsp;Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/complianz.io\/legal\/privacy-statement\/\">Complianz Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_consented_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_policy_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store accepted cookie policy ID<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_marketing<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_statistics<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_preferences<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_functional<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_banner-status<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store if the cookie banner has been dismissed<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_user_data<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Read to determine which cookie banner to show<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_saved_categories<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_saved_services<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">cmplz_id<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">365 dias<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store cookie consent preferences<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WordPress<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wordpress\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wordpress<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wordpress\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wordpress\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos WordPress para desenvolvimento de sites.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wpEmojiSettingsSupports<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store browser details<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-time-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wordpress_test_cookie<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Read if cookies can be placed<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wordpress_logged_in_*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store logged in users<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-settings-*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp_lang<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store language settings<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>WPML<\/h3>\n\t\t<p>Functional<\/p>\n\t\t<label for=\"cmplz_service_wpml\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service wpml<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_wpml\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"wpml\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos WPML para gerenciamento de localidade.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Esses dados n\u00e3o s\u00e3o partilhados com terceiros.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wp-wpml_current_language<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 day<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store language settings<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Fonts<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-fonts\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-fonts<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-fonts\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-fonts\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos Google Fonts para exibi\u00e7\u00e3o de fontes da web.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google Fonts Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">Google Fonts API<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">expires immediately<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Read user IP address<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google reCAPTCHA<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-recaptcha\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-recaptcha<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-recaptcha\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-recaptcha\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos Google reCAPTCHA para preven\u00e7\u00e3o de spam.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">Google reCAPTCHA Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">rc::c<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Read and filter requests from bots<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">rc::b<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Read and filter requests from bots<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">rc::a<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Read and filter requests from bots<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Google Maps<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_google-maps\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service google-maps<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_google-maps\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"google-maps\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos Google Maps para exibi\u00e7\u00e3o de mapas.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/business.safety.google\/privacy\/\">Google Maps Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">Google Maps API<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">expires immediately<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Read user IP address<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>YouTube<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_youtube\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service youtube<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_youtube\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"youtube\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos YouTube para exibi\u00e7\u00e3o de v\u00eddeo.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/policies.google.com\/privacy\">YouTube Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">GPS<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store location data<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">VISITOR_INFO1_LIVE<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">6 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Provide ad delivery or retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">YSC<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store and track interaction<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">PREF<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">8 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store user preferences<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>ShareThis<\/h3>\n\t\t<p>Marketing<\/p>\n\t\t<label for=\"cmplz_service_sharethis\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service sharethis<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_sharethis\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"sharethis\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos ShareThis para exibi\u00e7\u00e3o de posts sociais recentes e\/o bot\u00f5es de compartilhar sociais.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/sharethis.com\/privacy\/\">ShareThis Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalidade pendente de investiga\u00e7\u00e3o<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">UIDR<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__uset<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">uset<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_stgmap<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 week<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store and track audience reach<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_stamap<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 week<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store and track audience reach<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">stacxiommap<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 week<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store and track audience reach<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">stdlxmap<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 week<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store and track audience reach<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">__stid<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 week<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store and track audience reach<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Facebook<\/h3>\n\t\t<p>Marketing, Functional<\/p>\n\t\t<label for=\"cmplz_service_facebook\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service facebook<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_facebook\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"facebook\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos Facebook para exibi\u00e7\u00e3o de posts sociais recentes e\/o bot\u00f5es de compartilhar sociais.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/policy\/cookies\">Facebook Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_fbc<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store last visit<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">fbm*<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store account details<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">xs<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">3 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store a unique session ID<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">fr<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">3 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Provide ad delivery or retargeting<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">act<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">90 days<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store logged in users<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_fbp<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">3 months<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store and track visits across websites<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">datr<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Provide fraud prevention<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">c_user<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">30 days<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store a unique user ID<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">sb<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">2 years<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store browser details<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">*_fbm_<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 year<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store account details<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wd<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">1 week<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Read screen resolution<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">csm<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">90 days<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Provide fraud prevention<\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">actppresence<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">session<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store and track if the browser tab is active<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Twitter<\/h3>\n\t\t<p>Functional, Marketing<\/p>\n\t\t<label for=\"cmplz_service_twitter\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service twitter<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_twitter\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"twitter\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p>Usamos Twitter para exibi\u00e7\u00e3o de posts sociais recentes e\/o bot\u00f5es de compartilhar sociais.<\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>Para mais informa\u00e7\u00f5es, leia a <a target=\"_blank\" rel=\"noopener noreferrer nofollow\" href=\"https:\/\/twitter.com\/en\/privacy\">Twitter Declara\u00e7\u00e3o de Privacidade<\/a>.<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Functional<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">local_storage_support_test<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Provide load balancing functionality<\/div>\n\n<\/div><div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Marketing<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">metrics_token<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\">persistent<\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\">Store if the user has seen embedded content<\/div>\n\n<\/div>\n<\/details>\n<details class=\"cmplz-dropdown cmplz-service-desc cmplz-dropdown-cookiepolicy \">\n\t<summary class=\"cmplz-service-header\"><div>\n\t\t<h3>Diversos<\/h3>\n\t\t<p>Finalidade pendente de investiga\u00e7\u00e3o<\/p>\n\t\t<label for=\"cmplz_service_diversos\" class=\"cmplz_consent_per_service_label\"><span class=\"screen-reader-text\">Consent to service diversos<\/span><\/label>\n\t\t<input type=\"checkbox\" id=\"cmplz_service_diversos\" class=\"cmplz-accept-service cmplz-hidden\" data-service=\"diversos\" data-category=\"functional\"><\/div>\n\t<\/summary>\n\t<div class=\"cmplz-service-description\">\n\t\t<h4>Utiliza\u00e7\u00e3o<\/h4>\n\t\t<p><\/p>\n\t<\/div>\n\t<div class=\"cmplz-sharing-data\">\n\t\t<h4>Partilha de dados<\/h4>\n\t\t<p>A partilha de dados est\u00e1 pendente de investiga\u00e7\u00e3o<\/p>\n\t<\/div>\n\t<div class=\"cookies-per-purpose\">\n    <div class=\"purpose\"><h4>Finalidade pendente de investiga\u00e7\u00e3o<\/h4><\/div>\n    <div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_d2ad2316-e7bc-44df-911a-b3e8291e9249<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">_ams_session<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">continueReview<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wpml-available-translators-notice-dismissed<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ate-maiya-info_ebddbe18-f681-425f-923b-e858b9105caa<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">litespeed_qc_hide_banner<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">ams_tq_last_ids<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">WP_DATA_USER_1<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wpml-last-picked-up-translation-methods<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">wpml-wpml-notices<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n<div class=\"name-header\">\n\t<h5>Nome<\/h5>\n<\/div>\n<div class=\"name\">iawp_ignore_visitor<\/div>\n<div class=\"retention-header\">\n\t<h5>Vencimento<\/h5>\n<\/div>\n<div class=\"retention\"><\/div>\n<div class=\"function-header\">\n\t<h5>Fun\u00e7\u00e3o<\/h5>\n<\/div>\n<div class=\"function\"><\/div>\n\n<\/div>\n<\/details>\n<\/div><h2>7. Consentimento<\/h2><p>Quando visitar o nosso site pela primeira vez, mostraremos uma janela com uma explica\u00e7\u00e3o sobre cookies. Assim que clicar em \"Salva preferenze\", autoriza-nos a usar as categorias de cookies e plugins selecionados na janela, conforme descrito nesta Pol\u00edtica de Cookies. Pode desativar o uso de cookies atrav\u00e9s do seu navegador, mas observe que o nosso site pode n\u00e3o funcionar corretamente.<\/p><p class=\"cmplz-subtitle\">7.1 Fa\u00e7a a gest\u00e3o das suas configura\u00e7\u00f5es de consentimento<\/p><div id=\"cmplz-manage-consent-container-nojavascript\">Carregou a Pol\u00edtica de Cookies sem suporte para javascript.&nbsp;No AMP, pode usar o bot\u00e3o de gest\u00e3o de consentimento na parte inferior da p\u00e1gina.<\/div><div id=\"cmplz-manage-consent-container\" class=\"cmplz-manage-consent-container\"><\/div><h2>8. Ativa\u00e7\u00e3o\/desativa\u00e7\u00e3o e exclus\u00e3o de cookies<\/h2><p>Pode usar o seu browser para excluir cookies automaticamente ou manualmente. Tamb\u00e9m pode especificar que certos cookies podem n\u00e3o ser inseridos. Outra op\u00e7\u00e3o \u00e9 alterar as configura\u00e7\u00f5es do seu browser para que receba uma mensagem cada vez que um cookie \u00e9 inserido. Para obter mais informa\u00e7\u00f5es sobre essas op\u00e7\u00f5es, consulte as instru\u00e7\u00f5es na sec\u00e7\u00e3o Ajuda do seu browser.<\/p><p>Por favor note que nosso site pode n\u00e3o funcionar corretamente se todos os cookies forem desativados. Se excluir os cookies do seu navegador, eles ser\u00e3o inseridos novamente ap\u00f3s o seu consentimento quando visitar os nossos sites outra vez.<\/p><h2>9. Os seus direitos em rela\u00e7\u00e3o aos dados pessoais<\/h2><p>Tem os seguintes direitos em rela\u00e7\u00e3o aos seus dados pessoais:<\/p><ul>\n                    <li>Tem o direito de saber por que seus dados pessoais s\u00e3o necess\u00e1rios, o que acontecer\u00e1 com eles e por quanto tempo eles ser\u00e3o retidos.<\/li>\n                    <li>Direito de acesso: Tem o direito de aceder aos seus dados pessoais que s\u00e3o conhecidos por n\u00f3s.<\/li>\n                    <li>Direito \u00e0 retifica\u00e7\u00e3o: tem o direito de complementar, corrigir, ter exclu\u00eddos ou bloqueados os seus dados pessoais sempre que desejar.<\/li>\n                    <li>Se nos der o seu consentimento para processar seus dados, tem o direito de revogar esse consentimento e ter os seus dados pessoais exclu\u00eddos.<\/li>\n                    <li>Direito de transferir os seus dados: tem o direito de solicitar todos os seus dados pessoais do controlador e transferi-los em sua totalidade para outro controlador.<\/li>\n                    <li>Direito de objeto: pode rejeitar o processamento dos seus dados. N\u00f3s cumprimos isso, a menos que haja motivos justificados para o processamento.<\/li>\n                <\/ul><p>Para exercer esses direitos, entre em contacto connosco. Consulte os detalhes de contacto no final desta Pol\u00edtica de Cookies. Se tem uma reclama\u00e7\u00e3o sobre como lidamos com seus dados, gostar\u00edamos de ouvi-la, mas tamb\u00e9m tem o direito de enviar uma reclama\u00e7\u00e3o \u00e0 autoridade supervisora (a Autoridade de Prote\u00e7\u00e3o de Dados).<\/p><h2>10. Detalhes de contacto<\/h2><p>Para perguntas e\/ou coment\u00e1rios sobre nossa Pol\u00edtica de Cookies e esta declara\u00e7\u00e3o, entre em contacto connosco usando os seguintes detalhes de contacto:<\/p><p><span class=\"cmplz-contact-organisation\">Bollettino Salesiano OnLine - Oratorio Salesiano San Francesco di Sales<\/span><br>\n                      <span class=\"cmplz-contact-address\">Via Maria Ausiliatrice 32, 10152 Torino<\/span><br>\n                      <span class=\"cmplz-contact-country\">It\u00e1lia<\/span><br>\n                      <span class=\"cmplz-contact-domain\">Website: <a href=\"https:\/\/www.donbosco.press\/pt-pt\/\">https:\/\/www.donbosco.press\/pt-pt\/<\/a><\/span><br>\n                      <span class=\"cmplz-contact-email\">E-mail: <span class=\"cmplz-obfuscate\">pr&#105;v&#097;&#099;&#121;@<span class=\"cmplz-fmail-domain\">ex&#046;com<\/span>do&#110;b&#111;&#115;&#099;o.&#112;&#114;&#101;&#115;s<\/span><\/span><br>\n                    <span class=\"cmplz-contact-telephone\">Telefone: +39 378 084 1797<\/span><\/p><p>Esta Pol\u00edtica de Cookies foi sincronizada com <a href=\"https:\/\/cookiedatabase.org\/\" target=\"_blank\">cookiedatabase.org<\/a> em 12 de Maio, 2026.<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"iawp_total_views":12,"footnotes":""},"class_list":["post-5739","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/pages\/5739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/comments?post=5739"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/pages\/5739\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/media?parent=5739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}