{"id":170,"count":55,"description":"","link":"https:\/\/www.donbosco.press\/pt-pt\/category\/comunicacoes-do-reitor-mor\/","name":"Comunica\u00e7\u00f5es do Reitor-Mor","slug":"comunicacoes-do-reitor-mor","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/categories\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.donbosco.press\/pt-pt\/wp-json\/wp\/v2\/posts?categories=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}