{"id":44585,"date":"2025-07-28T09:10:16","date_gmt":"2025-07-28T09:10:16","guid":{"rendered":"https:\/\/www.donbosco.press\/bez-kategorii\/don-bosco-e-la-chiesa-del-santo-sudario\/"},"modified":"2025-07-28T14:12:39","modified_gmt":"2025-07-28T14:12:39","slug":"ksiadz-bosko-i-kosciol-swietego-calunu","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/pl\/dobra-prasa\/ksiadz-bosko-i-kosciol-swietego-calunu\/","title":{"rendered":"Ksi\u0105dz Bosko i ko\u015bci\u00f3\u0142 \u015awi\u0119tego Ca\u0142unu"},"content":{"rendered":"\r\n<p><em>A Santa S\u00edndone de Turim, uma das rel\u00edquias mais veneradas do cristianismo, tem uma hist\u00f3ria milenar entrela\u00e7ada com a dos Saboias e da cidade sabauda. Chegando a Turim em 1578, tornou-se objeto de profunda devo\u00e7\u00e3o, com exposi\u00e7\u00f5es solenes ligadas a eventos hist\u00f3ricos e din\u00e1sticos. No s\u00e9culo XIX, figuras como S\u00e3o Jo\u00e3o Bosco e outros santos turineses promoveram seu culto, contribuindo para sua difus\u00e3o. Hoje guardada na Capela do Guarini, a S\u00edndone est\u00e1 no centro de estudos cient\u00edficos e teol\u00f3gicos. Paralelamente, a igreja do Santo Sud\u00e1rio em Roma, ligada aos Saboias e \u00e0 comunidade piemontesa, representa outro local significativo, onde Dom Bosco tentou estabelecer uma presen\u00e7a salesiana.<\/em><br \/><br \/><br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 O Santo Sud\u00e1rio de Turim, impropriamente chamado de \u201cSanto Sud\u00e1rio\u201d pelo costume franc\u00eas de cham\u00e1-lo de\u00a0<em>\u201cLe Saint Suaire\u201d<\/em>, era propriedade da Casa de Saboia desde 1463 e foi transferido de Chambery para a nova capital da Saboia em 1578.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Naquele mesmo ano, foi realizada a primeira Exposi\u00e7\u00e3o, que Emanuel Filiberto quis fazer em homenagem ao Card. Carlos Borromeu, que veio a Turim em peregrina\u00e7\u00e3o para vener\u00e1-la.<br \/><br \/><strong>Exposi\u00e7\u00f5es no s\u00e9culo XIX e o culto ao Sud\u00e1rio<br \/><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No s\u00e9culo XIX, as Exposi\u00e7\u00f5es de 1815, 1842, 1868 e 1898 s\u00e3o particularmente dignas de nota: a primeira por ocasi\u00e3o do retorno da fam\u00edlia de Saboia aos seus estados, a segunda no casamento de V\u00edtor Emanuel II com Maria Adelaide de Habsburgo-Lorena, a terceira no casamento de Humberto I com Margarida de Saboia-G\u00eanova e a quarta na Exposi\u00e7\u00e3o Universal.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Os santos de Turim do s\u00e9culo XIX, Cottolengo, Cafasso e Dom Bosco, eram devotos do Santo Sud\u00e1rio, imitando o exemplo do Beato Sebasti\u00e3o Valfr\u00e9, o ap\u00f3stolo de Turim durante o cerco de 1706.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 As\u00a0<em>Mem\u00f3rias Biogr\u00e1ficas<\/em>\u00a0nos asseguram que Dom Bosco o venerou especialmente na Exposi\u00e7\u00e3o de 1842 e na de 1868, quando tamb\u00e9m levou os meninos do orat\u00f3rio para v\u00ea-lo (MBp II, 110-111; IX, 182).<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Hoje, a tela de valor inestim\u00e1vel, doada por Umberto II de Saboia \u00e0 Santa S\u00e9, \u00e9 confiada ao Arcebispo de Turim \u201cCust\u00f3dio Pontif\u00edcio\u201d e mantida na suntuosa Capela Guarini, atr\u00e1s da Catedral.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Em Turim, h\u00e1 tamb\u00e9m, na Rua Piave, na esquina da Rua S\u00e3o Domingos, a\u00a0<em>Igreja do Santo Sud\u00e1rio<\/em>, constru\u00edda pela Confraria de mesmo nome e reconstru\u00edda em 1761. Adjacente \u00e0 igreja est\u00e1 o\u00a0<em>\u201cMuseu Sindonol\u00f3gico\u201d<\/em>\u00a0e a sede do Sodal\u00edcio\u00a0<em>\u201cCultores Sanctae Sindonis\u201d [Cultores do Santo Sud\u00e1rio]<\/em>, um centro de estudos sindonol\u00f3gicos para o qual fizeram valiosas contribui\u00e7\u00f5es estudiosos salesianos como o P. Natal Noguier de Malijay, o P. Ant\u00f4nio Tonelli, o P. Alberto Caviglia, o P. Pedro Scotti e, mais recentemente, o P. Pedro Rinaldi e o P. Lu\u00eds Fossati, para citar apenas os principais.<br \/><br \/><strong>A Igreja do Santo Sud\u00e1rio em Roma<br \/><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tamb\u00e9m existe uma\u00a0<a href=\"https:\/\/www.google.com\/maps\/place\/Chiesa+del+Santissimo+Sudario+dei+Piemontesi+all'Argentina\/@41.8959701,12.4750964,71m\/data=!3m1!1e3!4m15!1m8!3m7!1s0x132f604ee2b67dcb:0x59755362f097844e!2sVia+del+Sudario,+47,+00186+Roma+RM!3b1!8m2!3d41.8959536!4d12.4753394!16s%2Fg%2F11rg5zy__3!3m5!1s0x132f604f1d157fff:0xc2bbb9238105ea4!8m2!3d41.8959244!4d12.4752197!16s%2Fm%2F012m7zyl?entry=ttu&amp;g_ep=EgoyMDI1MDYxNy4wIKXMDSoASAFQAw%3D%3D\" target=\"_blank\" rel=\"noreferrer noopener\">Igreja do Santo Sud\u00e1rio<\/a>\u00a0em Roma, ao longo da rua hom\u00f4nima que vai do Largo Argentina paralelamente \u00e0 Avenida Vit\u00f3rio. Erguida em 1604 com um projeto de Carlos di Castellamonte, era a Igreja dos Piemonteses, Saboianos e Niceanos, constru\u00edda pela Confraria do Santo Sud\u00e1rio que havia surgido em Roma naquela \u00e9poca. Depois de 1870, ela se tornou a igreja particular da Casa de Saboia.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Durante suas estadas em Roma, Dom Bosco celebrou a missa nessa igreja v\u00e1rias vezes e formulou um plano para ela e para a casa adjacente, de acordo com o prop\u00f3sito da ent\u00e3o extinta Confraria, dedicada a obras de caridade para jovens abandonados, doentes e prisioneiros.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 A Confraria havia deixado de funcionar no in\u00edcio do s\u00e9culo e a propriedade e a administra\u00e7\u00e3o da igreja haviam passado para a Delega\u00e7\u00e3o Sarda junto \u00e0 Santa S\u00e9. Na d\u00e9cada de 1860, a igreja estava precisando de grandes reformas, tanto que em 1868 foi temporariamente fechada.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mas, j\u00e1 em 1867, Dom Bosco teve a ideia de propor ao governo da Saboia que lhe entregasse o uso e a administra\u00e7\u00e3o da igreja, oferecendo sua colabora\u00e7\u00e3o em dinheiro para concluir o trabalho de restaura\u00e7\u00e3o. Talvez ele tenha previsto a entrada das tropas piemontesas em Roma, n\u00e3o muito distante, e, desejando abrir uma casa l\u00e1, pensou em faz\u00ea-lo antes que a situa\u00e7\u00e3o se precipitasse, tornando mais dif\u00edcil obter a aprova\u00e7\u00e3o da Santa S\u00e9 e o respeito do Estado pelos acordos (MBp IX, 461-462).<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ele ent\u00e3o apresentou o pedido ao governo. Em 1869, durante uma escala em Floren\u00e7a, ele preparou uma minuta de acordo que, ao chegar a Roma, apresentou a Pio IX. Depois de obter seu consentimento, ele passou para a solicita\u00e7\u00e3o oficial ao Minist\u00e9rio das Rela\u00e7\u00f5es Exteriores, mas, infelizmente, a ocupa\u00e7\u00e3o de Roma acabou prejudicando todo o caso. O pr\u00f3prio Dom Bosco percebeu a inadequa\u00e7\u00e3o de insistir. Assumir, de fato, naquela \u00e9poca, a oficializa\u00e7\u00e3o de uma igreja romana pertencente \u00e0 Casa da Saboia por uma Congrega\u00e7\u00e3o religiosa com sua Casa M\u00e3e em Turim, poderia ter parecido um ato de oportunismo e servilismo em rela\u00e7\u00e3o ao novo Governo.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ap\u00f3s a brecha de Porta Pia, com o registro de 2 de dezembro de 1871, a Igreja do SS. Sud\u00e1rio foi anexada \u00e0 Casa Real e designada como sede oficial do Capel\u00e3o-mor palatino. Em consequ\u00eancia do interdito de Pio IX sobre as Capelas do antigo pal\u00e1cio apost\u00f3lico do Quirinal, foi justamente na Igreja do Sud\u00e1rio que se realizavam todos os ritos sagrados da Fam\u00edlia Real.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Em 1874, Dom Bosco testou novamente o terreno com o governo. Mas, infelizmente, as not\u00edcias intempestivas que vazaram dos jornais interromperam definitivamente o projeto (MBp X, 1041-1042).<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Com o fim da monarquia, em 2 de junho de 1946, todo o complexo do Sud\u00e1rio passou para a gest\u00e3o da Secretaria Geral da Presid\u00eancia da Rep\u00fablica. Em 1984, ap\u00f3s o novo Conc\u00f3rdio que sancionou a aboli\u00e7\u00e3o das Capelas palatinas, a Igreja do Sud\u00e1rio foi confiada ao Ordinariato Militar e assim permanece at\u00e9 hoje.<br \/>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Gostar\u00edamos, por\u00e9m, de recordar o fato de que Dom Bosco, ao procurar uma oportunidade favor\u00e1vel para abrir uma casa em Roma, p\u00f4s os olhos na Igreja do Santo Sud\u00e1rio.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>A Santa S\u00edndone de Turim, uma das rel\u00edquias mais veneradas do cristianismo, tem uma hist\u00f3ria&#8230;<\/p>\n","protected":false},"author":11,"featured_media":44600,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":1,"footnotes":""},"categories":[147],"tags":[1718,1838,1742,2576,2018,1958,1970],"class_list":["post-44585","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dobra-prasa","tag-charyzmat-salezjanski","tag-inicjatywy","tag-kosciol","tag-ksiadz-bosko","tag-podroze","tag-salezjanie","tag-swieci"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/posts\/44585","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/comments?post=44585"}],"version-history":[{"count":2,"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/posts\/44585\/revisions"}],"predecessor-version":[{"id":44606,"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/posts\/44585\/revisions\/44606"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/media\/44600"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/media?parent=44585"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/categories?post=44585"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/pl\/wp-json\/wp\/v2\/tags?post=44585"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}