{"id":36002,"date":"2025-04-21T16:30:23","date_gmt":"2025-04-21T16:30:23","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=36002"},"modified":"2025-04-26T09:50:54","modified_gmt":"2025-04-26T09:50:54","slug":"eduquer-nos-emotions-avec-saint-francois-de-sales","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/fr\/nos-saints\/eduquer-nos-emotions-avec-saint-francois-de-sales\/","title":{"rendered":"\u00c9duquer nos \u00e9motions avec saint Fran\u00e7ois de Sales"},"content":{"rendered":"\n<p><em>La psychologie moderne a montr\u00e9 l\u2019importance et l\u2019influence de nos \u00e9motions dans la vie de notre psychisme. Mais on ne parle plus gu\u00e8re des \u00ab passions de l\u2019\u00e2me \u00bb, que l\u2019anthropologie classique analysait soigneusement, comme en t\u00e9moigne l\u2019\u0153uvre de Fran\u00e7ois de Sales, notamment quand il \u00e9crit que \u00ab l\u2019\u00e2me en tant qu\u2019\u00e2me est la source des passions et affections \u00bb. Dans le vocabulaire de Fran\u00e7ois de Sales, le terme \u00ab \u00e9motion \u00bb n\u2019appara\u00eet pas encore avec les connotations que nous lui connaissons. Par contre, il dira que nos passions sont \u00ab \u00e9mues \u00bb dans certaines circonstances. En \u00e9ducation la question qui se pose est l\u2019attitude qu\u2019il convient d\u2019avoir devant ces manifestations involontaires de notre sensibilit\u00e9 et qui ont presque toujours des r\u00e9percussions physiologiques. L\u2019humanisme de saint Fran\u00e7ois de Sales s\u2019accommode-t-il de ces ph\u00e9nom\u00e8nes \u00ab remuants \u00bb ?<br><\/em><br><br><strong>\u00ab Je suis tant homme que rien plus \u00bb<br><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Tous eux qui ont connu Fran\u00e7ois de Sales ont not\u00e9 sa grande sensibilit\u00e9 et \u00e9motivit\u00e9. Parfois on lui voyait monter le sang au visage et il devenait tout rouge. Comme un bon Savoyard, c\u2019\u00e9tait \u00ab un volcan sous la neige \u00bb. On l\u2019a vu pleurer sur la mort des \u00eatres chers, mais aussi sur les p\u00e9ch\u00e9s des autres. Lors de la mort de sa petite s\u0153ur Jeanne, qu\u2019il avait \u00ab baptis\u00e9e de ses propres mains \u00bb, il \u00e9crivait \u00e0 Jeanne de Chantal, elle-m\u00eame constern\u00e9e :<br><br><em>H\u00e9las, ma Fille, je suis tant homme que rien plus. Mon c\u0153ur s\u2019est attendri plus que je n\u2019eusse pens\u00e9 ; mais la v\u00e9rit\u00e9 est que le d\u00e9plaisir de ma m\u00e8re et le v\u00f4tre y ont beaucoup contribu\u00e9, car j\u2019ai eu peur de votre c\u0153ur et de celui de ma m\u00e8re.<br><\/em><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Comme on le voit, il ne refoulait pas syst\u00e9matiquement les manifestations ext\u00e9rieures de ses sentiments, son humanisme s\u2019en accommodait. Il a pleur\u00e9 \u00e0 la mort de sa m\u00e8re, de sa petite s\u0153ur, de son \u00e9v\u00eaque. Un t\u00e9moignage pr\u00e9cieux de Jeanne de Chantal nous apprend que \u00ab notre saint n\u2019\u00e9tait pas exempt de sentiments et \u00e9motions des passions, et ne voulait pas qu\u2019on d\u00e9sir\u00e2t d\u2019en \u00eatre affranchi \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Comme ils sont nombreux et divers les \u00e9tats successifs de notre \u00e2me ! Tant\u00f4t elle est \u00ab triste, joyeuse, en douceur, en amertume, en paix, en trouble, en clart\u00e9, en t\u00e9n\u00e8bres, en tentations, en repos, en go\u00fbt, en d\u00e9go\u00fbt, en s\u00e9cheresse, en tendret\u00e9 \u00bb. Fran\u00e7ois de Sales remarque sans tarder que les passions de l\u2019\u00e2me r\u00e9agissent sur le corps, provoquant des manifestations ext\u00e9rieures des mouvements int\u00e9rieurs : \u00ab Quand on craint on devient p\u00e2le ; quand l\u2019on nous avertit de quelque chose qui nous f\u00e2che, la couleur monte au visage et l\u2019on devient rouge, ou bien la f\u00e2cherie nous tire la larme de l\u2019\u0153il. \u00bb Quand Mme de Chantal rencontrera l\u2019assassin de son mari, que se passera-t-il ?<br><br><em>Je sais que sans doute, [votre c\u0153ur] se remuera et renversera, que votre sang bouillonnera ; mais qu\u2019est cela ? Ainsi fit bien celui de notre cher Sauveur \u00e0 la vue de son Lazare mort et de sa passion repr\u00e9sent\u00e9e. [\u2026] C\u2019est cela, ma Fille : Dieu nous fait voir en ces \u00e9motions, combien nous sommes de chair, d\u2019os et d\u2019esprit.<br><\/em><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Fran\u00e7ois de Sales n\u2019\u00e9tait pas de l\u2019avis des \u00ab apathistes \u00bb qui affirmaient que \u00ab les saints et les justes \u00e9taient exempts de toute perturbation \u00bb ; m\u00eame le Christ a \u00e9t\u00e9 troubl\u00e9, et s\u2019il n\u2019a pas eu des passions proprement dites, on lui attribue cependant des \u00ab propassions \u00bb. C\u2019est une erreur de penser que \u00ab l\u2019homme, par une soigneuse et fr\u00e9quente mortification, pouvait arriver jusques l\u00e0 que d\u2019\u00eatre sans passions et \u00e9motions de col\u00e8re ; qu\u2019il pouvait recevoir un soufflet sans rougir, \u00eatre injuri\u00e9, moqu\u00e9, battu sans le ressentir \u00bb. C\u2019est faux, parce que \u00ab tant que l\u2019homme vivra, rampera et tra\u00eenera sur cette terre il aura des passions, sentira des tr\u00e9moussements de col\u00e8re, des soul\u00e8vements de c\u0153ur, des affections, inclinations, r\u00e9pugnances, aversions et telles autres choses auxquelles nous sommes tous sujets \u00bb.<br><br><strong>Les douze passions de l\u2019\u00e2me<br><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le nombre des passions a vari\u00e9. L\u2019<em>Introduction \u00e0 la vie d\u00e9vote <\/em>en compte sept, semblables aux sept cordes d\u2019un luth qu\u2019il faut accorder au cours de l\u2019exercice annuel de renouvellement spirituel : l\u2019amour, la haine, le d\u00e9sir, la crainte, l\u2019esp\u00e9rance, la tristesse et la joie. Plus tard, au chapitre III du premier livre du <em>Trait\u00e9 de l\u2019amour de Dieu<\/em>, on en compte pas moins de douze, comme autant de tribus formant tout un peuple : \u00ab l\u2019amour, le d\u00e9sir, l\u2019esp\u00e9rance, le d\u00e9sespoir, la joie, la haine, la fuite du mal, la crainte, le courage, la col\u00e8re, la tristesse et la satisfaction ou assouvissement \u00bb.<br><br><strong><em>L\u2019amour, premi\u00e8re et principale passion<br><\/em><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La cause est entendue : \u00ab L\u2019amour tient le premier rang entre les passions de l\u2019\u00e2me : c\u2019est le roi de tous les mouvements du c\u0153ur, il convertit tout le reste \u00e0 soi et nous rend tels que ce qu\u2019il aime. \u00bb<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pour parler de l\u2019amour, l\u2019\u00e9v\u00eaque de Gen\u00e8ve prend l\u2019image de l\u2019horloge : \u00ab L\u2019amour est la vie de notre c\u0153ur ; et comme le contrepoids donne le mouvement \u00e0 toutes les pi\u00e8ces d\u2019un horloge, aussi l\u2019amour donne \u00e0 l\u2019\u00e2me tous les mouvements qu\u2019elle a \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En tant que passion ou \u00e9motion, l\u2019amour na\u00eet spontan\u00e9ment du plaisir que suscitent les qualit\u00e9s ext\u00e9rieures de la personne ou des choses, alors que la haine ou antipathie provient de la vue des d\u00e9fauts ou laideurs. Cette attirance ou antipathie naturelle que nous \u00e9prouvons pour certaines personnes ou certaines choses peut \u00eatre tr\u00e8s utile. Cependant, elle doit se soumettre aux deux facult\u00e9s sup\u00e9rieures que sont la raison et la volont\u00e9.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La haine, \u00e9crit Fran\u00e7ois de Sales citant saint Jean Chrysostome, \u00ab est un d\u00e9mon volontaire, une manie voulue, un jouet du diable \u00bb. Mais il s\u2019agit ici de la haine entretenue entre les personnes. Il y a des haines instinctives, irrationnelles, inconscientes : entre les mulets et les chevaux, entre le chou et la brebis&#8230; Mais la haine peut devenir tr\u00e8s bonne et utile quand on d\u00e9teste le p\u00e9ch\u00e9, ainsi que \u00ab toutes les affections, d\u00e9pendances et acheminements du p\u00e9ch\u00e9 \u00bb.<br><br><strong><em>Le d\u00e9sir et la fuite<br><\/em><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le d\u00e9sir consiste en \u00ab l\u2019esp\u00e9rance d\u2019un bien futur \u00bb. \u00ab Le d\u00e9sir qui pr\u00e9c\u00e8de la jouissance aiguise et affine le ressentiment d\u2019icelle, et plus le d\u00e9sir a \u00e9t\u00e9 pressant et puissant, plus la possession de la chose d\u00e9sir\u00e9e est agr\u00e9able et d\u00e9licieuse \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les d\u00e9sirs les plus communs sont les d\u00e9sirs touchant les biens, les plaisirs et les honneurs. L\u2019auteur de l\u2019<em>Introduction<\/em> propose une \u00e9ducation du d\u00e9sir : il faut se garder du d\u00e9sir des choses vicieuses, des choses dangereuses, des choses fort \u00e9loign\u00e9es, ou de r\u00eaver d\u2019une autre vie impossible, m\u00eame pour des motifs \u00e9lev\u00e9s ou religieux. Fran\u00e7ois de Sales enseigne le r\u00e9alisme. Il faut prendre les personnes, les choses, les \u00e9v\u00e9nements tels qu\u2019ils sont, \u00e0 commencer par soi-m\u00eame. \u00c0 quoi sert-il de d\u00e9sirer m\u00eame d\u2019avoir un esprit ou un jugement meilleurs que celui que l\u2019on a ? \u00ab Chacun doit avoir [le d\u00e9sir] de cultiver le sien tel qu\u2019il est \u00bb.<br><br><strong><em>L\u2019espoir et le d\u00e9sespoir<br><\/em><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 L\u2019espoir concerne un bien que l\u2019on pense pouvoir obtenir. Philoth\u00e9e est invit\u00e9e \u00e0 examiner comment elle s\u2019est comport\u00e9e \u00ab en l\u2019esp\u00e9rance, trop mise peut-\u00eatre au monde et en la cr\u00e9ature, et trop peu mise en Dieu et \u00e8s choses \u00e9ternelles \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le d\u00e9sespoir fait partie de ces passions dont il est extr\u00eamement difficile de faire un usage positif, \u00e0 moins qu\u2019on le r\u00e9duise \u00e0 \u00ab la juste d\u00e9fiance de nous-m\u00eames, ou bien au sentiment que nous devons avoir de la vanit\u00e9, faiblesse et inconstance des faveurs, assistances et promesses du monde \u00bb. Voyez le d\u00e9sespoir des \u00ab jeunes apprentis de la perfection \u00bb :<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 D\u00e8s qu\u2019ils rencontrent de la difficult\u00e9 en leur chemin, voil\u00e0 quant et quant (en m\u00eame temps) le chagrin qui les pousse \u00e0 faire tant de plaintes qu\u2019il semble qu\u2019il y ait grand piti\u00e9 en eux. L\u2019orgueil ou la vanit\u00e9 ne leur peut permettre un petit d\u00e9faut que tout incontinent [aussit\u00f4t] ils n\u2019entrent en de grands troubles qui les portent par apr\u00e8s au d\u00e9sespoir : \u00d4 Dieu, il ne faut plus rien attendre de moi, je ne ferai jamais rien qui vaille ! C\u2019est bien dit ; h\u00e9, pensiez-vous \u00eatre si brave que de ne point faillir ? En toutes sortes d\u2019arts il faut \u00eatre apprenti, premier que d\u2019\u00eatre ma\u00eetre.<br><br><strong><em>La joie et la tristesse<br><\/em><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La joie est \u00ab l\u2019all\u00e9gresse pour le bien obtenu \u00bb. Lorsque nous rencontrons ceux que nous aimons, \u00ab il ne se peut pas faire que nous ne soyons \u00e9mus de joie et de contentement \u00bb. Mais la joie peut \u00eatre \u00ab excessive et pour choses indignes \u00bb. La joie va parfois jusqu\u2019au rire. La possession d\u2019un bien provoque infailliblement une complaisance ou jouissance, comme la loi de la gravit\u00e9 \u00ab \u00e9meut \u00bb la pierre :<br><br><em>Le poids des choses les \u00e9branle, les meut et les arr\u00eate : c\u2019est le poids de la pierre qui lui donne l\u2019\u00e9motion et le branle \u00e0 la descente, soudain que les emp\u00eachements lui sont \u00f4t\u00e9s ; c\u2019est le m\u00eame poids qui lui fait continuer son mouvement en bas ; et c\u2019est enfin le m\u00eame poids encore qui la fait arr\u00eater et accoiser (reposer) quand elle est arriv\u00e9e en son lieu.<br><\/em><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La tristesse est presque toujours mauvaise, \u00e0 part celle qui consiste \u00e0 s\u2019affliger d\u2019un mal r\u00e9el chez autrui et chez soi-m\u00eame, mais m\u00eame dans ce cas il faut ne pas se laisser abattre par l\u2019exc\u00e8s. La tristesse est presque toujours inutile, voire contraire au service du saint amour. M\u00e9fions-nous de la mauvaise tristesse qui \u00ab trouble l\u2019\u00e2me, donne des craintes d\u00e9r\u00e9gl\u00e9es, d\u00e9go\u00fbte de l\u2019oraison, assoupit et accable le cerveau, prive l\u2019\u00e2me de conseil, de r\u00e9solution, de jugement et de courage \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Il faut donc la chasser le plus possible. Fran\u00e7ois de Sales donne pour cela un certain nombre de conseils. \u00c0 c\u00f4t\u00e9 des rem\u00e8des proprement spirituels, il conseille de \u00ab s\u2019employer aux \u0153uvres ext\u00e9rieures \u00bb, de \u00ab les diversifier le plus que l\u2019on peut, pour divertir l\u2019\u00e2me de l\u2019objet triste, purifier et \u00e9chauffer l\u2019\u00e2me les esprits \u00bb. Un autre rem\u00e8de tr\u00e8s utile consistera \u00e0 d\u00e9couvrir tous les sentiments de son \u00e2me \u00e0 une personne de confiance. La tristesse est \u00ab la douleur pour le mal pr\u00e9sent \u00bb. Elle peut aller dans certains cas jusqu\u2019aux pleurs :<br><br><em>Un p\u00e8re, envoyant son fils en cour ou aux \u00e9tudes, ne laisse pas de pleurer en le licenciant, t\u00e9moignant qu\u2019encore qu\u2019il veuille selon la portion sup\u00e9rieure le d\u00e9part de cet enfant pour son avancement \u00e0 la vertu, n\u00e9anmoins selon l\u2019inf\u00e9rieure il a de la r\u00e9pugnance \u00e0 la s\u00e9paration ; et quoiqu\u2019une fille soit mari\u00e9e au gr\u00e9 de son p\u00e8re et de sa m\u00e8re, si est-ce que prenant leur b\u00e9n\u00e9diction elle excite les larmes, en sorte que la volont\u00e9 sup\u00e9rieure acquies\u00e7ant \u00e0 son d\u00e9part, l\u2019inf\u00e9rieure montre de la r\u00e9sistance.<br><\/em><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Elle aussi peut \u00eatre excessive et pour des choses vaines, comme pour ce pauvre Alexandre le Grand, qui se laissa aller \u00e0 une passion d\u00e9raisonnable quand il apprend qu\u2019il y avait d\u2019autres terres qu\u2019il ne pourra jamais conqu\u00e9rir : \u00ab Comme un petit enfant qui veut pleurer pour une pomme qu\u2019on lui refuse, cet Alexandre que les mondains appellent le Grand, plus fol n\u00e9anmoins qu\u2019un petit enfant, se prend \u00e0 pleurer \u00e0 chaudes larmes de quoi il n\u2019y avait pas apparence qu\u2019il p\u00fbt conqu\u00e9rir les autres mondes \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La tristesse est une passion de l\u2019\u00e2me qu\u2019il est tr\u00e8s difficile de faire servir au bien. Certes, il y a une \u00ab tristesse selon Dieu \u00bb qui est bonne parce qu\u2019elle conduit \u00e0 la p\u00e9nitence et qu\u2019il faudrait nommer plut\u00f4t d\u00e9plaisir, ou sentiment et d\u00e9testation du mal ; elle n\u2019engourdit pas l\u2019esprit, mais le rend actif, prompt et diligent, ce qui la rend fort utile. Il y a une tristesse qui proc\u00e8de de la condition naturelle de ceux qui ont l\u2019humeur m\u00e9lancolique et qu\u2019il est difficile de changer, mais dont il faut n\u00e9anmoins combattre le plus possible les manifestations. Quant \u00e0 la tristesse qui proc\u00e8de de la vari\u00e9t\u00e9 des accidents humains de cette vie, elle peut servir grandement \u00e0 progresser dans l\u2019esp\u00e9rance chr\u00e9tienne. Aussi, \u00ab parmi toutes les m\u00e9lancolies qui nous peuvent arriver, nous devons employer l\u2019autorit\u00e9 de la volont\u00e9 sup\u00e9rieure pour faire tout ce qui se peut en faveur du divin amour \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Certes, quelqu\u2019un qui est d\u2019humeur m\u00e9lancolique pourra difficilement changer son temp\u00e9rament, mais il pourra dire des paroles \u00ab gracieuses, bonteuses et courtoises, et, malgr\u00e9 son inclination, faire par raison les choses convenables, en paroles et en \u0153uvres de charit\u00e9, douceur et condescendance \u00bb. \u00ab On est excusable de n\u2019\u00eatre pas toujours gai, car on n\u2019est pas ma\u00eetre de la gaiet\u00e9 pour l\u2019avoir quand on veut ; mais on n\u2019est pas excusable de n\u2019\u00eatre pas toujours bonteux, maniable et condescendant, car cela est toujours au pouvoir de notre volont\u00e9. \u00bb<br><br><strong><em>Le courage et la crainte<br><\/em><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 L\u2019homme est un \u00eatre perp\u00e9tuellement agit\u00e9 de mouvements divers \u00ab qui tant\u00f4t l\u2019\u00e9l\u00e8vent aux esp\u00e9rances, tant\u00f4t l\u2019abaissent par la crainte \u00bb. La crainte se rapporte \u00e0 un \u00ab mal \u00e0 venir \u00bb. Avant d\u2019\u00eatre une vertu, le courage est un sentiment qui nous envahit parfois devant les difficult\u00e9s qui devraient normalement nous abattre. Fran\u00e7ois de Sales l\u2019a \u00e9prouv\u00e9 au moment d\u2019entreprendre une longue visite de son dioc\u00e8se de montagnes :<br><br><em>Tout maintenant je monte \u00e0 cheval pour la visite qui durera environ cinq mois. [\u2026] Je m\u2019y en vais de grand courage, et d\u00e8s ce matin, j\u2019ai senti une particuli\u00e8re consolation \u00e0 l\u2019entreprendre, quoiqu\u2019auparavant, durant plusieurs jours, j\u2019en eusse eu mille vaines appr\u00e9hensions et tristesses, lesquelles n\u00e9anmoins ne touchaient que la peau de mon c\u0153ur et non point l\u2019int\u00e9rieur : c\u2019\u00e9tait comme ces frissonnements qui arrivent au premier sentiment de quelque froidure.<br><\/em><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Mais il y a aussi certains courages qui ne m\u00e9ritent pas ce nom, comme celui de se battre en duel : l\u2019\u00e9v\u00eaque de Gen\u00e8ve se demande comment \u00ab l\u2019on peut avoir un courage si d\u00e9r\u00e9gl\u00e9, m\u00eame pour des bagatelles et choses de rien \u00bb. Le vrai courage est celui qui est r\u00e9gl\u00e9 par la raison. Et quant au courage chr\u00e9tien, c\u2019est tout simplement un don de Dieu.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Au contraire, il n\u2019est pas en notre pouvoir de ne pas ressentir la crainte en certaines occasions : \u00ab C\u2019est comme qui dirait \u00e0 une personne \u00e0 la rencontre d\u2019un lion ou d\u2019un ours : n\u2019ayez point peur \u00bb. Les enfants \u00ab voient un chien qui aboie, soudain ils se prennent \u00e0 crier, et ne cessent point qu\u2019ils ne soient aupr\u00e8s de leur maman \u00bb. Il en est de m\u00eame face aux \u00e9l\u00e9ments d\u00e9cha\u00een\u00e9s de la nature :<br><br><em>Les \u00e9clairs, tonnerres, foudres, temp\u00eates, inondations, tremble-terre et autres tels accidents inopin\u00e9s excitent m\u00eame les plus ind\u00e9vots \u00e0 craindre Dieu ; et la nature, pr\u00e9venant le discours en telles occurrences, pousse le c\u0153ur, les yeux et les mains m\u00eames devers le ciel pour r\u00e9clamer le secours de la tr\u00e8s sainte Divinit\u00e9, selon le sentiment commun du genre humain, qui est, dit Tite-Live, que ceux qui servent la Divinit\u00e9 prosp\u00e8rent, et ceux qui la m\u00e9prisent sont afflig\u00e9s.<br><\/em><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Certains, voulant faire les courageux, vont de nuit quelque part, mais \u00ab d\u00e8s qu\u2019ils entendent tomber une petite pierre du plancher, ou qu\u2019ils oyent (entendent) seulement courir une petite souris se prennent \u00e0 crier : \u00d4 mon Dieu ! \u2013 Qu\u2019est-ce, leur dit-on, qu\u2019avez-vous trouv\u00e9 ? \u2013 J\u2019ai ou\u00ef. \u2013 Et quoi ? \u2013 Je ne sais \u00bb. Cette crainte naturelle, que nous n\u2019avons pas choisie, n\u2019est ni louable ni bl\u00e2mable, mais elle est peut \u00eatre utile. Il y a des craintes salutaires et d\u2019autres exag\u00e9r\u00e9es : \u00ab crainte des dangers de p\u00e9cher et des pertes des biens de ce monde : on craint trop l\u2019un, et trop peu l\u2019autre \u00bb.<br><br><strong><em>La col\u00e8re et son assouvissement<br><\/em><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Fran\u00e7ois de Sales reconnaissait que \u00ab de son naturel, il \u00e9tait fort prompt et sujet \u00e0 se mettre en col\u00e8re \u00bb. On ne peut s\u2019emp\u00eacher de ressentir de la col\u00e8re en certaines circonstances : \u00ab Si l\u2019on me vient rapporter que quelqu\u2019un a m\u00e9dit de moi, ou que l\u2019on me fasse quelque autre contradiction, incontinent (aussit\u00f4t) la col\u00e8re s\u2019\u00e9meut et je n\u2019ai pas une veine qui ne se torde, parce que le sang bouillonne \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 La col\u00e8re, de soi, n\u2019est pas mauvaise : elle est \u00ab un serviteur qui, \u00e9tant puissant, courageux et grand entrepreneur, fait aussi d\u2019abord beaucoup de besogne \u00bb. Dans certains cas elle est \u00ab un secours donn\u00e9 \u00e0 la raison \u00bb. Mais c\u2019est un serviteur qui peut devenir dangereux et peu d\u00e9sirable. C\u2019est surtout au sujet de la col\u00e8re que Fran\u00e7ois de Sales multiplie les conseils et les mises en garde, parce que cette passion est difficile \u00e0 ma\u00eetriser. Elle peut parfois \u00eatre l\u00e9gitime et les grands saints ont su la lancer et la retirer comme bon leur semblait ; \u00ab mais nous autres, qui avons des passions indompt\u00e9es, toutes jeunes, ou du moins mal apprises, nous ne pouvons l\u00e2cher notre ire qu\u2019avec p\u00e9ril de beaucoup de d\u00e9sordre, parce qu\u2019\u00e9tant une fois en campagne on ne la peut plus retenir ni ranger comme il serait requis \u00bb.<br><br><strong>Un id\u00e9al difficile \u00e0 atteindre : l\u2019\u00e9galit\u00e9 d\u2019humeur<br><\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les \u00e9motions et les passions font de l\u2019homme un \u00eatre extr\u00eamement sujet aux variations de la \u00ab temp\u00e9rature \u00bb psychologique, \u00e0 l\u2019image des variations climatiques : \u00ab sa vie s\u2019\u00e9coule sur cette terre comme les eaux, flottant et ondoyant en une perp\u00e9tuelle diversit\u00e9 de mouvements \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Malgr\u00e9 certaines expressions o\u00f9 il est question de \u00ab suffoquer et \u00e9touffer les passions \u00bb, pour Fran\u00e7ois de Sales il ne s\u2019agit pas d\u2019\u00e9liminer les \u00e9motions, passions et sentiments, chose impossible, mais de les contr\u00f4ler autant que faire se peut, c\u2019est-\u00e0-dire de les mod\u00e9rer et de les orienter vers une fin qui soit bonne. La tradition philosophique, pr\u00e9occup\u00e9e de la \u00ab constance \u00bb, et la tradition spirituelle orient\u00e9e vers la recherche de la paix de l\u2019\u00e2me et la lutte contre l\u2019inqui\u00e9tude, en tant qu\u2019elle est le fruit de l\u2019amour-propre, se rejoignent ici :<br><br><em>Il nous faut t\u00e2cher d\u2019avoir une continuelle et inviolable \u00e9galit\u00e9 de c\u0153ur en une si grande in\u00e9galit\u00e9 d\u2019accidents, et quoique toutes choses se tournent et varient diversement autour de nous, il nous faut demeurer constamment immobiles \u00e0 toujours regarder, tendre et pr\u00e9tendre \u00e0 notre Dieu.<br><\/em><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Les m\u00e9decins que connaissait Fran\u00e7ois de Sales disaient que \u00ab quand les quatre humeurs sont en bon ordre tout va bien, et l\u2019on jouit d\u2019une pleine sant\u00e9 ; comme au contraire, quand l\u2019une pr\u00e9domine sur l\u2019autre on est malade, et \u00e0 mesure que la pr\u00e9domination est grande, la maladie l\u2019est aussi. Par exemple, quand le flegme vient \u00e0 surabonder, il r\u00e9duit l\u2019homme \u00e0 de graves infirmit\u00e9s \u00bb.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 En r\u00e9alit\u00e9, il y en a toujours l\u2019une ou l\u2019autre qui pr\u00e9domine, ce qui fait que la sant\u00e9 n\u2019est presque jamais pleine et enti\u00e8re, mais elle penche toujours de quelque c\u00f4t\u00e9. Il en va de m\u00eame pour les passions et les \u00e9motions. Quand l\u2019une d\u2019elles pr\u00e9domine sur l\u2019autre, elle cause des maladies et des bizarreries :<br><br><em>Aujourd\u2019hui on sera joyeux \u00e0 l\u2019exc\u00e8s, et t\u00f4t apr\u00e8s on sera d\u00e9mesur\u00e9ment triste. En temps de carnaval, on verra des joies et liesses qui se montrent par des actions badines et fol\u00e2tres, et bient\u00f4t apr\u00e8s vous verrez des tristesses et ennuis si extr\u00eames que c\u2019est chose horrible et, ce semble, irr\u00e9m\u00e9diable. Tel aura \u00e0 cette heure trop d\u2019esp\u00e9rance et ne pourra craindre chose quelconque, lequel peu apr\u00e8s sera saisi d\u2019une crainte qui l\u2019enfoncera jusques aux enfers.<br><\/em><br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Quand les passions nous rendent malades, deux m\u00e9thodes sont possibles, correspondant \u00e0 l\u2019allopathie et \u00e0 l\u2019hom\u00e9opathie : \u00ab Nous combattons les passions, ou leur opposant des passions contraires, ou leur opposant des plus grandes affections de leur sorte. \u00bb<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Il ne s\u2019agit donc pas de feindre d\u2019ignorer ces passions et \u00e9motions, comme si elles n\u2019existaient pas \u2013 ce qui est impossible \u2013 mais de \u00ab veiller continuellement sur son c\u0153ur et sur son esprit pour tenir les passions en r\u00e8gle et sous l\u2019empire de la raison ; autrement on ne verra que bizarreries et in\u00e9galit\u00e9s \u00bb. La raison, dit-il encore, \u00ab s\u2019empare tant\u00f4t d\u2019une passion, tant\u00f4t de l\u2019autre, pour la mod\u00e9rer et gouverner \u00bb. Philoth\u00e9e sera heureuse quand elle aura pacifi\u00e9 beaucoup de passions qui l\u2019inqui\u00e9taient.<br>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Le but \u00e0 atteindre est exprim\u00e9 par une formule typique : \u00ab poss\u00e9der son \u00e2me \u00bb, ce qui exige avant tout la patience : \u00ab C\u2019est le grand bonheur de l\u2019homme, Philoth\u00e9e, que de poss\u00e9der son \u00e2me ; et \u00e0 mesure que la patience est plus parfaite, nous poss\u00e9dons plus parfaitement nos \u00e2mes. \u00bb Malgr\u00e9 les difficult\u00e9s, il faut t\u00e2cher d\u2019acqu\u00e9rir \u00ab ce bien non pareil de l\u2019\u00e9galit\u00e9 \u00bb. L\u2019\u00e9galit\u00e9 de l\u2019esprit est \u00ab un des plus illustres ornements de la vie chr\u00e9tienne et un des plus aimables moyens pour acqu\u00e9rir et conserver la gr\u00e2ce de Dieu, et m\u00eame de bien \u00e9difier le prochain. Ce sera le r\u00f4le des facult\u00e9s sup\u00e9rieures, la raison et surtout la volont\u00e9, de \u00ab r\u00e9gler \u00bb les passions.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La psychologie moderne a montr\u00e9 l\u2019importance et l\u2019influence de nos \u00e9motions dans la vie de&#8230;<\/p>\n","protected":false},"author":17,"featured_media":35996,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":195,"footnotes":""},"categories":[125],"tags":[1716,2634,2194,2221,1968,2022,2028],"class_list":["post-36002","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-saints","tag-charisme-salesien","tag-conciles","tag-education","tag-formation","tag-saints","tag-vertus","tag-vie"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/posts\/36002","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/comments?post=36002"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/posts\/36002\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/media\/35996"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/media?parent=36002"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/categories?post=36002"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/tags?post=36002"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}