{"id":20146,"date":"2023-12-13T13:45:47","date_gmt":"2023-12-13T13:45:47","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=20146"},"modified":"2024-02-02T15:59:15","modified_gmt":"2024-02-02T15:59:15","slug":"artemide-zatti-bon-samaritain-pour-les-malades-les-medecins-et-les-infirmiers-video","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/fr\/nos-saints\/artemide-zatti-bon-samaritain-pour-les-malades-les-medecins-et-les-infirmiers-video\/","title":{"rendered":"Art\u00e9mide Zatti, bon samaritain pour les malades, les m\u00e9decins et les infirmiers (vid\u00e9o)"},"content":{"rendered":"\n<p><strong><strong>\u00ab&nbsp;Zatti-H\u00f4pital&nbsp;\u00bb<br><\/strong><\/strong>Zatti et l&rsquo;h\u00f4pital formaient un couple ins\u00e9parable. Le p\u00e8re Entraigas se souvient que lorsqu&rsquo;il y avait un appel t\u00e9l\u00e9phonique, le coadjuteur s&rsquo;\u00e9criait presque d&rsquo;un coup sec : \u00a0\u00bb Zatti-H\u00f4pital \u00ab\u00a0. Sans s&rsquo;en rendre compte, il exprimait <strong>la r\u00e9alit\u00e9 ins\u00e9parable entre sa personne et l&rsquo;h\u00f4pital<\/strong>. Devenu responsable de l&rsquo;h\u00f4pital en 1913, apr\u00e8s la mort du P\u00e8re Garrone et le d\u00e9part de Giacinto Massini de la Congr\u00e9gation, il assume peu \u00e0 peu toutes les t\u00e2ches, mais il est avant tout et indubitablement \u00ab\u00a0l&rsquo;infirmier\u00a0\u00bb de <em>San Jos\u00e9<\/em>. Il ne contentait pas de la bonne volont\u00e9, mais il essayait de perfectionner ses connaissances empiriques par l&rsquo;\u00e9tude personnelle. Il a continu\u00e9 \u00e0 \u00e9tudier tout au long de sa vie et, surtout, il a acquis une grande exp\u00e9rience au cours de ses 48 ann\u00e9es de pratique \u00e0 <em>San Jos\u00e9<\/em>. Le docteur Sussini, qui fut l&rsquo;un de ceux qui le pratiqu\u00e8rent le plus longtemps, apr\u00e8s avoir affirm\u00e9 que Zatti soignait les malades \u00ab\u00a0<strong><em><strong><em>avec une sainte vocation<\/em><\/strong><\/em><\/strong>\u00ab\u00a0, ajoutait : \u00ab\u00a0Pour autant que je sache, M. Zatti, depuis que je l&rsquo;ai connu, \u00e9tant un homme m\u00fbr, d\u00e9j\u00e0 form\u00e9, n&rsquo;avait pas n\u00e9glig\u00e9 sa culture g\u00e9n\u00e9rale, ni ses connaissances en mati\u00e8re d&rsquo;infirmerie et de pr\u00e9paration \u00e0 la pharmacie\u00a0\u00bb.<br>Le p\u00e8re De Roia a parl\u00e9 lui aussi de la formation professionnelle de Zatti : \u00ab\u00a0En ce qui concerne la formation culturelle et professionnelle, je me souviens d&rsquo;avoir vu des livres et des publications sur la m\u00e9decine et de lui avoir demand\u00e9 une fois quand il les lisait, et il m&rsquo;a r\u00e9pondu qu&rsquo;il le faisait la nuit ou pendant la sieste des patients, une fois qu&rsquo;il avait termin\u00e9 ses t\u00e2ches \u00e0 l&rsquo;h\u00f4pital. Il m&rsquo;a \u00e9galement dit que le Dr Sussini lui pr\u00eatait parfois des livres et j&rsquo;ai vu qu&rsquo;il consultait souvent le \u00ab\u00a0Vademecum et les livres de cuisine\u00a0\u00bb.<br>Le Dr Pietro Echay a\ufb00irme que pour Zatti, \u00ab\u00a0<strong>l&rsquo;h\u00f4pital \u00e9tait un sanctuaire<\/strong>\u00ab\u00a0. Le p\u00e8re Feliciano Lopez d\u00e9crit la position de Zatti \u00e0 l&rsquo;h\u00f4pital comme suit, apr\u00e8s l&rsquo;avoir longuement fr\u00e9quent\u00e9 : \u00ab\u00a0Zatti \u00e9tait un homme de gouvernement, il savait exprimer clairement ce qu&rsquo;il voulait, mais <strong>il accompagnait ses actions de douceur, de respect et de joie<\/strong>. Il ne s&#8217;emportait jamais, il d\u00e9dramatisait m\u00eame avec bonhomie, mais son exemple d&rsquo;assiduit\u00e9 \u00e9tait formidable, et plus qu&rsquo;un directeur sans titre, il \u00e9tait devenu une sorte de travailleur universel ; en outre, il progressait rapidement dans sa comp\u00e9tence professionnelle, jusqu&rsquo;\u00e0 gagner aussi le respect des m\u00e9decins et encore plus des subordonn\u00e9s. C&rsquo;est pourquoi je n&rsquo;ai jamais entendu dire que dans ce petit monde de 60 ou 70 patients hospitalis\u00e9s, il y avait dans les premiers temps plusieurs religieuses, des femmes qui offraient leurs services et quelques infirmi\u00e8res&nbsp;; la paix ne r\u00e9gnait pas toujours, et m\u00eame si, comme il est logique, il y avait parfois des querelles, celles-ci ne d\u00e9g\u00e9n\u00e9raient pas gr\u00e2ce \u00e0 la prudence de Zatti, qui savait comment rem\u00e9dier aux d\u00e9viations\u00a0\u00bb.<br>L&rsquo;<em>H\u00f4pital San Jos\u00e9 <\/em>\u00e9tait un sanctuaire sp\u00e9cial de la souffrance humaine. Dans chaque fr\u00e8re et s\u0153ur dans le besoin Art\u00e9mide embrassait et gu\u00e9rissait la chair souffrante du Christ, donnant un sens et une esp\u00e9rance \u00e0 la souffrance humaine. Zatti &#8211; et avec lui de nombreux hommes et femmes de bonne volont\u00e9 &#8211; <strong>a incarn\u00e9 la parabole du bon Samaritain <\/strong>: il s&rsquo;est fait le prochain de chacun, a tendu la main, a soulag\u00e9, a gu\u00e9ri. Pour lui, chaque malade \u00e9tait comme un fils \u00e0 aimer. Hommes et femmes, grands et petits, riches et pauvres, intelligents et ignorants, tous \u00e9taient trait\u00e9s avec respect et amour, sans importuner ni rejeter les insolents et les d\u00e9sagr\u00e9ables. Il avait l&rsquo;habitude de dire : \u00ab\u00a0Parfois, vous pouvez avoir devant vous quelqu&rsquo;un avec un beau visage, d&rsquo;autres fois quelqu&rsquo;un de d\u00e9sagr\u00e9able, mais devant Dieu, nous sommes tous \u00e9gaux\u00a0\u00bb.<br>Malgr\u00e9 la pauvret\u00e9 des moyens, et beaucoup de ceux qui \u00e9taient hospitalis\u00e9s \u00e9taient pauvres, Zatti a suivi les r\u00e8gles concernant la sant\u00e9 et l&rsquo;hygi\u00e8ne \u00e0 l&rsquo;h\u00f4pital, compte tenu des temps, des lieux et des situations de tous les h\u00f4pitaux, m\u00eame nationaux de l&rsquo;\u00e9poque. \u00c0 cette \u00e9poque, en effet, on proc\u00e9dait de fa\u00e7on moins rigoureuse, mais il n&rsquo;y a aucune preuve que le sal\u00e9sien coadjuteur, en tant qu&rsquo;infirmier, ait manqu\u00e9 de justice et de charit\u00e9 envers les malades. Il \u00e9tait bien form\u00e9 pour sa t\u00e2che et bien exp\u00e9riment\u00e9, il savait ce qu&rsquo;il avait \u00e0 faire et les limites de ses comp\u00e9tences, et il n&rsquo;y a aucun souvenir d&rsquo;une quelconque erreur, d&rsquo;une quelconque n\u00e9gligence ou d&rsquo;une quelconque accusation \u00e0 son encontre. Le Dr Sussini a d\u00e9clar\u00e9 : \u00ab\u00a0Dans ses interventions aupr\u00e8s des malades, il a toujours respect\u00e9 les r\u00e8gles l\u00e9gales, sans outrepasser ses pouvoirs [&#8230;]. Je voudrais souligner que dans toutes ses interventions, il a consult\u00e9 des m\u00e9decins parmi ceux qui \u00e9taient toujours \u00e0 ses c\u00f4t\u00e9s pour le soutenir. \u00c0 ma connaissance, il n&rsquo;a pas effectu\u00e9 d&rsquo;interventions difficiles [&#8230;]. Il est certain qu&rsquo;il a utilis\u00e9 les prescriptions hygi\u00e9niques \u00e9tablies, m\u00eame si parfois, \u00e9tant donn\u00e9 sa grande foi, il les a jug\u00e9es excessives. Le contexte socio-\u00e9conomique dans lequel M. Zatti a principalement exerc\u00e9 son activit\u00e9 \u00e9tait celui d&rsquo;une \u00e9conomie et d&rsquo;un niveau d&rsquo;\u00e9ducation peu \u00e9lev\u00e9s. Dans son travail au sein de l&rsquo;h\u00f4pital, il mettait en pratique les connaissances bien \u00e9tablies en mati\u00e8re d&rsquo;hygi\u00e8ne et de technique qu&rsquo;il connaissait d\u00e9j\u00e0 et d&rsquo;autres qu&rsquo;il apprenait en s&rsquo;adressant \u00e0 des professionnels. \u00c0 l&rsquo;ext\u00e9rieur de l&rsquo;h\u00f4pital, son action a \u00e9t\u00e9 plus difficile car changer l&rsquo;environnement existant \u00e9tait tr\u00e8s difficile et d\u00e9passait ses efforts\u00a0\u00bb.<br>Luigi Palma \u00e0 \u00e9largi sa r\u00e9flexion : \u00ab\u00a0La discr\u00e9tion et la prudence du comportement de M. Zatti \u00e9taient de notori\u00e9t\u00e9 publique \u00e0 Viedma ; en revanche, tout abus en la mati\u00e8re serait rapidement devenu de notori\u00e9t\u00e9 publique dans une petite agglom\u00e9ration comme Viedma et l&rsquo;on n&rsquo;en a jamais entendu parler. M. Zatti n&rsquo;a jamais d\u00e9pass\u00e9 ses comp\u00e9tences. Je ne crois pas qu&rsquo;il ait effectu\u00e9 des op\u00e9rations difficiles. S&rsquo;il y avait eu des abus, les m\u00e9decins l&rsquo;auraient signal\u00e9, mais ils n&rsquo;ont fait que louer le travail de M. Zatti [&#8230;]. M. Zatti a pris les pr\u00e9cautions d&rsquo;hygi\u00e8ne qui s&rsquo;imposaient. Je le sais parce qu&rsquo;il m&rsquo;a soign\u00e9 \u00e0 plusieurs reprises : injections ou petites cures avec toute la diligence requise\u00a0\u00bb.<br>\u00c0 un homme qui a consacr\u00e9 toute sa vie, avec d&rsquo;\u00e9normes sacrifices, aux malades, qui a <strong>\u00e9t\u00e9 recherch\u00e9 par eux comme une b\u00e9n\u00e9diction<\/strong>, qui a gagn\u00e9 l&rsquo;estime de tous les m\u00e9decins qui ont collabor\u00e9 avec lui et contre lequel aucune voix d&rsquo;accusation n&rsquo;a jamais pu s&rsquo;\u00e9lever, il serait injuste de reprocher quelques libert\u00e9s que son exp\u00e9rience et sa prudence ont pu lui permettre dans certaines circonstances particuli\u00e8res : l&rsquo;exercice sublime de la charit\u00e9, m\u00eame dans ce cas, valait plus que l&rsquo;observation d&rsquo;une prescription formelle.<br><br><strong>Avec le c\u0153ur de Don Bosco<br><\/strong>En Zatti s&rsquo;est r\u00e9alis\u00e9 ce que Don Bosco avait recommand\u00e9 aux premiers missionnaires sal\u00e9siens en partance pour l&rsquo;Argentine : \u00ab\u00a0Occupez-vous <strong>sp\u00e9cialement des malades, des enfants, des vieillards et des pauvres, et vous gagnerez la b\u00e9n\u00e9diction de Dieu et la bienveillance des hommes<\/strong>\u00ab\u00a0. Comme un bon samaritain, Zatti accueillit dans l&rsquo;auberge de son c\u0153ur et \u00e0 l&rsquo;h\u00f4pital San Jos\u00e9 de Viedma les pauvres, les malades, les exclus de la soci\u00e9t\u00e9. Dans chacun d&rsquo;eux, il a visit\u00e9 le Christ, soign\u00e9 le Christ, nourri le Christ, habill\u00e9 le Christ, log\u00e9 le Christ, honor\u00e9 le Christ. Un m\u00e9decin de l&rsquo;h\u00f4pital t\u00e9moigne : \u00ab\u00a0Le seul miracle que j&rsquo;ai vu dans ma vie, c&rsquo;est M. Zatti, \u00e0 cause de l&rsquo;extraordinaire caract\u00e8re, de la capacit\u00e9 de servir son prochain et de l&rsquo;extraordinaire patience avec les malades\u00a0\u00bb.<br>Zatti a su reconna\u00eetre en chaque fr\u00e8re, en chaque s\u0153ur, en chaque personne particuli\u00e8rement pauvre et n\u00e9cessiteuse qu&rsquo;il rencontrait, un don : il a su voir en chacun d&rsquo;eux le visage lumineux de J\u00e9sus. Combien de fois s&rsquo;exclamait-il en accueillant un pauvre ou un infirme : \u00ab\u00a0J\u00e9sus vient ! &#8211; Le Christ vient ! Ce regard fix\u00e9 sur J\u00e9sus, surtout \u00e0 l&rsquo;heure de l&rsquo;\u00e9preuve et de la nuit de l&rsquo;esprit, sera la force qui lui permettra de ne pas \u00eatre prisonnier de ses propres pens\u00e9es et de ses propres peurs.<br>Dans l&rsquo;exercice de cette charit\u00e9, Zatti a fait resplendir l&rsquo;\u00e9treinte de Dieu pour tout \u00eatre humain, en particulier pour les derniers et les souffrants, en y engageant son c\u0153ur, son \u00e2me et tout son \u00eatre, parce qu&rsquo;il a v\u00e9cu avec les pauvres et pour les pauvres. Ce n&rsquo;\u00e9tait pas un simple service, mais une manifestation tangible de l&rsquo;amour de Dieu, reconnaissant et servant dans les pauvres et les malades le visage du Christ souffrant avec la douceur et la tendresse d&rsquo;une m\u00e8re. Vivant avec les pauvres, il a pratiqu\u00e9 la charit\u00e9 dans un esprit de pauvret\u00e9. Il n&rsquo;\u00e9tait pas un fonctionnaire ou un bureaucrate, un prestataire de services, mais un authentique ouvrier de la charit\u00e9 : et en <strong>voyant, en reconnaissant et en servant le Christ dans les pauvres et les exclus<\/strong>, il \u00e9duquait aussi les autres. Lorsqu&rsquo;il demandait quelque chose, il le demandait pour J\u00e9sus : \u00ab\u00a0Donnez-moi des v\u00eatements pour un J\u00e9sus petit vieux\u00a0\u00bb ; \u00ab\u00a0Donnez-moi des v\u00eatements pour un J\u00e9sus de 12 ans !<br>Impossible de ne pas se souvenir de ses <strong>aventures en bicyclette<\/strong>, de ses chevauch\u00e9es infatigables, avec son classique cache-nez blanc aux extr\u00e9mit\u00e9s et nou\u00e9 \u00e0 la taille, salu\u00e9 avec tendresse par tous ceux qu&rsquo;il rencontrait sur son chemin. Dans la lente progression de sa bicyclette, il avait le temps pour tout : le salut affectueux, le mot amical, le conseil prudent, une indication th\u00e9rapeutique, une aide spontan\u00e9e et d\u00e9sint\u00e9ress\u00e9e : ses grandes poches \u00e9taient toujours pleines de m\u00e9dicaments, qu&rsquo;il distribuait \u00e0 pleines mains aux n\u00e9cessiteux. Il allait personnellement \u00e0 la rencontre de ceux qui faisaient appel \u00e0 lui, prodiguant non seulement ses connaissances m\u00e9dicales, qu&rsquo;il poss\u00e9dait, mais aussi la confiance, l&rsquo;optimisme et la foi qui se d\u00e9gageaient de son sourire constant, large et doux, et de la bont\u00e9 de son regard ; le malade grave qui recevait la visite de M. Zatti ressentait l&rsquo;impond\u00e9rable soulagement qu&rsquo;il recevait de la personne qui \u00e9tait \u00e0 ses c\u00f4t\u00e9s ; le malade qui mourait en pr\u00e9sence de M. Zatti le faisait sans angoisse et sans contorsion. La charit\u00e9 dispens\u00e9e avec tant de g\u00e9n\u00e9rosit\u00e9 dans les rues boueuses de Viedma m\u00e9ritait bien qu&rsquo;Art\u00e9mide Zatti soit comm\u00e9mor\u00e9 dans la ville par une rue, un h\u00f4pital et un monument \u00e0 son nom.<br>Il exer\u00e7ait un petit apostolat qui donnait la mesure de sa charit\u00e9, mais qui lui demandait beaucoup en temps, en travail, en difficult\u00e9s et tracas. Comme sa bont\u00e9 et sa bonne volont\u00e9 au service des autres \u00e9taient connues de tous, tout le monde s&rsquo;adressait \u00e0 lui pour les choses les plus diverses. Les directeurs sal\u00e9siens des maisons de la province lui \u00e9crivaient pour lui demander des conseils m\u00e9dicaux, lui envoyaient des confr\u00e8res \u00e0 assister, et confiaient \u00e0 son h\u00f4pital des personnes de service devenues invalides. Les Filles de Marie Auxiliatrice n&rsquo;\u00e9taient pas en reste par rapport aux sal\u00e9siens pour demander des faveurs. Les \u00e9migr\u00e9s italiens demandent de l&rsquo;aide, \u00e9crivent \u00e0 l&rsquo;Italie, sollicitent des pratiques. Ceux qui avaient \u00e9t\u00e9 bien soign\u00e9s \u00e0 l&rsquo;h\u00f4pital, comme s&rsquo;il s&rsquo;agissait d&rsquo;une expression de gratitude, envoyaient des parents et des amis lui demander de l&rsquo;aide en raison de l&rsquo;estime qu&rsquo;ils avaient pour ses soins. Les autorit\u00e9s civiles avaient souvent des personnes incapables \u00e0 soigner et se tournaient vers Zatti. Des prisonniers et d&rsquo;autres personnes, le voyant en bons termes avec les autorit\u00e9s, lui recommandaient de demander la cl\u00e9mence pour eux ou de r\u00e9soudre leurs probl\u00e8mes.<br>La conversion de Lautaro Montalva est un fait qui exprime bien la capacit\u00e9 qu\u2019avait Zatti d\u2019influencer la vie des gens avec son t\u00e9moignage \u00e9vang\u00e9lique et sa parole persuasive. Ce Montalva, appel\u00e9 le Chilien \u00e0 cause de son origine, \u00e9tait un r\u00e9volutionnaire, exploit\u00e9 par les agitateurs politiques habituels. Il diffusait des revues antireligieuses. Finalement abandonn\u00e9 de tous, il tomba dans la mis\u00e8re et fut r\u00e9duit en fin de vie, avec une famille nombreuse. Seul Zatti eut le courage d&rsquo;entrer dans sa masure de bois, de r\u00e9sister \u00e0 sa premi\u00e8re r\u00e9action de r\u00e9bellion et de le gagner par sa charit\u00e9. Le r\u00e9volutionnaire s&rsquo;adoucit et demanda le bapt\u00eame : ses enfants furent \u00e9galement baptis\u00e9s. Zatti l&rsquo;admit \u00e0 l&rsquo;h\u00f4pital. Peu avant sa mort, il avait demand\u00e9 au cur\u00e9 : \u00ab\u00a0Donnez-moi les sacrements qu&rsquo;un chr\u00e9tien doit recevoir ! La conversion de Montalva est un accomplissement de la charit\u00e9 et du courage chr\u00e9tien de Zatti.<br>Zatti faisait de sa mission au service des malades son lieu d\u2019\u00e9ducation o\u00f9 il incarnait au quotidien le Syst\u00e8me Pr\u00e9ventif de Don Bosco &#8211; raison, religion, amour bienveillant &#8211; dans la proximit\u00e9 et l&rsquo;assistance aux n\u00e9cessiteux, en les aidant \u00e0 comprendre et \u00e0 accepter les situations douloureuses de la vie, en t\u00e9moignant de la pr\u00e9sence du Seigneur.<br><br><strong>Zatti infirmier<br><\/strong>Le profil professionnel d&rsquo;Art\u00e9mide Zatti, qui avait commenc\u00e9 par une promesse, s&rsquo;est enracin\u00e9 dans la confiance en la Providence et s&rsquo;est d\u00e9velopp\u00e9 une fois qu&rsquo;il s&rsquo;est remis de sa maladie. L&rsquo;expression \u00ab\u00a0<strong>Credetti, Promisi, Guarii<\/strong>\u00ab\u00a0, <strong>devise de sa canonisation<\/strong>, montre le d\u00e9vouement total de Zatti pour ses fr\u00e8res et s\u0153urs malades, pauvres et n\u00e9cessiteux.<br>Cet engagement, il l&rsquo;a poursuivi quotidiennement jusqu&rsquo;\u00e0 sa mort \u00e0 l&rsquo;h\u00f4pital de San Jos\u00e9, fond\u00e9 par les premiers sal\u00e9siens arriv\u00e9s en Patagonie, et il l&rsquo;a r\u00e9it\u00e9r\u00e9 lors de chaque visite \u00e0 domicile, urgente ou non, qu&rsquo;il effectuait aupr\u00e8s des malades qui avaient besoin de lui.<br>Sur sa bicyclette, dans le bureau de son administrateur, dans la salle d&rsquo;op\u00e9ration, dans la cour pendant les r\u00e9cr\u00e9ations avec ses pauvres \u00ab\u00a0parents\u00a0\u00bb, dans les services hospitaliers qu&rsquo;il visitait chaque jour, il \u00e9tait <strong>toujours un <\/strong>infirmier ; un saint infirmier d\u00e9di\u00e9 \u00e0 la gu\u00e9rison et au soulagement, <strong>apportant le meilleur rem\u00e8de <\/strong>: la pr\u00e9sence joyeuse et optimiste de l&#8217;empathie.<br><br><strong>Une personne et une \u00e9quipe qui font du bien<br><\/strong>C&rsquo;est la foi qui a pouss\u00e9 Art\u00e9mide Zatti \u00e0 une activit\u00e9 infatigable mais raisonnable. Sa cons\u00e9cration religieuse l&rsquo;avait introduit directement et compl\u00e8tement dans le soin des pauvres, des malades et de ceux qui avaient besoin de la sant\u00e9 et de la consolation mis\u00e9ricordieuse de Dieu.<br>M. Zatti a travaill\u00e9 dans le monde de la sant\u00e9 aux c\u00f4t\u00e9s de m\u00e9decins, d&rsquo;infirmi\u00e8res, de personnels de sant\u00e9, de Filles de Marie Auxiliatrice et des nombreuses personnes qui ont collabor\u00e9 avec lui pour soutenir l&rsquo;h\u00f4pital San Jos\u00e9, le premier de la Patagonie argentine, \u00e0 Viedma, dans la premi\u00e8re moiti\u00e9 du XX<sup>e<\/sup> si\u00e8cle.<br>La tuberculose qu&rsquo;il a contract\u00e9e \u00e0 l&rsquo;\u00e2ge de 20 ans n&rsquo;a pas \u00e9t\u00e9 un obstacle pour pers\u00e9v\u00e9rer dans son choix professionnel. <strong>Il a trouv\u00e9 dans la figure du coadjuteur sal\u00e9sien une forme d&rsquo;engagement pour travailler directement avec les pauvres<\/strong>. Sa cons\u00e9cration religieuse, v\u00e9cue dans la profession d&rsquo;infirmier, lui a permis de vivre sa vie consacr\u00e9e au service de Dieu et de ses fr\u00e8res. Naturellement, cela s&rsquo;est manifest\u00e9 dans une personnalit\u00e9 particuli\u00e8re, unique et irrempla\u00e7able. <strong>Art\u00e9mide Zatti \u00e9tait un brave homme, qui travaillait directement avec les pauvres, en faisant le bien.<\/strong><br>Le contact direct avec les pauvres visait la sant\u00e9 des personnes, en soulageant leurs douleurs, en accompagnant les derniers moments de leur vie, en offrant son sourire face \u00e0 l&rsquo;irr\u00e9versible, en tendant la main avec espoir. C&rsquo;est ainsi que <strong>Zatti est devenu une \u00ab\u00a0pr\u00e9sence-m\u00e9decine\u00a0\u00bb <\/strong>: il soignait directement par sa seule pr\u00e9sence amicale.<br>Son principal biographe, le sal\u00e9sien Raul Entraigas, a fait une d\u00e9couverte originale. Il a synth\u00e9tis\u00e9 la vie d&rsquo;Art\u00e9mide Zatti dans l\u2019expression d&rsquo;un de ses compatriotes qui le d\u00e9finissait comme \u00ab\u00a0le parent de tous les pauvres\u00a0\u00bb. Zatti voyait J\u00e9sus lui-m\u00eame dans les orphelins, les malades et les indig\u00e8nes. Il les a trait\u00e9s avec une telle proximit\u00e9, une telle estime et un tel amour <strong>qu&rsquo;ils semblaient tous \u00eatre les membres de sa famille<\/strong>.<br><br><strong>Se former pour aider<br><\/strong>Voyant les besoins du milieu, <strong>Zatti se perfectionna dans son m\u00e9tier<\/strong>. Peu \u00e0 peu, il devint le responsable de l&rsquo;h\u00f4pital, il \u00e9tudia et valida ses connaissances aupr\u00e8s de l&rsquo;\u00c9tat lorsque celui-ci le lui demanda. Les m\u00e9decins qui ont travaill\u00e9 avec Art\u00e9mide, comme les docteurs Molinari et Sussini, t\u00e9moignent que Zatti poss\u00e9dait un grand savoir m\u00e9dical, fruit non seulement de son exp\u00e9rience mais aussi de ses \u00e9tudes.<br>Don De Roia ajoute : \u00ab\u00a0En ce qui concerne sa formation culturelle et professionnelle, je me souviens avoir vu des livres et des publications sur la m\u00e9decine et, lui ayant demand\u00e9 une fois quand il les lisait, il m&rsquo;a r\u00e9pondu qu&rsquo;il le faisait le soir ou pendant le repos des patients l&rsquo;apr\u00e8s-midi, une fois qu&rsquo;il avait termin\u00e9 toutes ses t\u00e2ches \u00e0 l&rsquo;h\u00f4pital\u00a0\u00bb.<br>\u00c0 cet \u00e9gard, il existe un document intitul\u00e9 \u00ab\u00a0Certificats professionnels\u00a0\u00bb, d\u00e9livr\u00e9 par le secr\u00e9tariat de la Sant\u00e9 publique de l\u2019Argentine et portant le <strong>num\u00e9ro d&rsquo;enregistrement professionnel 07253<\/strong>. Il s&rsquo;agit de ses \u00e9tudes \u00e0 l&rsquo;Universit\u00e9 nationale de La Plata en 1948, \u00e0 l&rsquo;\u00e2ge de 67 ans. \u00c0 cela s&rsquo;ajoute une certification ant\u00e9rieure en 1917 en tant que \u00ab\u00a0dipl\u00f4m\u00e9\u00a0\u00bb en pharmacie.<br><strong>Son style de vie l&rsquo;a conduit \u00e0 un engagement dans lequel il a rencontr\u00e9 directement les pauvres, les malades, les n\u00e9cessiteux<\/strong>. C&rsquo;est pourquoi la profession d&rsquo;infirmier avait une valeur ajout\u00e9e : sa pr\u00e9sence \u00e9tait un t\u00e9moignage de la bont\u00e9 de Dieu. Cette fa\u00e7on simple de voir la r\u00e9alit\u00e9 peut aider \u00e0 mieux comprendre la vie de Zatti, en pr\u00eatant une attention particuli\u00e8re au mot \u00ab\u00a0directement\u00a0\u00bb.<br>Dans cette perspective, nous trouvons ce qu&rsquo;il y a de plus authentique chez Zatti, qui met l&rsquo;accent sur ce que l&rsquo;on appelle la \u00ab\u00a0vie religieuse\u00a0\u00bb ou la \u00ab\u00a0cons\u00e9cration\u00a0\u00bb. C&rsquo;est pourquoi Art\u00e9mide est un saint sal\u00e9sien. C&rsquo;est un infirmier saint. C&rsquo;est l&rsquo;h\u00e9ritage qu&rsquo;il a laiss\u00e9 \u00e0 tous. Et c&rsquo;est le d\u00e9fi qu&rsquo;il lance \u00e0 tous et qu&rsquo;il invite \u00e0 relever.<br><br><strong>1908<br><\/strong>Apr\u00e8s avoir recouvr\u00e9 la sant\u00e9, Zatti entre dans la congr\u00e9gation sal\u00e9sienne comme coadjuteur. Il commence \u00e0 travailler dans la pharmacie de l&rsquo;h\u00f4pital San Jos\u00e9, le seul de Viedma.<br><strong>1911<br><\/strong>Apr\u00e8s la mort de Don Evasio Garrone, directeur de l&rsquo;h\u00f4pital, Zatti reste \u00e0 la t\u00eate de la pharmacie et de l&rsquo;h\u00f4pital, le premier de Patagonie. Il y travailla pendant quarante ans.<br><strong>1917<br><\/strong>Il est titulaire d&rsquo;un dipl\u00f4me de pharmacie de l&rsquo;universit\u00e9 de La Plata.<br><strong>1941<br><\/strong>Le b\u00e2timent de l&rsquo;h\u00f4pital est d\u00e9moli. Les patients et les professionnels d\u00e9m\u00e9nagent avec Zatti \u00e0 l&rsquo;\u00e9cole agricole \u00ab\u00a0San Isidro\u00a0\u00bb.<br><strong>1948<br><\/strong>Zatti obtient son dipl\u00f4me d&rsquo;infirmier \u00e0 l&rsquo;universit\u00e9 de La Plata.<br><br><strong>Zatti avec les m\u00e9decins : c\u2019\u00e9tait un p\u00e8re !<br><\/strong>Parmi les principaux collaborateurs de Zatti \u00e0 l&rsquo;<em>H\u00f4pital San Jos\u00e9, il y avait les <\/em>m\u00e9decins. Les relations \u00e9taient d\u00e9licates, car un des m\u00e9decins \u00e9tait le directeur de l&rsquo;h\u00f4pital d&rsquo;un point de vue juridique et avait la responsabilit\u00e9 professionnelle des patients. Zatti \u00e9tait responsable de l&rsquo;organisation et des soins, et des d\u00e9saccords pouvaient survenir. Apr\u00e8s les premi\u00e8res ann\u00e9es, plusieurs m\u00e9decins sont venus \u00e0 Viedma, la capitale du Rio Negro, et \u00e0 Patagones et Zatti devait utiliser leurs sp\u00e9cialisations \u00e0 l&rsquo;h\u00f4pital sans susciter de rivalit\u00e9s. Il se comporta de mani\u00e8re \u00e0 gagner l&rsquo;estime de tous pour sa bont\u00e9 et sa comp\u00e9tence. Dans la documentation, on trouve les noms des directeurs, le Dr Riccardo Spurr et le Dr Francesco Pietrafraccia, puis Antonio Gumersindo Sussini, Ferdinando Molinari, Pietro Echay, Pasquale Attilio Guidi et Giovanni Cadorna Guidi, qui t\u00e9moigneront de la saintet\u00e9 de Zatti, et enfin Harosteguy, Quaranta et Cessi. Il y en eut certainement d&rsquo;autres, plus \u00e9ph\u00e9m\u00e8res, car, apr\u00e8s une p\u00e9riode d&rsquo;apprentissage, les m\u00e9decins aspiraient \u00e0 des lieux plus centraux et plus d\u00e9velopp\u00e9s. Il a \u00e9t\u00e9 unanimement reconnu que Zatti, en tant qu&rsquo;infirmier, \u00e9tait soumis aux instructions et aux r\u00e8gles des m\u00e9decins : il jouissait d&rsquo;un grand prestige aupr\u00e8s de tous en raison de sa bont\u00e9 et ne suscitait pas de plaintes quant aux soins qu&rsquo;il prodiguait aux malades dans sa maison. Le docteur Sussini, qui l&rsquo;a suivi jusqu&rsquo;\u00e0 sa mort, a d\u00e9clar\u00e9 : \u00ab\u00a0Tous les m\u00e9decins, sans exception, lui t\u00e9moignaient de l&rsquo;affection et du respect pour ses vertus personnelles, sa bont\u00e9, sa mis\u00e9ricorde et sa foi pure, sinc\u00e8re et d\u00e9sint\u00e9ress\u00e9e\u00a0\u00bb<a href=\"#_edn1\" id=\"_ednref1\"><sup>[i]<\/sup><\/a> .<br>Le Dr Pasquale Attilio Guidi a pr\u00e9cis\u00e9 : \u00ab\u00a0Il \u00e9tait toujours correct, il suivait les instructions des m\u00e9decins. Je me souviens que le Dr Harosteguy, qui \u00e9tait assez \u00ab\u00a0contestataire\u00a0\u00bb, nerveux, lorsque j&rsquo;\u00e9tais pr\u00e9sent lors d&rsquo;une op\u00e9ration, reprochait parfois \u00e0 M. Zatti ses probl\u00e8mes ; mais \u00e0 la fin de l&rsquo;op\u00e9ration, il lui donnait une tape et s&rsquo;excusait. Nous comprenions ainsi qu&rsquo;il n&rsquo;y avait pas de griefs \u00e0 l&rsquo;encontre de Zatti. Zatti \u00e9tait une personne respect\u00e9e par tous\u00a0\u00bb<a href=\"#_edn2\" id=\"_ednref2\"><sup>[ii]<\/sup><\/a> . La fille du Dr Harosteguy et le Dr Echay confirment le fort caract\u00e8re d&rsquo;Harosteguy et ses emportements injustifi\u00e9s contre Zatti, lequel l&rsquo;a conquis par sa patience. C&rsquo;est d&rsquo;ailleurs le Dr Harosteguy lui-m\u00eame qui, lorsqu&rsquo;il est tomb\u00e9 malade, n&rsquo;a autoris\u00e9 que Zatti \u00e0 venir le voir, appr\u00e9ciant sa pr\u00e9sence et sa proximit\u00e9.<br>Le Dr Molinari a t\u00e9moign\u00e9 : \u00ab\u00a0M. Zatti respectait le corps m\u00e9dical et suivait strictement ses instructions. Mais \u00e9tant donn\u00e9 le grand nombre de patients qui r\u00e9clamaient exclusivement son intervention, il a d\u00fb agir \u00e0 de nombreuses reprises de mani\u00e8re spontan\u00e9e, mais toujours sur la base de ses grandes connaissances, de son exp\u00e9rience et en fonction de ses propres connaissances m\u00e9dicales. Il n&rsquo;a jamais os\u00e9 faire une op\u00e9ration chirurgicale difficile. Il appelait toujours le m\u00e9decin. Nous, les m\u00e9decins, avions de l&rsquo;affection, du respect et de l&rsquo;admiration pour M. Zatti. Ce sentiment \u00e9tait g\u00e9n\u00e9ral [&#8230;]. Je dirais que les patients \u00ab\u00a0adoraient\u00a0\u00bb M. Zatti et lui faisaient une confiance aveugle\u00a0\u00bb<a href=\"#_edn3\" id=\"_ednref3\"><sup>[iii]<\/sup><\/a> .<br>Le Dr Echay a fait cette observation singuli\u00e8re : \u00ab\u00a0Avec tout le personnel de l&rsquo;h\u00f4pital, Zatti \u00e9tait un p\u00e8re ; m\u00eame avec nous, les jeunes m\u00e9decins, il \u00e9tait un bon conseiller\u00a0\u00bb<a href=\"#_edn4\" id=\"_ednref4\"><sup>[iv]<\/sup><\/a> . En ce qui concerne les visites que Zatti effectuait en ville, le Dr Guidi d\u00e9clare : \u00ab\u00a0Les m\u00e9decins n&rsquo;ont jamais consid\u00e9r\u00e9 ce travail de Zatti de mani\u00e8re n\u00e9gative, mais comme une collaboration. [&#8230;] Les patients qu&rsquo;il a servis lui auraient \u00e9lev\u00e9 un monument\u00a0\u00bb<a href=\"#_edn5\" id=\"_ednref5\"><sup>[v]<\/sup><\/a> .<br>M\u00eame les personnes ext\u00e9rieures ont toujours vu des relations \u00e9troites de collaboration et d&rsquo;estime entre Zatti et les m\u00e9decins, comme en t\u00e9moigne le p\u00e8re L\u00f3pez : \u00ab\u00a0Le comportement de M. Zatti envers les m\u00e9decins \u00e9tait consid\u00e9r\u00e9 par eux comme celui d\u2019un accueil cordial. Tous les m\u00e9decins avec lesquels je me suis entretenu \u00e9taient, sans exception, ses admirateurs\u00a0\u00bb<a href=\"#_edn6\" id=\"_ednref6\"><sup>[vi]<\/sup><\/a> . Et le P\u00e8re L\u00f3pez lui-m\u00eame d\u2019ajouter : \u00ab\u00a0Zatti a toujours eu une r\u00e9putation d&rsquo;amabilit\u00e9 envers les m\u00e9decins, de tol\u00e9rance et d\u2019humanit\u00e9 face \u00e0 la mauvaise humeur typique de nombreux m\u00e9decins ; en particulier, le Dr Harosteguy \u00e9tait un homme violent et la vertu de Zatti envers lui peut \u00eatre d\u00e9duite du fait qu&rsquo;il est devenu un admirateur de Zatti, avec des nuances de v\u00e9n\u00e9ration\u00a0\u00bb<a href=\"#_edn7\" id=\"_ednref7\"><sup>[vii]<\/sup><\/a> . Oscar Garcia utilise une expression efficace : \u00ab\u00a0Les m\u00e9decins ont collabor\u00e9 avec l&rsquo;h\u00f4pital en bonne partie parce que M. Zatti \u00e9tait l\u00e0 avec une charit\u00e9 qui touchait les c\u0153urs\u00a0\u00bb<a href=\"#_edn8\" id=\"_ednref8\"><sup>[viii]<\/sup><\/a> . Sa vie a \u00e9branl\u00e9 l&rsquo;indiff\u00e9rence religieuse de certains d&rsquo;entre eux : \u00ab\u00a0Quand je vois Zatti, mon incr\u00e9dulit\u00e9 vacille\u00a0\u00bb<a href=\"#_edn9\" id=\"_ednref9\"><sup>[ix]<\/sup><\/a> . Dans de nombreux cas, il y a eu des conversions et des d\u00e9buts de vie chr\u00e9tienne.<br><br><strong>Zatti et les infirmi\u00e8res : pour nous, il \u00e9tait tout !<br><\/strong>Le groupe le plus important de l&rsquo;h\u00f4pital \u00e9tait le personnel f\u00e9minin. <em>San Jos\u00e9 <\/em>comptait parfois jusqu&rsquo;\u00e0 70 lits. Il \u00e9tait donc naturel d&rsquo;avoir besoin d&rsquo;infirmi\u00e8res, d&rsquo;aides de cuisine, de blanchisseuses et de repasseuses, de femmes de service et d&rsquo;autres employ\u00e9es ayant re\u00e7u une formation professionnelle. Pour les emplois plus humbles et ordinaires, il n&rsquo;\u00e9tait pas difficile de trouver du personnel, car la population comptait de nombreux \u00e9l\u00e9ments pauvres et un stage \u00e0 l&rsquo;h\u00f4pital semblait particuli\u00e8rement souhaitable et s\u00fbr. Il \u00e9tait plus difficile de trouver des infirmi\u00e8res pour lesquelles, peut-\u00eatre dans tout le pays et certainement en Patagonie, il n&rsquo;y avait pas d&rsquo;\u00e9cole de formation. Zatti a d\u00fb se d\u00e9brouiller tout seul : choisir, former, organiser, assister les infirmi\u00e8res, se procurer les moyens de travailler, penser \u00e0 une r\u00e9compense, \u00e0 tel point qu&rsquo;il a \u00e9t\u00e9 l&rsquo;initiateur de la formation du personnel f\u00e9minin de l&rsquo;h\u00f4pital.<br>La Providence amena \u00e0 l&rsquo;h\u00f4pital un certain nombre de jeunes femmes bonnes mais pauvres qui, apr\u00e8s avoir \u00e9t\u00e9 soign\u00e9es et gu\u00e9ries, cherchaient une place dans la vie. Zatti se rendit compte de leur bont\u00e9 et disponibilit\u00e9 ; il montra par son exemple et sa parole combien il \u00e9tait beau de servir le Seigneur dans leurs fr\u00e8res et s\u0153urs malades. Puis il leur proposait discr\u00e8tement de rester avec lui et de partager la mission \u00e0 l&rsquo;h\u00f4pital. Les meilleures filles ont senti la grandeur et la joie de cet id\u00e9al et sont rest\u00e9es \u00e0 <em>San Jos\u00e9<\/em>. Zatti se chargea de les pr\u00e9parer professionnellement et, en bon religieux, veilla \u00e0 leur formation spirituelle. Elles en vinrent ainsi \u00e0 former en groupe une sorte de congr\u00e9gation sans v\u0153ux, d&rsquo;\u00e2mes \u00e9lues qui choisissaient de servir les pauvres. Zatti leur donnait tout ce dont elles avaient besoin pour vivre, m\u00eame s&rsquo;il ne les payait pas d&rsquo;ordinaire, et pensait \u00e0 un bon logement si elles voulaient quitter le service hospitalier. Il ne faut pas croire que la situation de l&rsquo;\u00e9poque exigeait toutes les garanties que les structures hospitali\u00e8res r\u00e9clament aujourd&rsquo;hui. Pour ces jeunes filles, la solution offerte par Zatti d&rsquo;un point de vue mat\u00e9riel \u00e9tait enviable, tout autant que d&rsquo;un point de vue spirituel. En effet, elles \u00e9taient heureuses et lorsque l&rsquo;<em>h\u00f4pital San Jos\u00e9 <\/em>a \u00e9t\u00e9 ferm\u00e9, ou avant, il a \u00e9t\u00e9 difficile pour elles de trouver un bon logement. Elles ont toujours exprim\u00e9 leur gratitude.<br>Le p\u00e8re Entraigas rappelle 13 membres du personnel f\u00e9minin qui ont travaill\u00e9 \u00e0 l&rsquo;h\u00f4pital \u00e0 diff\u00e9rentes \u00e9poques. Parmi les documents figurent les rapports des infirmi\u00e8res : Noelia Morero, Teodolinda Acosta, Felisa Botte, Andrea Rafaela Morales, Maria Danielis. Noelia Morero raconte son histoire, identique \u00e0 celle de plusieurs autres infirmi\u00e8res. Elle est arriv\u00e9e \u00e0 <em>San Jos\u00e9 <\/em>malade : \u00ab\u00a0Ici, j&rsquo;ai \u00e9t\u00e9 malade, puis j&rsquo;ai commenc\u00e9 \u00e0 travailler jusqu&rsquo;\u00e0 la fin de 1944, date \u00e0 laquelle j&rsquo;ai \u00e9t\u00e9 transf\u00e9r\u00e9e \u00e0 l&rsquo;h\u00f4pital r\u00e9gional national de Viedma, qui a ouvert ses portes en 1945 [&#8230;]. Zatti \u00e9tait tr\u00e8s aim\u00e9 et respect\u00e9 par tout le personnel et les patients ; il \u00e9tait le \u00ab\u00a0mouchoir des larmes\u00a0\u00bb de tout le monde. Je ne me souviens d&rsquo;aucune plainte contre lui. Lorsque Zatti entrait dans les chambres, c&rsquo;\u00e9tait comme si \u00ab\u00a0Dieu lui-m\u00eame\u00a0\u00bb y entrait. Je ne sais pas comment l&rsquo;exprimer. Pour nous, c&rsquo;\u00e9tait tout. Je n&rsquo;ai pas connu de difficult\u00e9s particuli\u00e8res ; en tant que malade, je n&rsquo;ai jamais manqu\u00e9 de rien : ni de nourriture, ni de m\u00e9dicaments, ni de v\u00eatements. M. Zatti \u00e9tait particuli\u00e8rement soucieux de la formation morale du personnel. Je me souviens qu&rsquo;il nous formait au moyen de le\u00e7ons pratiques, nous demandant de l&rsquo;accompagner lorsqu&rsquo;il visitait les malades, et apr\u00e8s une ou deux fois, il nous faisait faire cela surtout avec les cas les plus graves\u00a0\u00bb<a href=\"#_edn10\" id=\"_ednref10\"><sup>[x]<\/sup><\/a> .<\/p>\n\n\n\n<p class=\"has-text-align-center\"><strong>Film vu avant la conf\u00e9rence<\/strong><\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/OgIefPstgW4?cc_lang_pref=fr&amp;cc_load_policy=1\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n\n\n\n<p class=\"has-text-align-center\"><br><strong>Vid\u00e9o de la conf\u00e9rence: Zatti le bon samaritain, pour les malades, les m\u00e9decins et les infirmi\u00e8res<\/strong><br>Conf\u00e9rence donn\u00e9e par Don Pierluigi CAMERONI, Postulateur g\u00e9n\u00e9ral de la Soci\u00e9t\u00e9 sal\u00e9sienne de Saint Jean Bosco au Valdocco, le 15.11.2023.<\/p>\n\n\n\n<iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/UAnZ6qR1fJY?cc_lang_pref=fr&amp;cc_load_policy=1\"  title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" allowfullscreen><\/iframe>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p><a id=\"_edn1\" href=\"#_ednref1\"><sup>[i]<\/sup><\/a> T\u00e9moignage du Dr Antonio Gumersindo Sussini. <em>Positio &#8211; Summarium<\/em>, p. 139, \u00a7 561.<\/p>\n\n\n\n<p><a href=\"#_ednref2\" id=\"_edn2\"><sup>[ii]<\/sup><\/a> T\u00e9moignage d&rsquo;Attilio Guidi, pharmacien. Il a connu Zatti de 1926 \u00e0 1951. <em>Positio &#8211; Summarium<\/em>, p. 99, \u00a7 386.<\/p>\n\n\n\n<p><a href=\"#_ednref3\" id=\"_edn3\"><sup>[iii]<\/sup><\/a> T\u00e9moignage du Dr Ferdinando Molinari. Il a connu Zatti de 1942 \u00e0 1951. Il est devenu m\u00e9decin \u00e0 l&rsquo;<em>h\u00f4pital San Jos\u00e9 <\/em>et l&rsquo;a soign\u00e9 pendant sa derni\u00e8re maladie. Il a prononc\u00e9 le discours officiel lors de l&rsquo;inauguration du monument \u00e0 Zatti. <em>Positio &#8211; Summarium<\/em>, p. 147, \u00a7 600.<\/p>\n\n\n\n<p><a href=\"#_ednref4\" id=\"_edn4\"><sup>[iv]<\/sup><\/a> T\u00e9moignage du Dr Pietro Echay. <em>Positio &#8211; Informatio<\/em>, p. 108.<\/p>\n\n\n\n<p><a href=\"#_ednref5\" id=\"_edn5\"><sup>[v]<\/sup><\/a> T\u00e9moignage d&rsquo;Attilio Guidi. <em>Positio &#8211; Summarium<\/em>, p. 100, \u00a7 391.<\/p>\n\n\n\n<p><a href=\"#_ednref6\" id=\"_edn6\"><sup>[vi]<\/sup><\/a> T\u00e9moignage du p\u00e8re Feliciano L\u00f3pez. <em>Positio &#8211; Summarium<\/em>, p. 171, \u00a7 694.<\/p>\n\n\n\n<p><a href=\"#_ednref7\" id=\"_edn7\"><sup>[vii]<\/sup><\/a><em> Ibid., <\/em>p. 166, \u00a7 676.<\/p>\n\n\n\n<p><a href=\"#_ednref8\" id=\"_edn8\"><sup>[viii]<\/sup><\/a> T\u00e9moignage d&rsquo;Oscar Garc\u00eda, employ\u00e9 de police. Il a rencontr\u00e9 Zatti en 1925, mais a surtout trait\u00e9 avec lui apr\u00e8s 1935, \u00e0 la fois en tant que dirigeant des anciens \u00e9l\u00e8ves et en tant que membre du Cercle des travailleurs. <em>Positio &#8211; Summarium<\/em>, p. 111, \u00a7 440.<\/p>\n\n\n\n<p><a href=\"#_ednref9\" id=\"_edn9\"><sup>[ix]<\/sup><\/a> T\u00e9moignage du p\u00e8re Feliciano L\u00f3pez. <em>Positio &#8211; Summarium<\/em>, p. 181, \u00a7 737.<\/p>\n\n\n\n<p><a href=\"#_ednref10\" id=\"_edn10\"><sup>[x]<\/sup><\/a> T\u00e9moignage de Noelia Morero, infirmi\u00e8re. <em>Positio &#8211; Informatio<\/em>, p. 112.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab&nbsp;Zatti-H\u00f4pital&nbsp;\u00bbZatti et l&rsquo;h\u00f4pital formaient un couple ins\u00e9parable. Le p\u00e8re Entraigas se souvient que lorsqu&rsquo;il y&#8230;<\/p>\n","protected":false},"author":6,"featured_media":20136,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":6,"footnotes":""},"categories":[125],"tags":[1716,2563,1758,1992,1932,1968,1956,2616,1860],"class_list":["post-20146","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nos-saints","tag-charisme-salesien","tag-charite","tag-creativite-salesienne","tag-espoir","tag-pauvres","tag-saints","tag-salesiens","tag-temoins","tag-travail"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/posts\/20146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/comments?post=20146"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/posts\/20146\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/media\/20136"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/media?parent=20146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/categories?post=20146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/fr\/wp-json\/wp\/v2\/tags?post=20146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}