{"id":53213,"date":"2026-05-05T13:58:57","date_gmt":"2026-05-05T13:58:57","guid":{"rendered":"https:\/\/www.donbosco.press\/?p=53213"},"modified":"2026-05-05T13:59:17","modified_gmt":"2026-05-05T13:59:17","slug":"vi-congreso-mundial-de-los-salesianos-cooperadores","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/es\/buena-prensa\/vi-congreso-mundial-de-los-salesianos-cooperadores\/","title":{"rendered":"VI Congreso Mundial de los Salesianos Cooperadores"},"content":{"rendered":"<p><em>Del 6 al 10 de mayo de 2026, se celebrar\u00e1 en Roma, en la Casa Fraterna Domus, el VI Congreso Mundial de la Asociaci\u00f3n de Salesianos Cooperadores (ASSCC).<\/em><\/p>\n<p><em>La cita coincide con un aniversario extraordinario: <strong>el 9 de mayo de 2026 la Asociaci\u00f3n cumple 150 a\u00f1os<\/strong>. Fue de hecho el 9 de mayo de 1876 cuando Don Bosco dio forma definitiva a lo que hab\u00eda imaginado como la \u00abparte externa\u00bb de la Familia Salesiana: laicos cat\u00f3licos comprometidos en el mundo, animados por el mismo esp\u00edritu y la misma misi\u00f3n de los hijos de San Juan Bosco. Ciento cincuenta a\u00f1os de historia, de presencia capilar en los barrios, en las parroquias, en las escuelas, en las periferias del mundo, junto a los j\u00f3venes y a las familias m\u00e1s fr\u00e1giles.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Un Congreso esperado y preparado<\/strong><\/p>\n<p>El VI Congreso Mundial ha estado precedido por una preparaci\u00f3n trienal iniciada en 2023 y construida en torno al tema central: \u00abUn sue\u00f1o, una promesa y el futuro\u00bb. Un camino pensado para devolver a cada Salesiano Cooperador a sus propias ra\u00edces, para renovar su propia identidad y para proyectarse hacia los desaf\u00edos de los pr\u00f3ximos a\u00f1os.<\/p>\n<p>El tema se ha articulado en tres dimensiones inseparables.<\/p>\n<p>El <strong>sue\u00f1o<\/strong>, el de Don Bosco, que traz\u00f3 toda su vida y del que tom\u00f3 cuerpo, con el tiempo, toda la Familia Salesiana.<\/p>\n<p>La <strong>promesa<\/strong> es la pronunciada libremente por cada Salesiano Cooperador: la elecci\u00f3n de pertenecer a la Familia Salesiana, de testimoniar el carisma de Don Bosco, de estar junto a los j\u00f3venes con la misma pasi\u00f3n del fundador.<\/p>\n<p>El <strong>futuro<\/strong>, el de ser la \u00abbuena levadura\u00bb que la sociedad necesita, capaces de fermentar desde dentro las realidades en las que se vive, listos para afrontar con creatividad y esperanza los cambios de \u00e9poca del tiempo actual.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>El trienio: recordar, renovar, relanzar<\/strong><\/p>\n<p>Para estructurar este camino, el Consejo Mundial hab\u00eda articulado el trienio en torno a tres verbos din\u00e1micos, uno para cada a\u00f1o:<\/p>\n<p>2023\u20132024 &#8211; <strong>RECORDAR<\/strong>: mirar a los or\u00edgenes, recorrer hechos concretos de la propia historia personal y asociativa. Un ejercicio de memoria viva, no nostalgia, sino reapropiaci\u00f3n de una identidad.<\/p>\n<p>2024\u20132025 &#8211; <strong>RENOVAR<\/strong>: nutrirse de las novedades introducidas por el Proyecto de Vida Apost\u00f3lica (PVA), fortalecer el sentido de pertenencia a la Asociaci\u00f3n.<\/p>\n<p>2025\u20132026 &#8211; <strong>RELANZAR<\/strong>: hacer emerger con mayor claridad la identidad de los Salesianos Cooperadores, afrontar los desaf\u00edos de los pr\u00f3ximos a\u00f1os. Y es precisamente este relanzamiento el que el VI Congreso Mundial est\u00e1 llamado a sancionar y orientar.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Qu\u00e9 se decidir\u00e1 en el Congreso<\/strong><\/p>\n<p>El Congreso no es solo una celebraci\u00f3n. Es un momento de gobierno y discernimiento asociativo de gran relevancia. Los delegados provenientes de todo el mundo \u2014representantes de las diferentes regiones e inspector\u00edas\u2014 examinar\u00e1n el estado de la Asociaci\u00f3n, evaluar\u00e1n los frutos del trienio reci\u00e9n concluido y establecer\u00e1n las l\u00edneas de actuaci\u00f3n operativas para el sexenio 2026\u20132032. Se trata de un trabajo serio de reflexi\u00f3n compartida, en el que emergen las prioridades apost\u00f3licas, las estrategias formativas y las orientaciones pr\u00e1cticas que guiar\u00e1n a la ASSCC en los pr\u00f3ximos seis a\u00f1os.<\/p>\n<p>Un momento particularmente esperado es el nombramiento del nuevo Coordinador Mundial de la Asociaci\u00f3n para el sexenio 2026\u20132032, que corresponde al Rector Mayor de los Salesianos. Una elecci\u00f3n que expresa la profunda comuni\u00f3n entre la ASSCC y la Congregaci\u00f3n Salesiana, custodios juntos del mismo carisma.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>El 9 de mayo: coraz\u00f3n del Congreso<\/strong><\/p>\n<p>En esta fecha, exactamente ciento cincuenta a\u00f1os despu\u00e9s de la fundaci\u00f3n, el Congreso se detendr\u00e1 para celebrar el 150\u00ba aniversario de la Asociaci\u00f3n. No ser\u00e1 un momento de autocomplacencia, sino un acto de gratitud y de renovaci\u00f3n de la promesa originaria.<\/p>\n<p>Ciento cincuenta a\u00f1os durante los cuales much\u00edsimos hombres y mujeres, en cada rinc\u00f3n del planeta, han elegido vivir como \u00absalesianos en el mundo\u00bb: en las f\u00e1bricas y en las oficinas, en las familias y en las parroquias, en las escuelas y en los barrios dif\u00edciles, junto a los j\u00f3venes a los que nadie miraba.<\/p>\n<p>El 9 de mayo de 1876 fue una fecha fundacional; el 9 de mayo de 2026 quiere ser una fecha de relanzamiento. Una promesa renovada, una misi\u00f3n reafirmada, un impulso reencontrado.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Un Congreso abierto al mundo<\/strong><\/p>\n<p>Una de las novedades m\u00e1s significativas de esta edici\u00f3n es la dimensi\u00f3n de participaci\u00f3n universal que los responsables han querido garantizar. Diversos momentos del Congreso ser\u00e1n transmitidos en directo por streaming en el canal oficial de YouTube de la Asociaci\u00f3n, para que cada Salesiano Cooperador del mundo \u2014incluso quien no pueda estar f\u00edsicamente en Roma\u2014 pueda vivir el Congreso \u00aben comuni\u00f3n asociativa\u00bb, sinti\u00e9ndose parte de un \u00fanico cuerpo.<\/p>\n<p>En los meses que han precedido al evento, el sitio web oficial de la Asociaci\u00f3n ha puesto a disposici\u00f3n materiales, subsidios formativos, recursos gr\u00e1ficos y noticias, permitiendo a todas las comunidades locales prepararse y entrar en el clima del Congreso. Un himno oficial \u2014\u00bbCon la fuerza del amor\u00bb\u2014 ha acompa\u00f1ado este tiempo de preparaci\u00f3n, convirti\u00e9ndose en el s\u00edmbolo sonoro de este momento hist\u00f3rico.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>El hilo conductor: levadura en la historia<\/strong><\/p>\n<p>El tema elegido para el VI Congreso Mundial \u2014\u00bbSer levadura para ser fecundos\u00bb\u2014 no es un simple eslogan. Es una teolog\u00eda, un estilo de vida, una vocaci\u00f3n.<\/p>\n<p>La levadura no se ve, no ocupa espacio, no hace ruido. Pero transforma. Es la imagen evang\u00e9lica de la presencia cristiana en el mundo: peque\u00f1a, silenciosa, capilar, pero capaz de hacer crecer lo que toca. Y es exactamente la imagen que Don Bosco ten\u00eda en mente cuando pensaba en sus \u00absalesianos externos\u00bb: no una \u00e9lite separada del mundo, sino fermento dentro de la masa de la historia, capaces de transformarla desde dentro con la fuerza discreta del amor.<\/p>\n<p>A 150 a\u00f1os de aquella intuici\u00f3n genial, los Salesianos Cooperadores se re\u00fanen en Roma para reencontrar esa fuerza, esa identidad, esa promesa. Y para escuchar una vez m\u00e1s la sugerencia que Don Bosco dej\u00f3 como herencia espiritual a los suyos: \u00abConfiad todo a Jes\u00fas Eucarist\u00eda y a Mar\u00eda Auxiliadora y ver\u00e9is lo que son los milagros\u00bb.<\/p>\n<p>Un sue\u00f1o que contin\u00faa, una promesa que se renueva, un futuro que se abre.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><em>El calendario del evento se puede consultar en <\/em><a href=\"http:\/\/www.asscc-mondiale.org\/webSite\/agenda-vi-cm\"><em>www.asscc-mondiale.org\/webSite\/agenda-vi-cm<\/em><\/a><\/p>\n<p><em>Para informaci\u00f3n y actualizaciones sobre el evento: <\/em><a href=\"http:\/\/www.asscc-mondiale.org\"><em>www.asscc-mondiale.org<\/em><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Del 6 al 10 de mayo de 2026, se celebrar\u00e1 en Roma, en la Casa&#8230;<\/p>\n","protected":false},"author":1,"featured_media":53214,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":50,"footnotes":""},"categories":[175],"tags":[1708,1720,1756,1768,2582,1822,1912],"class_list":["post-53213","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-buena-prensa","tag-benefactores","tag-carisma-salesiano","tag-cooperadores-salesianos","tag-don-bosco","tag-eventos","tag-gracia","tag-noticias-religiosas"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/53213","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/comments?post=53213"}],"version-history":[{"count":1,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/53213\/revisions"}],"predecessor-version":[{"id":53221,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/53213\/revisions\/53221"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media\/53214"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media?parent=53213"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/categories?post=53213"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/tags?post=53213"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}