{"id":19560,"date":"2023-10-18T16:36:31","date_gmt":"2023-10-18T16:36:31","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=19560"},"modified":"2024-05-02T10:36:10","modified_gmt":"2024-05-02T10:36:10","slug":"has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-6-10","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/es\/pastoral-juvenil-es\/has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-6-10\/","title":{"rendered":"\u00bfHas pensado en tu vocaci\u00f3n? San Francisco de Sales podr\u00eda ayudarte (6\/10)"},"content":{"rendered":"\n<p><em><a href=\"..\/es\/pastoral-juvenil-es\/has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-5-10\">(continuaci\u00f3n del art\u00edculo anterior)<\/a><\/em><\/p>\n\n\n\n<p><strong><strong>6. Todo va bien en casa<br><\/strong><\/strong><br>Queridos j\u00f3venes,<br>\u201cCreo que, en el mundo, no hay almas que amen m\u00e1s cordialmente, m\u00e1s tiernamente y, por decirlo muy casualmente, con m\u00e1s amor que yo, porque a Dios le ha placido hacer que mi coraz\u00f3n sea as\u00ed. Se dice en mi familia que la primera frase que apareci\u00f3 en mis labios de ni\u00f1o fue: \u201cMi madre y Dios me quieren mucho\u201d.<br><br>Desde muy peque\u00f1o estuve entre la gente. Mi padre hab\u00eda decidido que no me educar\u00eda en nuestro castillo, sino en una escuela m\u00e1s normal, compar\u00e1ndome con otros compa\u00f1eros y profesores, en definitiva, alej\u00e1ndome de la especie de \u201cburbuja de amor\u201d que se hab\u00eda creado en el castillo.<br>De regreso de mis estudios en Par\u00eds y Padua, estaba bien convencido de mi elecci\u00f3n de hacerme sacerdote, pero mi pap\u00e1 no era del todo de esa opini\u00f3n: hab\u00eda preparado, sin que yo lo supiera, una completa biblioteca sobre Derecho, un puesto de senador y una noble prometida. No fue f\u00e1cil doblegarlo hacia otro camino. Present\u00e9 con calma mis intenciones a pap\u00e1: \u00abPadre m\u00edo, le servir\u00e9 hasta mi \u00faltimo aliento de vida, prometo todo el servicio a mis hermanos. Usted me habla de reflexi\u00f3n, Padre m\u00edo. Puedo decirle que he tenido la idea del sacerdocio desde que era un ni\u00f1o\u201d. El Padre, aunque era \u201cde esp\u00edritu muy firme\u201d, llor\u00f3. La madre intervino suavemente. Se hizo el silencio. La nueva realidad, bajo la palabra silenciosa de Dios, ferment\u00f3. Mi padre dijo: \u201cHijo m\u00edo, haz en Dios y para Dios lo que \u00c9l te inspire. Por \u00c9l, te doy mi bendici\u00f3n\u201d. Entonces no pudo m\u00e1s: se encerr\u00f3 bruscamente en su estudio.<br>Al final de la vida de mi padre, tuve la gracia de discernir en s\u00edntesis todo el amor que le hac\u00eda tan querido: en su candor, en su capacidad para asumir compromisos importantes, en su asunci\u00f3n de la responsabilidad de guiarme hasta el final, en la confianza constante que mostr\u00f3 en m\u00ed, discern\u00ed siempre la bondad de un hombre noble, acostumbrado tambi\u00e9n a una vida dura, pero con un gran coraz\u00f3n. Adem\u00e1s, con el paso del tiempo, su temperamento vivaz se suaviz\u00f3, incluso aprendi\u00f3 a permitir que le llevaran la contraria: la buena influencia a largo plazo de mi madre fue decisiva.<br>Pap\u00e1 y mam\u00e1 me mostraron realmente dos caras diferentes, pero complementarias, de la gracia y la bondad de Dios.<br>Quiz\u00e1 ustedes tambi\u00e9n, como yo, se hayan preguntado c\u00f3mo vivir la fatiga de experimentar que la vocaci\u00f3n que est\u00e1n descubriendo es diferente de lo que los dem\u00e1s esperar\u00edan. He propuesto, tanto a los hombres m\u00e1s sencillos de mi tierra como a los reyes de Francia, un camino muy simple pero muy exigente: por un lado, que \u201cnada te moleste\u201d y \u201cnada pedir y nada rechazar\u201d; por otra parte, que la existencia, con las elecciones que conlleva, encuentre su sentido en el hecho de enfrentarse, incluso con fatiga, exclusivamente a vivir \u201ccomo a Dios le place\u201d. S\u00f3lo de aqu\u00ed nace la \u201calegr\u00eda perfecta\u201d, que probablemente une a todos los verdaderos santos, hombres y mujeres de Dios de ayer y de hoy.<\/p>\n\n\n\n<p><br><br><em><em><em>Oficina de Animaci\u00f3n Vocacional<\/em><\/em><\/em><\/p>\n\n\n\n<p><em><a href=\"..\/es\/pastoral-juvenil-es\/has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-7-10\">(continuaci\u00f3n)<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(continuaci\u00f3n del art\u00edculo anterior) 6. Todo va bien en casaQueridos j\u00f3venes,\u201cCreo que, en el mundo,&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19552,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":16,"footnotes":""},"categories":[548],"tags":[2566,2636,2558,1768,1822,2190,1816,2620,2637],"class_list":["post-19560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pastoral-juvenil-es","tag-caridad","tag-consejos","tag-dios","tag-don-bosco","tag-gracia","tag-jesus","tag-jovenes","tag-testigos","tag-vocaciones"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/19560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/comments?post=19560"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/19560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media\/19552"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media?parent=19560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/categories?post=19560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/tags?post=19560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}