{"id":18367,"date":"2023-09-04T17:24:30","date_gmt":"2023-09-04T17:24:30","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=18367"},"modified":"2024-05-02T10:34:58","modified_gmt":"2024-05-02T10:34:58","slug":"has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-2-10","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/es\/pastoral-juvenil-es\/has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-2-10\/","title":{"rendered":"\u00bfHas pensado en tu vocaci\u00f3n? San Francisco de Sales podr\u00eda ayudarte (2\/10)"},"content":{"rendered":"\n<p><em><a href=\"..\/es\/pastoral-juvenil-es\/has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-1-10\">(continuaci\u00f3n del art\u00edculo anterior)<\/a><\/em><\/p>\n\n\n\n<p><strong><strong>2. Qu\u00e9 hacer ma\u00f1ana<br><\/strong><\/strong><br>Queridos j\u00f3venes,<br>seguro que se preguntar\u00e1n: \u00bfqu\u00e9 haremos m\u00e1s tarde, qu\u00e9 cosa esperar de la vida? \u00bfA qu\u00e9 estamos llamados? Son preguntas que todo el mundo se hace, consciente o incluso inconscientemente. Quiz\u00e1s conozcan la palabra vocaci\u00f3n. Qu\u00e9 palabra tan extra\u00f1a: \u00a1vocaci\u00f3n! Si lo prefieren, podemos hablar de felicidad, del sentido de la vida, de la voluntad de vivir&#8230;<br>Vocaci\u00f3n significa llamada. \u00bfQui\u00e9n llama? Es una buena pregunta. Quiz\u00e1s alguien que me quiere. Cada uno de nosotros tiene su propia vocaci\u00f3n. La m\u00eda fue un poco especial. En mi Saboya natal, cuando era peque\u00f1o, a los once a\u00f1os, me sent\u00ed llamado a entregarme a Dios al servicio de su pueblo, pero mis padres, en particular mi pap\u00e1, ten\u00eda otros planes para m\u00ed, ya que era el mayor de la familia. Con el paso de los a\u00f1os y durante los estudios que mi pap\u00e1 me hizo hacer en Par\u00eds, mi deseo crec\u00eda cada vez m\u00e1s: gram\u00e1tica, literatura, filosof\u00eda, pero tambi\u00e9n equitaci\u00f3n, esgrima, baile&#8230;<br>A los 17 a\u00f1os, tuve una crisis. Me iba bien en los estudios, pero mi coraz\u00f3n no estaba satisfecho. Buscaba algo&#8230; Durante el carnaval de Par\u00eds, un compa\u00f1ero me vio triste: \u201c\u00bfQu\u00e9 te pasa, est\u00e1s enfermo? Vamos a ver el carnaval\u201d, \u201cpero yo no quiero ver el carnaval\u201d, le contest\u00e9, \u201c\u00a1quiero ver a Dios!\u201d. Aquel a\u00f1o, un famoso profesor de Biblia explicaba el Cantar de los Cantares. Fui a escucharle. Fue como un rayo para m\u00ed. La Biblia era una historia de amor. \u00a1Hab\u00eda encontrado a Aquel a quien buscaba! Y con la ayuda de mi compa\u00f1ero espiritual, me impuse la peque\u00f1a regla de recibir a Jes\u00fas en la Eucarist\u00eda lo m\u00e1s a menudo posible.<br>A los 20 a\u00f1os, una nueva crisis grave me golpe\u00f3. Estaba convencido de que ir\u00eda al infierno, de que me condenar\u00eda eternamente. Lo que m\u00e1s me dol\u00eda, adem\u00e1s por supuesto de la privaci\u00f3n de la visi\u00f3n de Jes\u00fas, era verme privado de la visi\u00f3n de Mar\u00eda. Este pensamiento me torturaba: \u00a1ya casi no com\u00eda, ya no dorm\u00eda, me hab\u00eda vuelto todo amarillo! Mi oraci\u00f3n era \u00e9sta: \u201c\u00a1Se\u00f1or, lo s\u00e9, ir\u00e9 al infierno, pero dame al menos esta gracia para que cuando est\u00e9 en el infierno, pueda seguir am\u00e1ndote!\u201d Despu\u00e9s de seis semanas de angustia fui a la iglesia ante el altar de Nuestra Se\u00f1ora y le rec\u00e9 una oraci\u00f3n que comienza as\u00ed: \u201cRecuerda, oh Virgen Mar\u00eda, que nunca se ha o\u00eddo decir que alguien, recurriendo a tu patrocinio, implorando tu ayuda y protecci\u00f3n, haya sido abandonado por ti\u201d. Despu\u00e9s de aquello mi enfermedad cay\u00f3 al suelo \u201ccomo las escamas de la lepra\u201d. Estaba curado.<br><br>Despu\u00e9s de Par\u00eds, mi padre me envi\u00f3 a Padua para estudiar derecho. Mientras tanto, yo segu\u00eda sufriendo mi dilema vocacional: sent\u00eda que la llamada ven\u00eda de Dios y, al mismo tiempo, deb\u00eda obediencia a mi pap\u00e1, seg\u00fan las costumbres muy arraigadas en mi \u00e9poca. Estaba perplejo. Ped\u00ed consejo a mis compa\u00f1eros, especialmente al padre Antonio Possevino. Con su ayuda y discernimiento, eleg\u00ed algunas reglas y ejercicios para la vida espiritual y tambi\u00e9n para la vida en sociedad con los compa\u00f1eros y toda clase de personas. Al final de mis estudios hice una peregrinaci\u00f3n a Loreto. Permanec\u00ed como en \u00e9xtasis -dicen mis compa\u00f1eras- durante media hora en la Santa Casa de Mar\u00eda de Nazaret. Volv\u00ed a confiar mi vocaci\u00f3n y mi futuro a la Madre de Jes\u00fas. Nunca me he arrepentido de haber confiado totalmente en Ella.<br>De vuelta a casa, a la edad de 24 a\u00f1os, conoc\u00ed a una hermosa chica llamada Francesca. Ella me gustaba, pero me gustaba m\u00e1s mi proyecto de vida. \u00bfQu\u00e9 hacer? No les contar\u00e9 aqu\u00ed todos los detalles de mi batalla. S\u00f3lo s\u00e9 que al final me atrev\u00ed a pedirle a mi pap\u00e1 que me diera permiso para seguir mi sue\u00f1o. Finalmente acept\u00f3 mi elecci\u00f3n, pero llor\u00f3.<br><br>A partir de ese momento, mi vida cambi\u00f3 por completo. Antes, mi familia y mis compa\u00f1eros me ve\u00edan concentrado en m\u00ed mismo, preocupado, un poco cerrado. De un momento a otro, todo se puso en marcha. Me hab\u00eda convertido en otro hombre. Me orden\u00e9 sacerdote a los 26 a\u00f1os e inmediatamente me lanc\u00e9 a mi misi\u00f3n. Ya no ten\u00eda dudas: Dios me quer\u00eda en este camino. Me sent\u00eda feliz.<br>Mi vocaci\u00f3n, pensar\u00e1n, era una vocaci\u00f3n especial, aunque les dir\u00e9 que tambi\u00e9n fui nombrado obispo de Ginebra-Annecy a la edad de 35 a\u00f1os. En mi ministerio pastoral y de acompa\u00f1amiento, siempre estuve convencido y me ense\u00f1aron que toda persona tiene una vocaci\u00f3n. De hecho, no se deber\u00eda decir: todo el mundo tiene vocaci\u00f3n, sino que se deber\u00eda decir: todo el mundo es una vocaci\u00f3n, es decir, una persona que ha recibido una tarea \u201cprovidencial\u201d en este mundo, en previsi\u00f3n del mundo futuro que se nos ha prometido.<\/p>\n\n\n\n<p><br><br><em>Oficina de Animaci\u00f3n Vocacional<\/em><\/p>\n\n\n\n<p><em><a href=\"..\/es\/pastoral-juvenil-es\/has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-3-10\">(continuaci\u00f3n)<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(continuaci\u00f3n del art\u00edculo anterior) 2. Qu\u00e9 hacer ma\u00f1anaQueridos j\u00f3venes,seguro que se preguntar\u00e1n: \u00bfqu\u00e9 haremos m\u00e1s&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18360,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":78,"footnotes":""},"categories":[548],"tags":[2566,2636,2558,1768,1822,2190,1816,2620,2637],"class_list":["post-18367","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pastoral-juvenil-es","tag-caridad","tag-consejos","tag-dios","tag-don-bosco","tag-gracia","tag-jesus","tag-jovenes","tag-testigos","tag-vocaciones"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/18367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/comments?post=18367"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/18367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media\/18360"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media?parent=18367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/categories?post=18367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/tags?post=18367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}