{"id":18086,"date":"2023-07-27T09:39:37","date_gmt":"2023-07-27T09:39:37","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=18086"},"modified":"2024-05-02T10:34:43","modified_gmt":"2024-05-02T10:34:43","slug":"has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-1-10","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/es\/pastoral-juvenil-es\/has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-1-10\/","title":{"rendered":"\u00bfHas pensado en tu vocaci\u00f3n? San Francisco de Sales podr\u00eda ayudarte (1\/10)"},"content":{"rendered":"\n<p><em>\u201cNo es por la grandeza de nuestras acciones por lo que agradaremos a Dios, sino por el amor con que las hacemos\u201d, San Francisco de Sales.<br>Un itinerario en diez episodios en el que San Francisco de Sales podr\u00eda acompa\u00f1ar tambi\u00e9n a los j\u00f3venes de hoy que se plantean preguntas sobre el sentido de su vida<\/em>.<br><br><br><strong>1. Si parti\u00e9ramos del ABC de la vida cristiana<br><\/strong><br>Queridos j\u00f3venes,<br>S\u00e9 que escribo a aquellos que ya llevan en su coraz\u00f3n un peque\u00f1o deseo de bien, una b\u00fasqueda de luz. Ya han caminado en amistad con el Se\u00f1or, pero perm\u00edtanme que les resuma aqu\u00ed el ABC de la vida del creyente, es decir, una vida interior y espiritual rica y profunda. Con esta base estar\u00e1n equipados para tomar decisiones fruct\u00edferas en su existencia. Este trabajo no es nuevo para m\u00ed: cuando era obispo, visitaba todas las parroquias de mi di\u00f3cesis, y muchas estaban situadas en las monta\u00f1as. Para llegar a ellas no hab\u00eda carreteras y ten\u00eda que recorrer largas distancias a pie, incluso en invierno, pero me alegraba de encontrarme con esas gentes sencillas, de animarlas a vivir como Dios quiere.<br>Para caminar con fruto, es decisiva la labor del gu\u00eda espiritual que se da cuenta de lo que pasa en el coraz\u00f3n, los anima, los sigue, les hace propuestas claras, graduales y estimulantes. Escrib\u00eda en la Filotea: \u201c\u00bfQuieres emprender con confianza los caminos del Esp\u00edritu? Encuentra a alguien capaz, que sea tu gu\u00eda y te acompa\u00f1e; es la recomendaci\u00f3n de las recomendaciones\u201d. Hace cuatro siglos, como hoy: \u00e9ste es el punto crucial, decisivo.<br>La meta a alcanzar es la santidad, que consiste en una vida cristiana consciente, es decir, una profunda amistad con Dios, una vida espiritual ferviente, marcada por el amor a Dios y al pr\u00f3jimo. Es un camino sencillo, sabiendo que las grandes oportunidades de servir a Dios rara vez se presentan, mientras que las peque\u00f1as siempre las tenemos. Esto nos estimula a una caridad pronta, activa y diligente.<br>Si, al pensar en tal meta, son tentado por el des\u00e1nimo, le repito lo que escrib\u00ed hace siglos: \u201cNo debemos esperar que todo el mundo empiece con perfecci\u00f3n: poco importa c\u00f3mo empecemos. S\u00f3lo hay que estar decidido a continuar y terminar bien\u201d.<br>Para empezar con buen pie, los invito a la purificaci\u00f3n del coraz\u00f3n mediante la confesi\u00f3n. El pecado es una falta de amor, un robo a tu humanidad, un estar a oscuras y en fr\u00edo: en la confesi\u00f3n entregas a Jes\u00fas todo lo que puede agobiarte y oscurecer tu camino. Es volver a tener la alegr\u00eda del coraz\u00f3n.<br>Siguiendo adelante, las herramientas para caminar son tan antiguas y preciosas como la Iglesia, y han sostenido a generaciones de cristianos de todas las edades, \u00a1durante 20 siglos! Tambi\u00e9n ustedes ciertamente lo han experimentado.<br>La oraci\u00f3n, es decir, el di\u00e1logo con un Padre enamorado de ti y de tu vida. No olvides que a rezar se aprende rezando: por tanto, tengan fidelidad y perseverancia.<br><br>La Palabra de Dios, es decir, la \u201ccarta de Dios\u201d dirigida precisamente a ti en forma particular. Es como una especie de br\u00fajula que orienta tu caminar, \u00a1sobre todo cuando hay niebla, oscuridad y se corre el riesgo de perder la orientaci\u00f3n! No olvides que al leerla tienes el Tesoro en tus manos.<br>El sacramento de la Eucarist\u00eda es el term\u00f3metro de tu vida creyente: si tu coraz\u00f3n no ha madurado un vivo deseo de recibir el Pan de Vida, tu encuentro con \u00c9l tendr\u00e1 resultados modestos. Escrib\u00eda a mis contempor\u00e1neos: \u201cSi el mundo les pregunta por qu\u00e9 comulgan tan a menudo, respondan que es para aprender a amar a Dios, para purificarnos de las imperfecciones, para liberaros de las miserias, para encontrar fuerza en las debilidades y consuelo en las aflicciones. Dos clases de personas deben comunicarse con frecuencia: los perfectos, porque estando bien dispuestos har\u00edan mal en no acercarse a la fuente y manantial de la perfecci\u00f3n; y los imperfectos para esforzarse por alcanzar la perfecci\u00f3n. Los fuertes para no debilitarse y los d\u00e9biles para fortalecerse. Los enfermos para curarse y los sanos para no enfermar\u201d. Asiste a la Santa Misa con gran frecuencia: \u00a1tanto como sea posible!<br>Luego insisto en las virtudes, porque si el encuentro con Dios es verdadero y profundo, cambia tambi\u00e9n las relaciones con las personas, el trabajo, las cosas. Ellas permiten tener un car\u00e1cter humanamente rico, capaz de amistades verdaderas y profundas, de comprometerse alegremente a hacer bien su deber (trabajo-estudio), paciente y cordial en el trato, bueno.<br>Todo esto no sucede en tu coraz\u00f3n solitario, para mejorar y complacerse. La vida con los dem\u00e1s es un est\u00edmulo para caminar mejor (\u00a1cu\u00e1ntos son mejores que nosotros!), para ayudar m\u00e1s (\u00a1cu\u00e1ntos nos necesitan!), para ser ayudados (\u00a1cu\u00e1nto tenemos que aprender!), para recordarnos a nosotros mismos que no somos autosuficientes (\u00a1no somos auto-creados y auto-educados!). Sin una dimensi\u00f3n comunitaria, pronto nos perdemos a nosotros mismos.<br>Espero que ya hayas saboreado los frutos de una gu\u00eda estable, de confesiones bien hechas, de una oraci\u00f3n fiel y firme, de la riqueza de la Palabra, de la Eucarist\u00eda vivida con fecundidad, de las virtudes practicadas en la alegr\u00eda de la vida cotidiana, de amistades enriquecedoras, de lo indispensable del servicio. En este humus se florece: s\u00f3lo en este ecosistema se puede percibir el verdadero rostro del Dios cristiano, a cuya mano es hermoso y da alegr\u00eda confiar la propia vida.<\/p>\n\n\n\n<p><br><br><em>Oficina de Animaci\u00f3n Vocacional<\/em><\/p>\n\n\n\n<p><em><a href=\"..\/es\/pastoral-juvenil-es\/has-pensado-en-tu-vocacion-san-francisco-de-sales-podria-ayudarte-2-10\">(continuaci\u00f3n)<\/a><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNo es por la grandeza de nuestras acciones por lo que agradaremos a Dios, sino&#8230;<\/p>\n","protected":false},"author":1,"featured_media":18080,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":24,"footnotes":""},"categories":[548],"tags":[2566,2636,2558,1768,1822,2190,1816,2620,2637],"class_list":["post-18086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pastoral-juvenil-es","tag-caridad","tag-consejos","tag-dios","tag-don-bosco","tag-gracia","tag-jesus","tag-jovenes","tag-testigos","tag-vocaciones"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/18086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/comments?post=18086"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/18086\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media\/18080"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media?parent=18086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/categories?post=18086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/tags?post=18086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}