{"id":17859,"date":"2023-07-11T06:54:45","date_gmt":"2023-07-11T06:54:45","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=17859"},"modified":"2026-03-26T07:52:52","modified_gmt":"2026-03-26T07:52:52","slug":"la-presencia-salesiana-en-el-caribe","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/es\/don-bosco-en-el-mundo\/la-presencia-salesiana-en-el-caribe\/","title":{"rendered":"La presencia Salesiana en el Caribe"},"content":{"rendered":"\n<p><em><em>Bajo el sol del Caribe, en pueblos llenos de vida y alegr\u00eda, Don Bosco sigue siendo una respuesta significativa para los j\u00f3venes de estas tierras.<br><\/em><\/em><br><br>Ya desde hace m\u00e1s de cien a\u00f1os la presencia salesiana ha encontrado un ambiente y un clima muy fecundo en algunos pa\u00edses del Caribe, hoy como ayer confirman su significatividad en la presencia de sus j\u00f3venes, en su pueblo alegre, cari\u00f1oso y sencillo, en su sensibilidad religiosa y en su capacidad de acogida: <strong>Cuba, Hait\u00ed, Rep\u00fablica Dominicana y Puerto Rico<\/strong> han ofrecido y siguen ofreciendo un escenario propicio para la misi\u00f3n salesiana y una tierra f\u00e9rtil para el carisma de Don Bosco.<br><br>Los salesianos que est\u00e1n organizados en dos inspector\u00edas, Antillas y Hait\u00ed, junto a otros muchos miembros de la familia salesiana hacen concreta hoy esta presencia. Ellos son fruto de la generosidad y pasi\u00f3n de grandes misioneros, con buena voluntad, grandes sue\u00f1os, confianza en la Providencia y compromiso por la educaci\u00f3n y evangelizaci\u00f3n de los j\u00f3venes; as\u00ed se consolido la presencia de Don Bosco. Tambi\u00e9n hubo acontecimientos hist\u00f3ricos naturales o sociales que motivaron la toma de decisiones hasta su actual conformaci\u00f3n.<br><br><strong>Un poco de historia<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Aunque la primera solicitud para que hubiera salesianos en el territorio antillano fue en 1896, el primer pa\u00eds que recibi\u00f3 la presencia salesiana fue Cuba, en el 1916; despu\u00e9s le sigui\u00f3 Rep\u00fablica Dominicana en 1933, luego Hait\u00ed en 1936 y por \u00faltimo Puerto Rico en 1947.<br><br>El 24 de junio de 1915, la srta. Dolores Betancourt, oriunda de Camag\u00fcey, hab\u00eda firmado en Tur\u00edn un acuerdo privado con don Pablo Albera referente a una fundaci\u00f3n en su ciudad de origen. Los primeros salesianos llegaron a Cuba el 4 de abril de 1917 para abrir una obra en Camag\u00fcey.<br><br>El padre Jos\u00e9 Calasanz (1872-1936) de origen en Azanuy, Espa\u00f1a, salesiano desde 1890 fue enviado como misionero a promover las fundaciones de Cuba, Per\u00fa y Bolivia. En 1917 entraron los primeros salesianos a Cuba, junto con el sacerdote don Esteban Capra y dos coadjutores (se\u00f1ores Ullivarri y Celaya). En 1917 les conf\u00edan a los salesianos el templo dedicado a Nuestra Se\u00f1ora de la Caridad en un predio rural de Camag\u00fcey, para desde ah\u00ed coordinar la primera escuela de artes y oficios.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized td-caption-align-center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-1_tn.jpg\" alt=\"\" class=\"wp-image-17799\" width=\"272\" height=\"362\" srcset=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-1_tn.jpg 600w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-1_tn-225x300.jpg 225w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-1_tn-150x200.jpg 150w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-1_tn-300x400.jpg 300w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-1_tn-315x420.jpg 315w\" sizes=\"auto, (max-width: 272px) 100vw, 272px\" \/><figcaption class=\"wp-element-caption\"><em>Hait\u00ed, Cap-Ha\u00eftien<\/em><\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<p>Las comunidades salesianas empezaron su crecimiento y consolidaci\u00f3n en Cuba, compartiendo pertenec\u00eda can\u00f3nica primero con la Inspector\u00eda salesiana \u201cTarraconense\u201d de Espa\u00f1a. A partir de 1924, pasa a la Inspector\u00eda de M\u00e9xico y tres a\u00f1os m\u00e1s tarde, debido a la persecuci\u00f3n religiosa vivida en M\u00e9xico, se traslad\u00f3\u0301 la sede de la Inspector\u00eda a La Habana, Cuba.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>El padre Pittini desempe\u00f1a las funciones de Provincial en la parte este de los Estados Unidos y all\u00ed recibe instrucciones del Superior General, don Pedro Ricaldone, de trasladarse a Santo Domingo, para examinar la posibilidad de que la congregaci\u00f3n pueda establecerse en Rep\u00fablica Dominicana.<br><br>El 16 de agosto de 1933, el padre Pittini llega al puerto de San Pedro de Macor\u00eds. En febrero de 1934, el Pittini asume como superior de los reci\u00e9n llegados salesianos Rep\u00fablica Dominicana; el supervisaba los trabajos de la escuela en construcci\u00f3n y se familiarizaba con los dominicanos. El 11 de octubre de 1935, el Papa P\u00edo XI, lo design\u00f3 arzobispo de Santo Domingo.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large is-resized td-caption-align-center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-1024x760.jpg\" alt=\"\" class=\"wp-image-17807\" width=\"346\" height=\"256\" srcset=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-1024x760.jpg 1024w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-300x223.jpg 300w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-768x570.jpg 768w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-150x111.jpg 150w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-485x360.jpg 485w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-696x517.jpg 696w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-1068x793.jpg 1068w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-566x420.jpg 566w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn-80x60.jpg 80w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-2_tn.jpg 1078w\" sizes=\"auto, (max-width: 346px) 100vw, 346px\" \/><figcaption class=\"wp-element-caption\">Hait\u00ed, P\u00e9tion-Ville<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>La llegada de los salesianos en Hait\u00ed se dio en 1936. El Rector Mayor deleg\u00f3 en don Pedro Gimbert, ex-inspector de Lyon, para que implantase el carisma salesiano en Hait\u00ed. Lleg\u00f3 el 27 de mayo de 1936, en compa\u00f1\u00eda de un coadjutor salesiano, el sr. Adriano Massa. Despu\u00e9s llegaron otros hermanos para completar la comunidad.<br><br>Desde su fundaci\u00f3n, Hait\u00ed form\u00f3 parte sucesivamente de la Inspector\u00eda Salesiana M\u00e9xico-Antillas con sede en La Habana; m\u00e1s tarde form\u00f3 parte de la Inspector\u00eda de las Antillas \u2013juntamente con Cuba, Rep\u00fablica Dominicana y Puerto Rico \u2013 con sede en Santo Domingo.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full is-resized td-caption-align-center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-3_tn.jpg\" alt=\"\" class=\"wp-image-17814\" width=\"324\" height=\"375\" srcset=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-3_tn.jpg 689w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-3_tn-258x300.jpg 258w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-3_tn-150x174.jpg 150w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-3_tn-300x348.jpg 300w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-3_tn-362x420.jpg 362w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><figcaption class=\"wp-element-caption\">Hait\u00ed, Gressier<\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>La fundaci\u00f3n en Puerto Rico se hizo realidad el 24 de abril de 1947 cuando lleg\u00f3 el padre Pedro M. Savani, ex-inspector de M\u00e9xico-Antillas, para asumir la Parroquia de San Juan Bosco en Santurce, en la Calle Lutz. Desde aqu\u00ed se comenz\u00f3 a atender un Oratorio en los terrenos actuales de Cantera, donde ya en 1949 se inici\u00f3 la construcci\u00f3n de la capilla que dar\u00eda posteriormente lugar a la imponente Iglesia-Santuario de Mar\u00eda Auxiliadora.<br><br>La erecci\u00f3n can\u00f3nica de la Inspector\u00eda de las Antillas se realiza el 15 de septiembre de 1953 durante el rectorado de don Renato Ziggiotti, bajo el patrocinio de San Juan Bosco, con sede en La V\u00edbora (La Habana, Cuba). Posteriormente fue trasladada a Compostela (La Habana Vieja). Despu\u00e9s de la Revoluci\u00f3n Cubana la sede inspectorial fue transferida a Santo Domingo, Rep\u00fablica Dominicana, al \u201cColegio Don Bosco\u201d, donde permaneci\u00f3\u0301 hasta 1993, cuando fue traslada a la sede actual ubicada en la calle 30 de marzo #52 en la ciudad de Santo Domingo.<br><br>A partir de enero de 1992, Hait\u00ed es una Visitadur\u00eda, con sede en Port-au-Prince.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p><strong><strong>Don Bosco en el Caribe, hoy<br><\/strong><\/strong>La Inspector\u00eda Salesiana de las Antillas est\u00e1 constituida por tres pa\u00edses en la regi\u00f3n del Caribe: Cuba, Rep\u00fablica Dominicana y Puerto Rico. Hait\u00ed forma una Visitadur\u00eda aparte. En total en los cuatro pa\u00edses hay 169 Salesianos de Don Bosco: 15 en Cuba, 74 en Hait\u00ed, 67 en Rep\u00fablica Dominicana y 13 en Puerto Rico.<br><br>Las obras que animan las dos inspector\u00edas en 32 comunidades son: 41 centros educativos (de esos al menos 20 son centros de capacitaci\u00f3n t\u00e9cnica), 33 oratorios, 23 obras sociales, 8 casas de retiros \u2013 encuentros, 1 centro de formaci\u00f3n medioambiental, 3 casas de formaci\u00f3n, 4 centros de comunicaci\u00f3n social \u2013 estudios de grabaci\u00f3n, 2 estaciones de radio y 18 parroquias con 80 capillas y 44 casas de misi\u00f3n.<br><br>La Familia Salesiana en el Caribe tiene una gran vitalidad y est\u00e1 compuesta por varios grupos: Salesianos de Don Bosco, Hijas de Mar\u00eda Auxiliadora, Salesianos Cooperadores, Asociaci\u00f3n de Devotos de Mar\u00eda Auxiliadora, Exalumnos (SDB-FMA), Hijas de los Sagrados Corazones, Voluntarias de Don Bosco, Damas Salesianas y Misioneras Parroquiales de Mar\u00eda Auxiliadora (esta \u00faltima, una Pia Uni\u00f3n, aprobado por el Arzobispo de Santo Domingo, Monse\u00f1or Octavio A. Beras, fundadas por el padre Andr\u00e9s Nemeth, sdb, el 16 de junio 1961; aunque no forme parte de la Familia Salesiana, por su proximidad, asiste a sus encuentros). Las relaciones son cordiales, se comparten algunos proyectos pastorales y se re\u00fanen con frecuencia.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>En medio de un clima social y pol\u00edtico muy particular, los cuatro pa\u00edses est\u00e1n sufriendo una migraci\u00f3n masiva de sus j\u00f3venes y de familias enteras, motivados por el hambre, la falta de alimentos, la falta de empleo, la violencia, la b\u00fasqueda de oportunidades mejor remuneradas. En estas circunstancias la presencia salesiana sigue muy comprometida en los procesos de educaci\u00f3n, formaci\u00f3n al trabajo, a la ciudadan\u00eda y la vida de fe, existe un serio compromiso en la defensa a los derechos de educaci\u00f3n, alimentaci\u00f3n y vida de digna de sus ni\u00f1os, adolescentes y j\u00f3venes, se acompa\u00f1a y anima desde los patios el juego y encuentro que permite hacer amigos. La m\u00fasica y la danza son expresiones naturales que descubren en los oratorios salesianos el est\u00edmulo y espacio para sus mejores expresiones. Sus patios son siempre lugares de encuentro y refugio incluso ante los eventos naturales que han sufrido.<br><br>Esta presencia hoy es prof\u00e9tica al compartir con la gente las realidades sociales que cada pa\u00eds est\u00e1 viviendo, decidiendo permanecer junto a los m\u00e1s necesitados, animando la fe de todos los d\u00edas, una amistad sencilla que habla de Dios, llena de esperanza y consuelo, con gestos fraternos de solidaridad y amor a los m\u00e1s vulnerables, en especial a sus ni\u00f1os y j\u00f3venes.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized td-caption-align-center\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-4_tn.jpg\" alt=\"\" class=\"wp-image-17822\" width=\"308\" height=\"410\" srcset=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-4_tn.jpg 600w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-4_tn-225x300.jpg 225w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-4_tn-150x200.jpg 150w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-4_tn-300x400.jpg 300w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/07\/La-presenza-salesiana-nel-Caraibi-4_tn-315x420.jpg 315w\" sizes=\"auto, (max-width: 308px) 100vw, 308px\" \/><figcaption class=\"wp-element-caption\">Santo Domingo, La Plaza<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n\n\n\n<p><em><em>don Hugo OROZCO S\u00c1NCHEZ, sdb<br>Consejero Regional para Interam\u00e9rica<\/em><\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bajo el sol del Caribe, en pueblos llenos de vida y alegr\u00eda, Don Bosco sigue&#8230;<\/p>\n","protected":false},"author":1,"featured_media":17797,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":146,"footnotes":""},"categories":[177],"tags":[1924,1966],"class_list":["post-17859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-don-bosco-en-el-mundo","tag-paises","tag-salvacion"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/17859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/comments?post=17859"}],"version-history":[{"count":1,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/17859\/revisions"}],"predecessor-version":[{"id":51623,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/17859\/revisions\/51623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media\/17797"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media?parent=17859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/categories?post=17859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/tags?post=17859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}