{"id":15092,"date":"2023-05-20T12:51:56","date_gmt":"2023-05-20T12:51:56","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=15092"},"modified":"2026-03-25T16:22:37","modified_gmt":"2026-03-25T16:22:37","slug":"los-benefactores-de-don-bosco","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/es\/don-bosco\/los-benefactores-de-don-bosco\/","title":{"rendered":"Los benefactores de Don Bosco"},"content":{"rendered":"\n<p><em><em>Hacer el bien a los j\u00f3venes requiere no s\u00f3lo dedicaci\u00f3n, sino tambi\u00e9n grandes recursos materiales y financieros. Don Bosco sol\u00eda decir \u201cConf\u00edo ilimitadamente en la Divina Providencia, pero tambi\u00e9n la Providencia quiere ser ayudada por nuestros inmensos esfuerzos\u201d; dicho y hecho.<br><\/em><\/em><br><br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; A sus misioneros que part\u00edan, el 11 de noviembre de 1875, Don Bosco les dio 20 preciosos \u201cRecuerdos\u201d. El primero era: \u201cBuscad almas, pero no dinero, ni honores, ni dignidad\u201d.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco mismo tuvo que ir en busca de dinero toda su vida, pero quer\u00eda que sus hijos no se afanaran en buscar dinero, que no se preocuparan cuando les faltara, que no perdieran la cabeza cuando lo encontraran, sino que estuvieran dispuestos a toda humillaci\u00f3n y sacrificio en la b\u00fasqueda de lo necesario, con plena confianza en la Divina Providencia que nunca les dejar\u00eda faltar. Y les dio el ejemplo.<br><br><strong>\u201c\u00a1El Santo de los millones!\u201d<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco manej\u00f3 en su vida grandes sumas de dinero, reunidas al precio de enormes sacrificios, humillantes b\u00fasquedas, laboriosas loter\u00edas, incesantes peregrinaciones. Con ese dinero dio pan, vestido, alojamiento y trabajo a muchos chicos pobres, compr\u00f3 casas, abri\u00f3 hospicios y colegios, construy\u00f3 iglesias, puso en marcha grandes iniciativas de imprenta y editoriales, lanz\u00f3 misiones salesianas en Am\u00e9rica y, finalmente, ya debilitado por los achaques de la vejez, erigi\u00f3 la Bas\u00edlica del Sagrado Coraz\u00f3n en Roma, obedeciendo al Papa.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; No todos comprendieron el esp\u00edritu que le animaba, no todos apreciaron sus m\u00faltiples actividades y la prensa anticlerical se permiti\u00f3 insinuaciones rid\u00edculas. El 4 de abril de 1872, el peri\u00f3dico sat\u00edrico turin\u00e9s \u201cIl Fischietto\u201d (\u201cEl silbato\u201d) dec\u00eda que Don Bosco ten\u00eda \u201cfabulosos fondos\u201d, mientras que, a su muerte, en el peri\u00f3dico \u201cIl Birichin\u201d (\u201cEl p\u00edcaro\u201d), Luigi Pietracqua public\u00f3 un soneto blasfemo en el que calificaba a Don Bosco de astuto \u201ccapaz de sacar sangre de un nabo\u201d y le defin\u00eda como \u201cel Santo de los millones\u201d porque habr\u00eda contado millones a pu\u00f1ados sin ganarlos con su propio sudor.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Quienes conocen el estilo de pobreza en el que vivi\u00f3 y muri\u00f3 el Santo pueden comprender f\u00e1cilmente lo injusta que era la s\u00e1tira de Pietracqua. Don Bosco fue, s\u00ed, un h\u00e1bil administrador del dinero que le proporcionaba la caridad de los buenos, pero nunca guard\u00f3 nada para s\u00ed. El mobiliario de su peque\u00f1a habitaci\u00f3n en Valdocco consist\u00eda en una cama de hierro, una mesita, una silla y, m\u00e1s tarde, un sof\u00e1, sin cortinas en las ventanas, ni alfombras, ni siquiera una peque\u00f1a alfombra. En su \u00faltima enfermedad, atormentado por la sed, cuando le proporcionaron agua mineral para aliviarle, no quer\u00eda beberla, creyendo que era una bebida cara. Fue necesario asegurarle que s\u00f3lo costaba siete c\u00e9ntimos la botella. Unos d\u00edas antes de morir, orden\u00f3 a don Viglietti que buscara en los bolsillos de su ropa y le diera a don Rua la cartera, para que pudiera morir sin un c\u00e9ntimo en el bolsillo.<br><br><strong>Nobleza filantr\u00f3pica<br><\/strong><em>Las Memorias Biogr\u00e1ficas y el Epistolario de Don Bosco<\/em> proporcionan una rica documentaci\u00f3n sobre sus benefactores. Encontramos all\u00ed los nombres de casi 300 familias nobles de las que es imposible dar aqu\u00ed una lista.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Ciertamente no debemos cometer el error de limitar los benefactores de Don Bosco \u00fanicamente a la nobleza. Obtuvo la ayuda y la colaboraci\u00f3n desinteresada de miles de personas de la clase eclesi\u00e1stica y civil, de la burgues\u00eda y del pueblo, empezando por esa incomparable benefactora que fue Mam\u00e1 Margarita.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Nos detenemos en una figura de la nobleza que se distingui\u00f3 por apoyar la obra de Don Bosco, destacando la actitud sencilla y delicada y, al mismo tiempo, valiente y apost\u00f3lica que supo mantener para recibir y hacer el bien.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; En 1866 Don Bosco dirigi\u00f3 una carta a la condesa Enrichetta Bosco di Ruffino, de soltera Riccardi, que llevaba a\u00f1os en contacto con el Oratorio de Valdocco. Era una de las Damas que se reun\u00edan semanalmente para reparar la ropa de los j\u00f3venes internos. He aqu\u00ed el texto:<br><br><em>\u201cBenemerita Se\u00f1ora Condesa,<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; No puedo ir a visitar a Vuestra Se\u00f1or\u00eda como desear\u00eda, pero voy con la persona de Jesucristo oculta bajo estos harapos que le recomiendo para que en su caridad los remiende. Es algo pobre en el tiempo; pero espero que para usted sea un tesoro para la eternidad.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Que Dios le bendiga a usted, a sus trabajos y a toda su familia, mientras tengo el honor de poder profesarme con toda estima<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; de V.S.B. Obbl.mo servidor\u00bb.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sac. Bosco Gio. Tur\u00edn, 16 de mayo de 1866<\/em><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large td-caption-align-center td-img-style-shadow\"><img loading=\"lazy\" decoding=\"async\" width=\"628\" height=\"1024\" src=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2-628x1024.jpg\" alt=\"\" class=\"wp-image-15079\" srcset=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2-628x1024.jpg 628w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2-184x300.jpg 184w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2-768x1252.jpg 768w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2-150x245.jpg 150w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2-300x489.jpg 300w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2-696x1134.jpg 696w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2-258x420.jpg 258w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/05\/I-benefattori-di-don-Bosco_1_tn2.jpg 800w\" sizes=\"auto, (max-width: 628px) 100vw, 628px\" \/><figcaption class=\"wp-element-caption\">Carta de Don Bosco a los benefactores<\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; En esta carta Don Bosco se disculpa por no haber podido ir en persona a visitar a la Condesa. A cambio le env\u00eda un fardo de ropa vieja de los chicos del Oratorio para &#8230;. remendar&#8230; \u00a1unas pobres cosas (en piamont\u00e9s: basura) ante los hombres, pero un tesoro precioso para los que visten a los desnudos por amor a Cristo!<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Hay quien ha querido ver en las relaciones de Don Bosco con los ricos un esp\u00edritu cortesano interesado. \u00a1Pero aqu\u00ed hay un aut\u00e9ntico esp\u00edritu evang\u00e9lico!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hacer el bien a los j\u00f3venes requiere no s\u00f3lo dedicaci\u00f3n, sino tambi\u00e9n grandes recursos materiales&#8230;<\/p>\n","protected":false},"author":11,"featured_media":15076,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":63,"footnotes":""},"categories":[187],"tags":[1708,2566,1756,2593,1936,1702,1966,2620],"class_list":["post-15092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-don-bosco","tag-benefactores","tag-caridad","tag-cooperadores-salesianos","tag-familia-salesiana","tag-pobres","tag-providencia","tag-salvacion","tag-testigos"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/15092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/comments?post=15092"}],"version-history":[{"count":1,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/15092\/revisions"}],"predecessor-version":[{"id":50894,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/posts\/15092\/revisions\/50894"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media\/15076"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/media?parent=15092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/categories?post=15092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/es\/wp-json\/wp\/v2\/tags?post=15092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}