{"id":45001,"date":"2025-08-23T07:21:49","date_gmt":"2025-08-23T07:21:49","guid":{"rendered":"https:\/\/www.donbosco.press\/?p=45001"},"modified":"2025-09-10T14:49:32","modified_gmt":"2025-09-10T14:49:32","slug":"don-jose-luis-carreno-salesianer-missionar","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/de\/ihr-andenken-ist-segen\/don-jose-luis-carreno-salesianer-missionar\/","title":{"rendered":"Don Jose-Luis Carreno, Salesianer-Missionar"},"content":{"rendered":"<p>Don Jos\u00e9 Luis Carre\u00f1o (1905-1986) wurde vom Historiker Joseph Thekkedath als \u201eder beliebteste Salesianer S\u00fcdindiens\u201c in der ersten H\u00e4lfte des 20. Jahrhunderts beschrieben. \u00dcberall, wo er lebte \u2013 sei es im britischen Indien, in der portugiesischen Kolonie Goa, auf den Philippinen oder in Spanien \u2013 finden sich Salesianer, die seine Erinnerung liebevoll bewahren. Seltsamerweise gibt es jedoch noch keine angemessene Biografie dieses gro\u00dfen Salesianers, abgesehen von dem umfangreichen Nachruf, den Don Jos\u00e9 Antonio Rico verfasste: \u201eJos\u00e9 Luis Carre\u00f1o Etxeand\u00eda, obrero de Dios\u201c. Wir hoffen, dass diese L\u00fccke bald geschlossen wird. Don Carre\u00f1o war einer der Architekten der S\u00fcdasien-Region, und wir k\u00f6nnen es uns nicht leisten, ihn zu vergessen.<\/p>\n<p>Jos\u00e9-Luis Carre\u00f1o Etxeand\u00eda wurde am 23. Oktober 1905 in Bilbao, Spanien, geboren. Nachdem er im zarten Alter von acht Jahren seine Mutter verloren hatte, wurde er im salesianischen Haus von Santander aufgenommen. 1917, im Alter von zw\u00f6lf Jahren, trat er in das Aspirantat von Campello ein. Er erinnerte sich, dass zu jener Zeit \u201enicht viel \u00fcber Don Bosco gesprochen wurde\u2026 Aber f\u00fcr uns war ein Don Binelli ein Don Bosco, ganz zu schweigen von Don Rinaldi, damals Generalpr\u00e4fekt, dessen Besuche uns ein \u00fcbernat\u00fcrliches Gef\u00fchl hinterlie\u00dfen, wie wenn die Boten Jahwes das Zelt Abrahams besuchten\u201c.<br \/>\nNach dem Noviziat und Postnoviziat absolvierte er sein Praktikum als Assistent der Novizen. Er muss ein brillanter Kleriker gewesen sein, denn Don Pedro Escursell schrieb \u00fcber ihn an den Generaloberen: \u201eIch spreche gerade jetzt mit einem der vorbildlichen Kleriker dieses Hauses. Er ist ein Assistent in der Ausbildung des Personals dieser Provinz; er sagt mir, dass er seit langem bittet, in die Missionen geschickt zu werden, und dass er aufgeh\u00f6rt hat, darum zu bitten, weil er keine Antwort erh\u00e4lt. Er ist ein junger Mann von gro\u00dfem intellektuellem und moralischem Wert\u201c.<br \/>\nAm Vorabend seiner Priesterweihe im Jahr 1932 schrieb der junge Jos\u00e9-Luis direkt an den Generaloberen und bot sich f\u00fcr die Missionen an. Das Angebot wurde angenommen, und er wurde nach Indien geschickt, wo er 1933 in Mumbai landete. Nur ein Jahr sp\u00e4ter, als die Provinz S\u00fcdindien errichtet wurde, wurde er zum Novizenmeister in Tirupattur ernannt: Er war gerade 28 Jahre alt. Mit seinen au\u00dfergew\u00f6hnlichen Qualit\u00e4ten des Geistes und des Herzens wurde er schnell zur Seele des Hauses und hinterlie\u00df einen tiefen Eindruck bei seinen Novizen. \u201eEr gewann uns mit seinem v\u00e4terlichen Herzen\u201c, schreibt einer von ihnen, Erzbischof Hubert D\u2019Rosario von Shillong.<br \/>\nDon Joseph Vaz, ein weiterer Novize, erz\u00e4hlte oft, wie Carre\u00f1o bemerkte, dass er w\u00e4hrend einer Konferenz vor K\u00e4lte zitterte. \u201eWarte einen Moment, hombre\u201c, sagte der Novizenmeister und ging hinaus. Kurz darauf kam er mit einem blauen Pullover zur\u00fcck, den er Joe \u00fcbergab. Joe bemerkte, dass der Pullover seltsam warm war. Dann erinnerte er sich, dass sein Meister unter der Soutane etwas Blaues trug\u2026 das jetzt fehlte. Carre\u00f1o hatte ihm seinen eigenen Pullover gegeben.<br \/>\n1942, als die britische Regierung in Indien alle Ausl\u00e4nder aus L\u00e4ndern, die mit Gro\u00dfbritannien im Krieg standen, internierte, wurde Carre\u00f1o als B\u00fcrger eines neutralen Landes nicht bel\u00e4stigt. 1943 erhielt er eine Nachricht \u00fcber Radio Vatikan: Er sollte den Platz von Don Eligio Cinato, dem Pronvizial der Provinz S\u00fcdindien, der ebenfalls interniert war, einnehmen. Zur gleichen Zeit lud der salesianische Erzbischof Louis Mathias von Madras-Mylapore ihn ein, sein Generalvikar zu sein.<br \/>\n1945 wurde er offiziell zum Provinzial ernannt \u2013 ein Amt, das er von 1945 bis 1951 innehatte. Einer seiner allerersten Akte war die Weihe der Provinz an das Heilige Herz Jesu. Viele Salesianer waren davon \u00fcberzeugt, dass das au\u00dfergew\u00f6hnliche Wachstum der S\u00fcdprovinz auf diese Geste zur\u00fcckzuf\u00fchren war. Unter der Leitung von Don Carre\u00f1o verdoppelten sich die salesianischen Werke. Eine seiner weitsichtigsten Handlungen war die Gr\u00fcndung eines Universit\u00e4tskollegs im abgelegenen und armen Dorf Tirupattur. Das Sacred Heart College sollte schlie\u00dflich den gesamten Distrikt verwandeln.<br \/>\nCarre\u00f1o war auch der Hauptarchitekt der \u201eIndisierung\u201c des salesianischen Gesichts in Indien, indem er von Anfang an nach lokalen Berufungen suchte, anstatt sich ausschlie\u00dflich auf ausl\u00e4ndische Missionare zu verlassen. Eine Wahl, die sich als providentiell erwies: Zun\u00e4chst, weil der Strom ausl\u00e4ndischer Missionare w\u00e4hrend des Krieges versiegte; dann, weil das unabh\u00e4ngige Indien beschloss, keine Visa mehr f\u00fcr neue ausl\u00e4ndische Missionare zu erteilen. \u201eWenn es heute mehr als zweitausend Salesianer in Indien gibt, ist das Verdienst dieses Wachstums den von Don Carre\u00f1o eingeleiteten Politiken zuzuschreiben\u201c, schreibt Don Thekkedath in seiner Geschichte der Salesianer in Indien.<br \/>\nDon Carre\u00f1o, wie gesagt, war nicht nur Provinzial, sondern auch Vikar von Msgr. Mathias. Diese beiden gro\u00dfen M\u00e4nner, die sich zutiefst sch\u00e4tzten, waren jedoch sehr unterschiedlich im Temperament. Der Erzbischof bef\u00fcrwortete strenge disziplinarische Ma\u00dfnahmen gegen\u00fcber Mitbr\u00fcdern in Schwierigkeiten, w\u00e4hrend Don Carre\u00f1o mildere Verfahren bevorzugte. Der au\u00dferordentliche Visitator, Don Albino Fedrigotti, schien dem Erzbischof recht zu geben, indem er Don Carre\u00f1o als \u201eeinen hervorragenden Ordensmann, einen Mann mit einem gro\u00dfen Herzen\u201c beschrieb, aber auch als \u201eein bisschen zu sehr Dichter\u201c.<br \/>\nEs gab auch den Vorwurf, er sei ein schlechter Verwalter, aber es ist bezeichnend, dass eine Figur wie Don Aurelio Maschio, gro\u00dfer Prokurator und Architekt der salesianischen Werke in Mumbai, diesen Vorwurf entschieden zur\u00fcckwies. In Wirklichkeit war Don Carre\u00f1o ein Innovator und Vision\u00e4r. Einige seiner Ideen \u2013 wie die Einbeziehung nicht-salesianischer Freiwilliger f\u00fcr einen Dienst von einigen Jahren \u2013 wurden damals mit Misstrauen betrachtet, sind heute aber weitgehend akzeptiert und werden aktiv gef\u00f6rdert.<br \/>\n1951, am Ende seiner offiziellen Amtszeit als Provinzial, wurde Carre\u00f1o gebeten, nach Spanien zur\u00fcckzukehren, um sich um die Salesianischen Mitarbeiter zu k\u00fcmmern. Dies war nicht der wahre Grund f\u00fcr seine Abreise nach achtzehn Jahren in Indien, aber Carre\u00f1o nahm es gelassen an, wenn auch nicht ohne Schmerz.<br \/>\n1952 wurde er stattdessen gebeten, nach Goa zu gehen, wo er bis 1960 blieb. \u201eGoa war Liebe auf den ersten Blick\u201c, schrieb er in Urdimbre en el telar. Goa seinerseits nahm ihn ins Herz. Er setzte die Tradition der Salesianer fort, die als geistliche Leiter und Beichtv\u00e4ter des Di\u00f6zesanklerus dienten, und war sogar Patron der Vereinigung der Schriftsteller in Konkani. Vor allem aber regierte er die Gemeinschaft von Don Bosco Panjim mit Liebe, k\u00fcmmerte sich mit au\u00dfergew\u00f6hnlicher Vaterschaft um die vielen armen Jungen und widmete sich erneut aktiv der Suche nach Berufungen zum salesianischen Leben. Die ersten Salesianer von Goa \u2013 Menschen wie Thomas Fernandes, Elias Diaz und Romulo Noronha \u2013 erz\u00e4hlten mit Tr\u00e4nen in den Augen, wie Carre\u00f1o und andere vom Goa Medical College, gleich neben dem salesianischen Haus, kamen, um Blut zu spenden und so ein paar Rupien zu bekommen, um Lebensmittel und andere G\u00fcter f\u00fcr die Jungen zu kaufen.<br \/>\n1961 fanden die indische Milit\u00e4raktion und die Annexion von Goa statt. Zu diesem Zeitpunkt war Don Carre\u00f1o in Spanien und konnte nicht in das geliebte Land zur\u00fcckkehren. 1962 wurde er als Novizenmeister auf die Philippinen geschickt. Er begleitete nur drei Gruppen von Novizen, weil er 1965 um die R\u00fcckkehr nach Spanien bat. Der Grund f\u00fcr seine Entscheidung war eine ernsthafte Meinungsverschiedenheit zwischen ihm und den salesianischen Missionaren aus China, insbesondere mit Don Carlo Braga, dem Oberen der Visitatorie. Carre\u00f1o lehnte die Politik, junge philippinische Salesianer kurz nach ihrer Profess nach Hongkong zum Philosophiestudium zu schicken, entschieden ab. Wie es geschah, akzeptierten die Oberen schlie\u00dflich den Vorschlag, die jungen Salesianer auf den Philippinen zu behalten, aber zu diesem Zeitpunkt war Carre\u00f1os Bitte um R\u00fcckkehr bereits bewilligt worden.<\/p>\n<p>Don Carre\u00f1o verbrachte nur vier Jahre auf den Philippinen, aber auch hier hinterlie\u00df er, wie in Indien, einen unausl\u00f6schlichen Eindruck, \u201eeinen unermesslichen und entscheidenden Beitrag zur salesianischen Pr\u00e4senz auf den Philippinen\u201c, so die Worte des salesianischen Historikers Nestor Impelido.<br \/>\nNach seiner R\u00fcckkehr nach Spanien arbeitete er mit den Missionsprokuren von Madrid und New Rochelle zusammen und animierte die iberischen Provinzen. Viele in Spanien erinnern sich noch an den alten Missionar, der die salesianischen H\u00e4user besuchte und die Jugendlichen mit seinem missionarischen Enthusiasmus, seinen Liedern und seiner Musik ansteckte.<br \/>\nAber in seiner sch\u00f6pferischen Fantasie nahm ein neues Projekt Gestalt an. Carre\u00f1o widmete sich von ganzem Herzen dem Traum, ein Pueblo Misionero mit zwei Zielen zu gr\u00fcnden: junge Missionare \u2013 meist aus Osteuropa \u2013 f\u00fcr Lateinamerika vorzubereiten; einen Zufluchtsort f\u00fcr \u201epensionierte\u201c Missionare wie ihn anzubieten, die auch als Ausbilder dienen k\u00f6nnten. Nach einem langen und schmerzhaften Briefwechsel mit den Oberen nahm das Projekt schlie\u00dflich im Hogar del Misionero in Alzuza, wenige Kilometer von Pamplona entfernt, Gestalt an. Die missionarische Berufungskomponente kam nie richtig in Gang, und nur sehr wenige \u00e4ltere Missionare schlossen sich Carre\u00f1o tats\u00e4chlich an. Sein Hauptapostolat in diesen letzten Jahren blieb das der Feder. Er hinterlie\u00df mehr als drei\u00dfig B\u00fccher, darunter f\u00fcnf, die dem Heiligen Grabtuch gewidmet waren, dem er besonders ergeben war.<br \/>\nDon Jos\u00e9-Luis Carre\u00f1o starb 1986 in Pamplona im Alter von 81 Jahren. Trotz der H\u00f6hen und Tiefen seines Lebens konnte dieser gro\u00dfe Liebhaber des Heiligen Herzens Jesu im goldenen Jubil\u00e4um seiner Priesterweihe sagen: \u201eWenn vor f\u00fcnfzig Jahren mein Motto als junger Priester \u201aChristus ist alles\u2018 war, w\u00fcrde ich es heute, alt und \u00fcberw\u00e4ltigt von seiner Liebe, in goldenen Buchstaben schreiben, denn in Wirklichkeit IST CHRISTUS ALLES\u201c.<\/p>\n<p>Don Ivo COELHO, sdb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Don Jos\u00e9 Luis Carre\u00f1o (1905-1986) wurde vom Historiker Joseph Thekkedath als \u201eder beliebteste Salesianer S\u00fcdindiens\u201c&#8230;<\/p>\n","protected":false},"author":1,"featured_media":44995,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":3,"footnotes":""},"categories":[139],"tags":[1819,1957,2504,2023,1705,2564,2617],"class_list":["post-45001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ihr-andenken-ist-segen","tag-gnade","tag-salesianer","tag-charyzmat-salezjanski","tag-tugend","tag-wohltaeter","tag-wohltaetigkeit","tag-zeugen"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/45001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/comments?post=45001"}],"version-history":[{"count":1,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/45001\/revisions"}],"predecessor-version":[{"id":45002,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/45001\/revisions\/45002"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media\/44995"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media?parent=45001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/categories?post=45001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/tags?post=45001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}