{"id":36062,"date":"2025-04-27T08:31:19","date_gmt":"2025-04-27T08:31:19","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=36062"},"modified":"2025-04-27T08:57:03","modified_gmt":"2025-04-27T08:57:03","slug":"don-bosco-als-verfechter-der-goettlichen-barmherzigkeit","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/de\/don-bosco\/don-bosco-als-verfechter-der-goettlichen-barmherzigkeit\/","title":{"rendered":"Don Bosco als Verfechter der \u201eg\u00f6ttlichen Barmherzigkeit\u201c"},"content":{"rendered":"\n<p><em><em>Als sehr junger Priester ver\u00f6ffentlichte Don Bosco ein B\u00e4ndchen im Kleinformat mit dem Titel \u201e\u00dcbung der Verehrung der Barmherzigkeit Gottes\u201c.<br><\/em><\/em><br><br><strong>Es begann alles mit der Marquise di Barolo<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Die Marquise Juliette Colbert di Barolo (1785-1864), die am 12. Mai 2015 von Papst Franziskus zum Ehrw\u00fcrdigen erkl\u00e4rt wurde, pflegte pers\u00f6nlich eine besondere Verehrung der g\u00f6ttlichen Barmherzigkeit. So lie\u00df sie in den von ihr gegr\u00fcndeten Ordens- und Bildungsgemeinschaften in der N\u00e4he von Valdocco den Brauch einer Woche mit Meditationen und Gebeten zu diesem Thema einf\u00fchren. Aber sie war nicht zufrieden. Sie wollte, dass sich diese Praxis auch anderswo, vor allem in den Pfarreien, unter dem Volk verbreitete. Sie suchte die Zustimmung des Heiligen Stuhls, der sie nicht nur erteilte, sondern auch verschiedene Abl\u00e4sse f\u00fcr diese Andachtspraxis gew\u00e4hrte. Nun ging es darum, eine geeignete Publikation f\u00fcr diesen Zweck zu erstellen.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Wir befinden uns jetzt im Sommer 1846, als Don Bosco, nachdem er die schwere Ersch\u00f6pfungskrise, die ihn an den Rand des Grabes gebracht hatte, \u00fcberwunden hatte, sich zur Genesung zu Mama Margareta in Becchi zur\u00fcckgezogen hatte und zum gro\u00dfen Missfallen der Marquise selbst von seinem sehr gesch\u00e4tzten Dienst als Kaplan in einem der Werke von Barolo \u201ezur\u00fcckgetreten\u201c war. Aber \u201eseine jungen Leute\u201c riefen ihn in das neu gemietete Haus Pinardi.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; An diesem Punkt schaltete sich der ber\u00fchmte Patriot Silvio Pellico ein, der Sekret\u00e4r und Bibliothekar der Marquise und ein Bewunderer und Freund Don Boscos, der einige seiner Gedichte vertont hatte. In den Memoiren der Salesianer hei\u00dft es, dass Pellico der Marquise mit einer gewissen Dreistigkeit vorschlug, Don Bosco mit der Ver\u00f6ffentlichung zu beauftragen, an der sie interessiert war. Was hat die Marquise getan? Sie akzeptierte, wenn auch nicht allzu begeistert. Wer wei\u00df? Vielleicht wollte sie ihn erst einmal auf die Probe stellen. Und Don Bosco akzeptierte ebenfalls.<br><br><strong>Ein Thema, das ihm am Herzen lag<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Das Thema der Barmherzigkeit Gottes geh\u00f6rte zu seinen geistlichen Interessen, zu denen er im Seminar in Chieri und vor allem im Turiner Internat ausgebildet worden war. Erst zwei Jahre zuvor hatte er den Unterricht seines Landsmannes, des heiligen Giuseppe Cafasso, beendet, der nur vier Jahre \u00e4lter war als er, aber sein geistlicher Leiter, dessen Predigten er bei den Exerzitien f\u00fcr Priester verfolgte, aber auch der Ausbilder von einem halben Dutzend anderer Gr\u00fcnder, einige sogar Heilige. Obwohl Cafasso ein Kind der religi\u00f6sen Kultur seiner Zeit war \u2013 die aus Vorschriften und der Logik bestand, \u201eGutes zu tun, um der g\u00f6ttlichen Strafe zu entgehen und das Paradies zu verdienen\u201c \u2013, lie\u00df er keine Gelegenheit aus, sowohl in seiner Lehre als auch in seinen Predigten von der Barmherzigkeit Gottes zu sprechen. Und wie k\u00f6nnte er das nicht tun, wenn er sich st\u00e4ndig dem Bu\u00dfsakrament widmete und den zum Tode Verurteilten beistand? Dies umso mehr, als diese nachsichtige Hingabe zu jener Zeit eine pastorale Reaktion auf die Strenge des Jansenismus darstellte, der die Pr\u00e4destination der Geretteten bef\u00fcrwortete.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; So machte sich Don Bosco, sobald er Anfang November vom Land zur\u00fcckkehrte, an die Arbeit und folgte den von Rom genehmigten und im ganzen Piemont verbreiteten frommen Praktiken. Mit Hilfe einiger Texte, die er in der Bibliothek des Internats, das er gut kannte, leicht finden konnte, ver\u00f6ffentlichte er am Ende des Jahres auf eigene Kosten ein kleines B\u00fcchlein von 111 Seiten im Kleinformat mit dem Titel \u201e<a href=\"https:\/\/www.donboscosanto.eu\/oe\/esercizio_di_divozione_alla_misericordia_di_dio.php\" target=\"_blank\" rel=\"noreferrer noopener\"><em>\u00dcbung der Verehrung der Barmherzigkeit Gottes<\/em><\/a>\u201c. Er verteilte es sofort an die M\u00e4dchen, Frauen und Nonnen der Stiftungen von Barolo. Es ist nicht dokumentiert, aber die Logik und die Dankbarkeit lassen vermuten, dass er es auch der Marquise Barolo, der Initiatorin des Projekts, geschenkt hat. Allerdings lassen die gleiche Logik und Dankbarkeit vermuten, dass die Marquise sich in ihrer Gro\u00dfz\u00fcgigkeit nicht hat \u00fcbertreffen lassen und ihm, vielleicht anonym wie bei anderen Gelegenheiten, einen eigenen Beitrag zu den Ausgaben geschickt hat.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Es ist hier nicht der Platz, den \u201eklassischen\u201c Inhalt von Don Boscos Meditations- und Gebetsb\u00fcchlein vorzustellen; wir m\u00f6chten nur darauf hinweisen, dass sein Grundprinzip lautet: \u201eJeder muss Gottes Barmherzigkeit f\u00fcr sich selbst und f\u00fcr alle Menschen erflehen, denn \u201ewir sind alle S\u00fcnder\u201c [&#8230;] alle bed\u00fcrfen der Vergebung und der Gnade [&#8230;] alle sind zur ewigen Erl\u00f6sung berufen\u201c.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Bezeichnend ist also die Tatsache, dass Don Bosco am Ende jedes Wochentages in der Logik des Titels \u201e\u00dcbungen der Verehrung\u201c (Andachts\u00fcbungen) eine Praxis der Fr\u00f6mmigkeit vorgibt: andere einladen, einzugreifen, denen vergeben, die uns beleidigt haben, eine sofortige Abt\u00f6tung vornehmen, um die Barmherzigkeit Gottes f\u00fcr alle S\u00fcnder zu erlangen, einige Almosen geben oder sie durch das Aufsagen von Gebeten oder Sto\u00dfgebeten ersetzen usw. Am letzten Tag wird die \u00dcbung durch eine nette Aufforderung ersetzt, vielleicht sogar in Anspielung auf die Marquise von Barolo, \u201emindestens ein <em>Ave-Maria<\/em> f\u00fcr die Person zu beten, die diese Andacht und Verehrung gef\u00f6rdert hat!\u201c.<br><br><strong>Die p\u00e4dagogische Praxis<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Aber abgesehen von den Schriften mit erbaulichen und bildenden Zwecken kann man sich fragen, wie Don Bosco seine jungen Leute konkret zum Vertrauen in die g\u00f6ttliche Barmherzigkeit erzogen hat. Die Antwort ist nicht schwer und k\u00f6nnte auf viele Arten dokumentiert werden. Wir beschr\u00e4nken uns auf drei wichtige Erfahrungen, die er in Valdocco gemacht hat: die Sakramente der Beichte und der Kommunion und seine Figur als \u201eVater voller G\u00fcte und Liebe\u201c.<br><br><strong>Die Beichte<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco hat Hunderte von jungen Menschen aus Valdocco in das christliche Erwachsenenleben eingef\u00fchrt. Aber mit welchen Mitteln? Vor allem durch zwei: die Beichte und die Kommunion.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco ist, wie wir wissen, einer der gro\u00dfen Apostel der Beichte. Das liegt vor allem daran, dass er dieses Amt in vollem Umfang aus\u00fcbte, wie \u00fcbrigens auch sein oben erw\u00e4hnter Lehrer und geistlicher Leiter Cafasso und die viel bewunderte Gestalt seines Fast-Zeitgenossen, des heiligen Pfarrers von Ars (1876-1859). W\u00e4hrend letzterer, wie geschrieben wurde, sein Leben \u201eim Beichtstuhl verbrachte\u201c und viele Stunden des Tages (\u201edie n\u00f6tige Zeit\u201c) aufbringen konnte, um \u201eBisch\u00f6fen, Priestern, Ordensleuten, bedeutenden Laien und einfachen Leuten, die zu ihm str\u00f6mten\u201c, die Beichte abzunehmen, war dies bei Don Bosco aufgrund der vielen Besch\u00e4ftigungen, in die er vertieft war, nicht m\u00f6glich. Dennoch stand er den Jugendlichen (und den Salesianern) an jedem Tag, an dem in Valdocco oder in den Salesianerh\u00e4usern Gottesdienste gefeiert wurden, oder bei besonderen Anl\u00e4ssen im Beichtstuhl zur Verf\u00fcgung.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Er hatte damit begonnen, sobald er seine \u201ePriesterausbildung\u201c im Internat (1841-1844) beendet hatte, als er sonntags die jungen M\u00e4nner im Wanderoratorium des zweij\u00e4hrigen Kurses versammelte, als er in der Wallfahrtskirche der Consolata oder in den piemontesischen Pfarreien, in die er eingeladen wurde, Beichte h\u00f6rte, als er Kutschen- oder Zugfahrten nutzte, um Kutschern oder Passagieren die Beichte abzunehmen. Er h\u00f6rte nicht auf, dies zu tun, bis zu seinem Ende. Als er gefragt wurde, ob er sich nicht zu sehr mit Beichten abm\u00fchen wolle, antwortete er, dass dies inzwischen das Einzige sei, was er f\u00fcr seine jungen Leute tun k\u00f6nne. Und wie gro\u00df war sein Kummer, als seine Beichtlizenz aus b\u00fcrokratischen Gr\u00fcnden und aufgrund von Missverst\u00e4ndnissen vom Erzbischof nicht verl\u00e4ngert wurde! Die Zeugnisse \u00fcber Don Bosco als Beichtvater sind zahllos, und das ber\u00fchmte Foto, das ihn bei der Beichte eines kleinen Jungen zeigt, umgeben von so vielen anderen, die darauf warten, muss dem Heiligen selbst gefallen haben, der vielleicht die Idee dazu hatte, und das in der kollektiven Vorstellung immer noch ein bedeutendes und unausl\u00f6schliches Symbol seiner Figur ist.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Aber \u00fcber seine Erfahrung als Beichtvater hinaus war Don Bosco ein unerm\u00fcdlicher Verfechter des Sakraments der Vers\u00f6hnung, er verbreitete seine Notwendigkeit, seine Bedeutung, die N\u00fctzlichkeit seiner H\u00e4ufigkeit, er wies auf die Gefahren einer Feier hin, der es an den notwendigen Voraussetzungen mangelt, er veranschaulichte die klassischen Wege, um es fruchtbar zu machen. Er tat dies durch Vortr\u00e4ge, gute Abende, geistreiche Mottos und kleine Worte im Ohr, Rundbriefe an die jungen Leute in den Kollegs, pers\u00f6nliche Briefe und die Erz\u00e4hlung zahlreicher Tr\u00e4ume, die die Beichte zum Ziel hatten, ob gut oder schlecht gemacht. In \u00dcbereinstimmung mit seiner intelligenten katechetischen Praxis erz\u00e4hlte er ihnen Episoden von Bekehrungen gro\u00dfer S\u00fcnder und auch seine eigenen pers\u00f6nlichen Erfahrungen in dieser Hinsicht.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco, ein profunder Kenner der jugendlichen Seele, nutzte die Liebe und Dankbarkeit gegen\u00fcber Gott, die er in seiner unendlichen G\u00fcte, Gro\u00dfz\u00fcgigkeit und Barmherzigkeit darstellte, um alle jungen Menschen zur aufrichtigen Reue zu bewegen. Um die k\u00e4ltesten und verh\u00e4rtetsten Herzen zu ersch\u00fcttern, beschreibt er stattdessen die m\u00f6glichen Strafen f\u00fcr die S\u00fcnde und beeindruckt ihr Gem\u00fct auf heilsame Weise mit anschaulichen Beschreibungen des Gottesurteils und der H\u00f6lle. Aber auch in diesen F\u00e4llen begn\u00fcgt er sich nicht damit, die Jungen zur Reue \u00fcber ihre S\u00fcnden zu treiben, sondern versucht, sie auf die Notwendigkeit der g\u00f6ttlichen Barmherzigkeit hinzuweisen \u2013 eine wichtige Voraussetzung, um ihre Vergebung schon vor der sakramentalen Beichte zu erwarten. Don Bosco l\u00e4sst sich wie \u00fcblich nicht auf doktrin\u00e4re Abhandlungen ein, er ist nur an einer aufrichtigen Beichte interessiert, die therapeutisch die Wunde der Vergangenheit heilt und das geistige Gef\u00fcge der Gegenwart f\u00fcr eine Zukunft in einem \u201eLeben der Gnade\u201c neu zusammensetzt.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco glaubt an die S\u00fcnde, er glaubt an die schwere S\u00fcnde, er glaubt an die H\u00f6lle, und er spricht mit seinen Lesern und Zuh\u00f6rern \u00fcber deren Existenz. Aber er ist auch \u00fcberzeugt, dass Gott die Barmherzigkeit verk\u00f6rpert, weshalb er dem Menschen das Sakrament der Vers\u00f6hnung geschenkt hat. Und so besteht er auf den Bedingungen f\u00fcr einen guten Empfang und vor allem auf dem Beichtvater als \u201eVater\u201c und \u201eArzt\u201c und nicht so sehr als \u201eArzt und Richter\u201c: \u201eDer Beichtvater wei\u00df, wie viel gr\u00f6\u00dfer als eure Fehler die Barmherzigkeit Gottes ist, der euch durch sein Eingreifen Vergebung gew\u00e4hrt\u201c (<a href=\"https:\/\/www.donboscosanto.eu\/oe\/cenno_biografico_sul_giovanetto_magone_michele.php\" target=\"_blank\" rel=\"noreferrer noopener\">Biographischer Abriss \u00fcber den jungen Magone Michele<\/a>, S. 24-25).<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Den Erinnerungen der Salesianer zufolge empfahl er seinen Jugendlichen oft, die g\u00f6ttliche Barmherzigkeit anzurufen, sich nach einer S\u00fcnde nicht entmutigen zu lassen, sondern ohne Angst zur Beichte zur\u00fcckzukehren, auf die G\u00fcte des Herrn zu vertrauen und dann feste Vors\u00e4tze zum Guten zu fassen.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Als \u201eErzieher im Bereich der Jugend\u201c hielt es Don Bosco f\u00fcr notwendig, weniger auf <em>ex opere operato<\/em> und mehr auf <em>ex opere operantis<\/em> zu bestehen, d.h. auf der Gesinnung des P\u00f6nitenten. In Valdocco f\u00fchlten sich alle eingeladen, eine gute Beichte abzulegen, alle sp\u00fcrten das Risiko einer schlechten Beichte und die Bedeutung einer guten Beichte; viele von ihnen hatten damals das Gef\u00fchl, dass sie in einem vom Herrn gesegneten Land lebten. Nicht umsonst hatte die g\u00f6ttliche Barmherzigkeit daf\u00fcr gesorgt, dass ein verstorbener junger Mann aufwachte, nachdem die Leichent\u00fccher gel\u00fcftet worden waren, damit er (Don Bosco) seine S\u00fcnden beichten konnte.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Kurzum, das Sakrament der Beichte, das in seinen Besonderheiten gut erkl\u00e4rt und h\u00e4ufig zelebriert wurde, war vielleicht das wirksamste Mittel, mit dem der piemontesische Heilige seine jungen Leute dazu brachte, auf die unermessliche Barmherzigkeit Gottes zu vertrauen.<br><strong><br>Die Kommunion<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Aber auch die Kommunion, die zweite S\u00e4ule der religi\u00f6sen P\u00e4dagogik Don Boscos, erf\u00fcllte ihren Zweck.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco ist sicherlich einer der gr\u00f6\u00dften Verfechter der sakramentalen Praxis der h\u00e4ufigen Kommunion. Seine Lehre, die sich an der gegenreformatorischen Denkweise orientierte, gab der Kommunion einen h\u00f6heren Stellenwert als der liturgischen Feier der Eucharistie, auch wenn es eine Entwicklung bei der H\u00e4ufigkeit der Kommunion gab. In den ersten zwanzig Jahren seines priesterlichen Lebens, im Gefolge des heiligen Alfons, aber auch des Konzils von Trient und noch davor von Tertullian und dem heiligen Augustinus, schlug er die w\u00f6chentliche Kommunion vor, oder mehrmals in der Woche oder sogar t\u00e4glich, je nach der Vollkommenheit der den Gnaden des Sakraments entsprechenden Veranlagungen. Dominikus Savio, der in Valdocco damit begonnen hatte, alle vierzehn Tage zur Beichte und zur Kommunion zu gehen, ging dann dazu \u00fcber, dies jede Woche zu tun, dann dreimal pro Woche und schlie\u00dflich, nach einem Jahr intensiven geistlichen Wachstums, jeden Tag, wobei er offensichtlich immer dem Rat seines Beichtvaters, Don Bosco selbst, folgte.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sp\u00e4ter, in der zweiten H\u00e4lfte der 1960er Jahre, ging Don Bosco auf der Grundlage seiner p\u00e4dagogischen Erfahrungen und einer starken theologischen Str\u00f6mung, die sich f\u00fcr die h\u00e4ufige Kommunion aussprach und in der der franz\u00f6sische Bischof Msgr. de S\u00e9gur und der Prior von Genua, Don Giuseppe Frassinetti, f\u00fchrend waren, dazu \u00fcber, seine jungen M\u00e4nner zu einer h\u00e4ufigeren Kommunion einzuladen, in der \u00dcberzeugung, dass dies entscheidende Schritte im geistlichen Leben erm\u00f6glichte und ihr Wachstum in der Liebe zu Gott beg\u00fcnstigte. Und f\u00fcr den Fall, dass die t\u00e4gliche sakramentale Kommunion nicht m\u00f6glich war, schlug er die geistliche Kommunion vor, vielleicht w\u00e4hrend eines Besuchs des Allerheiligsten Sakraments, den der heilige Alfons so sehr sch\u00e4tzte. Das Wichtigste war jedoch, das Gewissen in einem Zustand zu halten, der es erm\u00f6glichte, jeden Tag zur Kommunion zu gehen: Die Entscheidung lag gewisserma\u00dfen beim Beichtvater.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; F\u00fcr Don Bosco hebt jede w\u00fcrdig empfangene Kommunion \u2013 vorgeschriebenes Fasten, Zustand der Gnade, Bereitschaft, sich von der S\u00fcnde zu l\u00f6sen, eine sch\u00f6ne Danksagung danach \u2013 die t\u00e4glichen Fehler auf, st\u00e4rkt die Seele, sie in Zukunft zu vermeiden, st\u00e4rkt das Vertrauen in Gott und in seine unendliche G\u00fcte und Barmherzigkeit; au\u00dferdem ist sie eine Quelle der Gnade, um in der Schule und im Leben erfolgreich zu sein, sie ist eine Hilfe, um Leiden zu ertragen und Versuchungen zu \u00fcberwinden.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco glaubt, dass die Kommunion f\u00fcr die \u201eGuten\u201c eine Notwendigkeit ist, um sich als solche zu erhalten und f\u00fcr die \u201eB\u00f6sen\u201c, um \u201egut\u201c zu werden. Sie ist f\u00fcr diejenigen, die heilig werden wollen, nicht f\u00fcr die Heiligen, so wie die Arzneimittel den Kranken gegeben werden. Nat\u00fcrlich wei\u00df er, dass die Teilnahme an der Kommunion allein kein sicheres Indiz f\u00fcr die G\u00fcte ist, denn es gibt Menschen, die sie nur lauwarm und aus Gewohnheit empfangen, zumal die Oberfl\u00e4chlichkeit junger Menschen ihnen oft nicht erlaubt, die volle Bedeutung dessen, was sie tun, zu verstehen.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Mit der Kommunion kann man also besondere Gnaden des Herrn f\u00fcr sich selbst und f\u00fcr andere erflehen. Don Boscos Briefe sind voll von Bitten an seine jungen M\u00e4nner, zu beten und die Kommunion in seinem Sinne zu empfangen, damit der Herr ihm guten Erfolg in den \u201eAngelegenheiten\u201c jedes Ordens, in den er eingetaucht ist, gew\u00e4hren m\u00f6ge. Und er tat dasselbe mit all seinen Briefpartnern, die er aufforderte, sich diesem Sakrament zu n\u00e4hern, um die erbetenen Gnaden zu erhalten, w\u00e4hrend er dasselbe bei der Feier der Heiligen Messe tun w\u00fcrde.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Don Bosco war es sehr wichtig, dass seine Jungen mit den Sakramenten aufwuchsen, aber er wollte auch, dass ihre Freiheit in h\u00f6chstem Ma\u00dfe respektiert wurde. Und er hinterlie\u00df seinen Erziehern in seiner kleinen Abhandlung \u00fcber das Pr\u00e4ventivsystem genaue Anweisungen: \u201eZwingt die jungen Menschen niemals, die heiligen Sakramente zu besuchen, sondern ermutigt sie nur und gebt ihnen den Trost, davon Gebrauch zu machen\u201c.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Gleichzeitig blieb er jedoch unnachgiebig in seiner \u00dcberzeugung, dass die Sakramente von \u00fcberragender Bedeutung sind. Er schrieb entschieden: \u201eSagt, was ihr wollt \u00fcber die verschiedenen Erziehungssysteme, aber ich finde keine sichere Grundlage au\u00dfer der H\u00e4ufigkeit von Beichte und Kommunion\u201c (<a href=\"https:\/\/www.donboscosanto.eu\/oe\/il_pastorello_delle_alpi_ovvero_vita_del_giovane_besucco_francesco_d-argentera.php\" target=\"_blank\" rel=\"noreferrer noopener\">Der Hirtenjunge der Alpen, oder das Leben des jungen Besucco Francesco d\u2019Argentera<\/a>, 1864. S. 100).<br><br><strong>Die Verk\u00f6rperung der V\u00e4terlichkeit und der Barmherzigkeit<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Die Barmherzigkeit Gottes, die vor allem bei den Sakramenten der Beichte und der Kommunion am Werk war, fand dann ihren \u00e4u\u00dferen Ausdruck nicht nur in einem Don Bosco als \u201eBeichtvater\u201c, sondern auch als \u201eVater, Bruder, Freund\u201c der jungen M\u00e4nner im normalen Alltag. Mit einer gewissen \u00dcbertreibung k\u00f6nnte man sagen, dass ihr Vertrauen zu Don Bosco so gro\u00df war, dass viele von ihnen kaum einen Unterschied zwischen Don Bosco als \u201eBeichtvater\u201c und Don Bosco als \u201eFreund\u201c und \u201eBruder\u201c machten; andere konnten die sakramentale Anklage manchmal mit den aufrichtigen Ausgie\u00dfungen eines Sohnes gegen\u00fcber seinem Vater austauschen; andererseits war Don Boscos Kenntnis der jungen Menschen so gro\u00df, dass er ihnen mit n\u00fcchternen Fragen \u00e4u\u00dferstes Vertrauen einfl\u00f6\u00dfte und nicht selten an ihrer Stelle die Anklage zu erheben wusste.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Die Figur des barmherzigen und f\u00fcrsorglichen Gottes, der im Laufe der Geschichte von Adam an seine G\u00fcte gegen\u00fcber den Menschen bewiesen hat, seien sie nun gerecht oder s\u00fcndig, aber alle bed\u00fcrftig und Gegenstand v\u00e4terlicher F\u00fcrsorge, und auf jeden Fall alle zum Heil in Jesus Christus berufen, wird so moduliert und spiegelt sich in der G\u00fcte von Don Bosco, dem \u201eVater seiner Jugendlichen\u201c, wider, der nur ihr Wohl will, der sie nicht im Stich l\u00e4sst, immer bereit, sie zu verstehen, zu bemitleiden, ihnen zu vergeben. F\u00fcr viele von ihnen, Waisenkinder, Arme und Verlassene, die von klein auf an die harte t\u00e4gliche Arbeit gew\u00f6hnt waren, das Objekt sehr bescheidener Z\u00e4rtlichkeitsbekundungen, Kinder einer Epoche, in der entschlossene Unterwerfung und absoluter Gehorsam gegen\u00fcber jeder konstituierten Beh\u00f6rde herrschten, war Don Bosco vielleicht die Liebkosung eines Vaters, die nie erfahren wurde, die \u201eZ\u00e4rtlichkeit\u201c, von der Papst Franziskus spricht.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Sein Brief an die jungen M\u00e4nner des Mirabello-Hauses Ende 1864 ist immer noch bewegend: \u201eDiese Stimmen, diese Beifallsbekundungen, das K\u00fcssen und H\u00e4ndesch\u00fctteln, das herzliche L\u00e4cheln, die Gespr\u00e4che \u00fcber die Seele, die gegenseitige Ermutigung, Gutes zu tun, sind Dinge, die mein Herz balsamierten, und deshalb kann ich nicht an sie denken, ohne zu Tr\u00e4nen ger\u00fchrt zu sein. Ich werde euch sagen [&#8230;], dass ihr mein Augapfel seid\u201c (Epistolario II, herausgegeben von F. Motto II, Brief Nr. 792).<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Noch bewegender ist sein Brief an die jungen M\u00e4nner von Lanzo vom 3. Januar 1876: \u201eLasst mich euch sagen, und niemand soll daran Ansto\u00df nehmen, ihr seid alle Diebe; ich sage es und wiederhole es, ihr habt mir alles genommen. Als ich in Lanzo war, habt ihr mich mit eurem Wohlwollen und eurer liebevollen G\u00fcte verzaubert, ihr habt die F\u00e4higkeiten meines Geistes mit eurem Mitleid gefesselt; mir blieb noch dieses arme Herz, dessen Zuneigung ihr mir schon ganz gestohlen hattet. Nun hat euer Brief, der von 200 freundlichen und lieben H\u00e4nden geschrieben wurde, von diesem ganzen Herzen Besitz ergriffen, dem nichts mehr geblieben ist als der lebendige Wunsch, euch im Herrn zu lieben, euch Gutes zu tun und die Seelen aller zu retten\u201c (Epistolario III, Brief Nr. 1389).<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Die liebevolle G\u00fcte, mit der er die Jungen behandelte und von der er wollte, dass die Salesianer sie behandeln, hatte eine g\u00f6ttliche Grundlage. Er bekr\u00e4ftigte dies, indem er einen Ausspruch des heiligen Paulus zitierte: \u201eDie N\u00e4chstenliebe ist g\u00fctig und langm\u00fctig; sie ertr\u00e4gt alles, hofft aber auch alles und h\u00e4lt allen M\u00fchen stand\u201c.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Die liebende G\u00fcte war also ein Zeichen der Barmherzigkeit und der g\u00f6ttlichen Liebe, die sich aufgrund der theologischen N\u00e4chstenliebe, die ihr zugrunde lag, der Sentimentalit\u00e4t und den Formen der Sinnlichkeit entzog. Don Bosco vermittelte diese Liebe einzelnen Jungen und auch Gruppen von ihnen: \u201eDass ich euch sehr liebe, brauche ich euch nicht zu sagen, ich habe es euch deutlich bewiesen. Dass ihr mich auch liebt, brauche ich nicht zu sagen, denn ihr habt es mir st\u00e4ndig gezeigt. Aber worauf gr\u00fcndet sich unsere gegenseitige Zuneigung? [&#8230;] Das Wohl unserer Seelen ist also das Fundament unserer Zuneigung\u201c (Epistolario II, Nr. 1148). Die Liebe zu Gott, das theologische <em>Primum<\/em>, ist also das Fundament vom p\u00e4dagogischen <em>Primum<\/em>.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Die G\u00fcte war auch die \u00dcbersetzung der g\u00f6ttlichen Liebe in eine wahrhaft menschliche Liebe, die aus rechtem Einf\u00fchlungsverm\u00f6gen, liebensw\u00fcrdiger Herzlichkeit, wohlwollender und geduldiger Zuneigung besteht, die zu einer tiefen Gemeinschaft des Herzens f\u00fchrt. Kurz gesagt handelt es sich hier um diese wirksame und affektive Liebe, die in einer privilegierten Form in der Beziehung zwischen dem zu Erziehenden und dem Erzieher erlebt wird, wenn Gesten der Freundschaft und der Vergebung seitens des Erziehers den jungen Menschen dazu bringen, sich aufgrund der Liebe, die den Erzieher leitet, dem Vertrauen zu \u00f6ffnen, sich in seinem Bem\u00fchen, \u00fcber sich selbst hinauszuwachsen und sich zu engagieren, unterst\u00fctzt zu f\u00fchlen, seine Zustimmung zu geben und den Werten, die der Erzieher pers\u00f6nlich lebt und ihm vorschl\u00e4gt, in der Tiefe zu folgen. Der junge Mensch begreift, dass diese Beziehung ihn als Mann rekonstruiert und umstrukturiert. Das m\u00fchsamste Unterfangen des Pr\u00e4ventivsystems besteht gerade darin, das Herz des jungen Menschen zu gewinnen, seine Wertsch\u00e4tzung zu genie\u00dfen, sein Vertrauen zu gewinnen, ihn zu einem Freund zu machen. Wenn ein junger Mensch den Erzieher nicht liebt, kann er sehr wenig von dem jungen Menschen und f\u00fcr den jungen Menschen tun.<br><br><strong>Die Werke der Barmherzigkeit<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Wir k\u00f6nnten nun mit den Werken der Barmherzigkeit fortfahren, bei denen der Katechismus zwischen k\u00f6rperlichen und geistlichen Werken unterscheidet und zwei Gruppen von sieben aufz\u00e4hlt. Es w\u00e4re nicht schwer, zu dokumentieren, wie Don Bosco diese Werke der Barmherzigkeit gelebt, praktiziert und gef\u00f6rdert hat und wie er durch sein \u201eSein und Wirken\u201c in der Tat ein Zeichen und sichtbares Zeugnis der Liebe Gottes zu den Menschen in Taten und Worten darstellte. Aus Platzgr\u00fcnden beschr\u00e4nken wir uns darauf, auf die M\u00f6glichkeiten der Forschung hinzuweisen. Es bleibt jedoch festzuhalten, dass sie heute auch wegen des falschen Gegensatzes zwischen Barmherzigkeit und Gerechtigkeit aufgegeben zu werden scheinen, als ob die Barmherzigkeit nicht eine typische Form des Ausdrucks jener Liebe w\u00e4re, die als solche niemals im Widerspruch zur Gerechtigkeit stehen kann.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als sehr junger Priester ver\u00f6ffentlichte Don Bosco ein B\u00e4ndchen im Kleinformat mit dem Titel \u201e\u00dcbung&#8230;<\/p>\n","protected":false},"author":7,"featured_media":36055,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":9,"footnotes":""},"categories":[145],"tags":[2575,2555,1969,1993,1735,1963,1957,2504,2564],"class_list":["post-36062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-don-bosco","tag-don-bosco","tag-gott","tag-heilige","tag-hoffnung","tag-katechese","tag-rettung","tag-salesianer","tag-charyzmat-salezjanski","tag-wohltaetigkeit"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/36062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/comments?post=36062"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/36062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media\/36055"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media?parent=36062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/categories?post=36062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/tags?post=36062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}