{"id":31043,"date":"2024-12-12T17:38:29","date_gmt":"2024-12-12T17:38:29","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=31043"},"modified":"2026-03-26T07:57:36","modified_gmt":"2026-03-26T07:57:36","slug":"andrea-beltrami-und-sein-tugendhaftes-profil-1-2","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/de\/unsere-heiligen\/andrea-beltrami-und-sein-tugendhaftes-profil-1-2\/","title":{"rendered":"Andrea Beltrami und sein tugendhaftes Profil (1\/2)"},"content":{"rendered":"\n<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Der ehrw\u00fcrdige Don Andrea Beltrami (1870-1897) steht sinnbildlich f\u00fcr eine Dimension, die nicht nur f\u00fcr das salesianische Charisma, sondern auch f\u00fcr das Christentum konstitutiv ist: die Dimension der Selbstlosigkeit und der Opferbereitschaft, die im salesianischen Sinne die Forderungen des <em>\u201ecaetera tolle\u201c<\/em> verk\u00f6rpert. Ein Zeugnis, das entweder aufgrund seiner Einzigartigkeit oder aus Gr\u00fcnden, die zum Teil mit veralteten Lesarten zusammenh\u00e4ngen oder durch eine bestimmte Vulgata \u00fcberliefert wurden, aus dem Blickfeld der salesianischen Welt verschwunden ist. Es bleibt die Tatsache, dass die christliche Botschaft von Natur aus Aspekte aufweist, die mit der Welt unvereinbar sind, und wenn sie ignoriert werden, besteht die Gefahr, dass die Botschaft des Evangeliums selbst und insbesondere das salesianische Charisma, das in seinen charismatischen Wurzeln des Opfergeistes, der harten Arbeit und des apostolischen Verzichts ungesch\u00fctzt ist, unfruchtbar wird. Das Zeugnis von Don Andrea Beltrami ist paradigmatisch f\u00fcr einen ganzen Strang salesianischer Heiligkeit, der mit den drei Heiligen Andrea Beltrami, dem seligen August Czartoryski und dem seligen Aloisius Variara beginnt und sich im Laufe der Zeit mit anderen Familienfiguren wie der seligen Eusebia Palomino, der seligen Alexandrina Maria da Costa und der seligen Laura Vicu\u00f1a fortsetzt, ohne die zahlreichen M\u00e4rtyrer zu vergessen.<br><br><strong>1. Evangelischer Radikalismus<br><br>1.1 Radikal in der Berufungswahl<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Andrea Beltrami wurde am 24. Juni 1870 in Omegna (Novara), am Ufer des Ortasees, geboren. In seiner Familie erhielt er eine zutiefst christliche Erziehung, die er am Salesianerkolleg in Lanzo, in das er im Oktober 1883 eintrat, vertiefte. Hier reifte er in seiner Berufung. In Lanzo hatte er eines Tages das gro\u00dfe Gl\u00fcck, Don Bosco zu treffen. Fasziniert von ihm, kam in ihm die Frage auf: \u201eWarum kann ich nicht so sein wie er? Warum sollte ich nicht auch mein Leben f\u00fcr die Ausbildung und das Heil der jungen Menschen einsetzen?\u201c. 1885 sagte Don Bosco zu ihm: \u201eAndrea, werde auch du ein Salesianer!\u201c. 1886 erhielt er von Don Bosco in Foglizzo das Priestergewand und am 29. Oktober 1886 begann er sein Noviziatsjahr mit einem Vorsatz: \u201eIch will ein Heiliger werden\u201c. Dieser Vorsatz war keine Formalit\u00e4t, sondern wurde zu einem Lebensmotto. Besonders Don Eugenio Bianchi, sein Novizenmeister, beschrieb ihn in seinem Bericht an Don Bosco als vollkommen in jeder Tugend. Schon im Noviziat dr\u00fcckte sich seinen Radikalismus im Gehorsam gegen\u00fcber den Vorgesetzten, in der Aus\u00fcbung der N\u00e4chstenliebe gegen\u00fcber seinen Mitbr\u00fcdern und in der Einhaltung der religi\u00f6sen Regeln aus, so dass er als die \u201everk\u00f6rperte Regel\u201c bezeichnet wurde. Am 2. Oktober 1887 erhielt Don Bosco in Valsalice (Turin) Andreas Ordensgel\u00fcbde: Er war Salesianer geworden und begann sofort mit den Studien zur Vorbereitung auf das Priesteramt.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Die Festigkeit und Entschlossenheit, mit der er dem Ruf des Herrn folgte, war sehr auff\u00e4llig und ein Zeichen f\u00fcr den Wert, den er seiner Berufung beima\u00df: \u201eDie Gnade der Berufung war f\u00fcr mich eine ganz besondere Gnade, unbesiegbar, unwiderstehlich und wirksam. Der Herr hatte mir eine feste \u00dcberzeugung ins Herz gelegt, eine tiefe \u00dcberzeugung, dass der einzige Weg, der zu mir passte, darin bestand, Salesianer zu werden; es war eine Befehlsstimme, die keine Antwort zulie\u00df, die jedes Hindernis aus dem Weg r\u00e4umte, dem ich nicht h\u00e4tte widerstehen k\u00f6nnen, selbst wenn ich es gewollt h\u00e4tte, und deshalb h\u00e4tte ich tausend Schwierigkeiten \u00fcberwunden, selbst wenn es darum gegangen w\u00e4re, \u00fcber den Leichnam meines Vaters und meiner Mutter hinwegzugehen, wie Chantal, als sie \u00fcber den Leichnam ihres Sohnes hinwegging\u201c. Diese Ausdr\u00fccke sind sehr stark und vielleicht nicht sehr angenehm f\u00fcr unseren Gaumen; sie sind wie der Auftakt zu einer Berufungsgeschichte, die mit einem Radikalismus gelebt wird, das nicht leicht zu verstehen, geschweige denn zu akzeptieren ist.<br><br><strong>1.2. Radikal auf dem Ausbildungsweg<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Ein interessanter und aufschlussreicher Aspekt des umsichtigen Handelns ist die F\u00e4higkeit, sich beraten und korrigieren zu lassen und seinerseits f\u00e4hig zu werden, die anderen zu korrigieren und zu beraten: \u201eIch werfe mich wie ein Kind in Ihre Arme und \u00fcberlasse mich ganz Ihrer F\u00fchrung. M\u00f6gen Sie mich auf den Weg der Vollkommenheit f\u00fchren, ich bin entschlossen, mit der Gnade Gottes jede Schwierigkeit zu \u00fcberwinden, jede Anstrengung zu unternehmen, um Ihrem Rat zu folgen\u201c; so an seinen geistlichen Begleiter Don Giulio Barberis. Bei der Aus\u00fcbung von Lehre und Assistenz \u201esprach er immer ruhig und gelassen&#8230; zuerst las er sorgf\u00e4ltig die Vorschriften derselben \u00c4mter&#8230; die Regeln und Vorschriften \u00fcber die Assistenz und \u00fcber die Unterrichtsmethoden&#8230; bald lernte er jeden seiner Sch\u00fcler und ihre individuellen Bed\u00fcrfnisse kennen, dann wurde er allen und jedem alles\u201c. Bei der br\u00fcderlichen Korrektur lie\u00df er sich von christlichen Grunds\u00e4tzen leiten und griff ein, indem er seine Worte gut abwog und seine Gedanken klar zum Ausdruck brachte.<br><br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; In dieser Zeit machte Andrea die Bekanntschaft des polnischen F\u00fcrsten August Czartoryski, der kurz zuvor in die Kongregation eingetreten war und mit dem er eng befreundet wurde: Sie studierten gemeinsam Fremdsprachen und halfen sich gegenseitig, den Gipfel der Heiligkeit zu erreichen. Als August krank wurde, baten die Oberen Andrea, in seiner N\u00e4he zu bleiben und ihm zu helfen. Sie verbrachten ihre Sommerferien gemeinsam in den Salesianer-Instituten von Lanzo, Penango d\u2019Asti und Alassio. August, der inzwischen das Priesteramt erreicht hatte, war Andreas Schutzengel, Lehrer und heldenhaftes Vorbild der Heiligkeit. Don August verstarb 1893 und Don Andrea sagte \u00fcber ihn: \u201eIch habe einen Heiligen behandelt\u201c. Als Don Beltrami seinerseits an der gleichen Krankheit erkrankte, war eine der wahrscheinlichen Ursachen diese Vertrautheit mit seinem kranken Freund.<br><br><strong>1.3. Radikal bei der Pr\u00fcfung<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Seine Krankheit begann auf brutale Art und Weise am 20. Februar 1891, als nach einer sehr anstrengenden Reise und w\u00e4hrend Tagen mit hartem Winterwetter die ersten Symptome einer Krankheit auftraten, die seine Gesundheit untergraben und ihn ins Grab f\u00fchren sollte. Wenn zu den Ursachen auch der Schulbesuch und der Kontakt mit dem an der Krankheit leidenden F\u00fcrsten Czartoryski geh\u00f6ren, so sind doch sowohl die asketischen Anstrengungen als auch die Opfergabe erw\u00e4hnenswert. Sein Landsmann und Noviziatskamerad Giulio Cane bezeugt diesen Kampf mit dem alten Mann: \u201eIch war immer davon \u00fcberzeugt, dass der Diener Gottes den schwersten Schlag f\u00fcr seine Gesundheit durch die gewaltsame und st\u00e4ndige Art und Weise erlitt, mit der er sich zwang, auf alle seine freiwilligen Bewegungen zu verzichten, um sich, ich w\u00fcrde sagen, zum Sklaven des Willens des Oberen zu machen, in dem er den Gottes sah. Nur wer den Diener Gottes in den Jahren seiner Adoleszenz und Jugend kennen gelernt hat, mit seinem impulsiven, feurigen Geist, der sich fast gegen jede Zur\u00fcckhaltung auflehnte, und wer wei\u00df, wie hartn\u00e4ckig er an seiner eigenen Meinung festhielt, was typisch f\u00fcr das Volk der Beltrami Manera war, kann sich eine klare Vorstellung von der Anstrengung machen, die der Diener Gottes auf sich nehmen musste, um sich selbst zu beherrschen. Aus den Gespr\u00e4chen, die ich mit dem Diener Gottes gef\u00fchrt habe, bin ich zu der \u00dcberzeugung gelangt, dass er sich in der Hoffnung, sich selbst nach und nach in seinem Charakter erobern zu k\u00f6nnen, schon in den ersten Monaten seines Noviziats den Vorsatz gefasst hat, seinem Willen, seinen Neigungen und seinen Bestrebungen radikal abzuschw\u00f6ren. All dies erreichte er mit st\u00e4ndiger Wachsamkeit \u00fcber sich selbst, um niemals in seinem Vorhaben zu scheitern. Es ist unm\u00f6glich, dass ein solcher innerer Kampf nicht mehr als die M\u00fchen des Studiums und der Lehre dazu beigetragen hat, die Gesundheit des Dieners Gottes zu untergraben\u201c. Wahrlich, der junge Beltrami nahm die Worte des Evangeliums w\u00f6rtlich: \u201eDas Himmelreich leidet Gewalt, und die Gewalt brauchen, rei\u00dfen es an sich\u201c (Mt 11,12).<br><br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Er lebte sein Leiden mit innerer Freude: \u201eDer Herr will, dass ich Priester und Opfer bin: Was k\u00f6nnte sch\u00f6ner sein?\u201c. Sein Tag begann mit der Heiligen Messe, in der er sein Leiden mit dem Opfer Jesu auf dem Altar verband. Die Meditation wurde zur Kontemplation. Von Msgr. Cagliero zum Priester geweiht, widmete er sich ganz der Kontemplation und dem Apostolat des Stiftes. Mit einem unb\u00e4ndigen Willen und einem vehementen Wunsch nach Heiligkeit verzehrte er seine Existenz in Schmerz und unabl\u00e4ssiger Arbeit. \u201eDie Mission, die Gott mir anvertraut hat, ist zu beten und zu leiden\u201c, sagte er. \u201eIch bin zufrieden und gl\u00fccklich und ich feiere immer. Weder sterben noch heilen, sondern leben, um zu leiden: Im Leiden habe ich die wahre Zufriedenheit gefunden\u201c, war sein Motto. Aber seine wahre Berufung war das Gebet und das Leiden: ein Opfer mit dem g\u00f6ttlichen Opfer, das Jesus ist, zu sein. Das zeigt sich in seinen leuchtenden und gl\u00fchenden Schriften: \u201eEs ist auch sch\u00f6n, in der Dunkelheit, wenn alle ruhen, mit Jesus zusammen zu sein, im flackernden Licht der Lampe vor dem Tabernakel. Man erkennt dann die unendliche Gr\u00f6\u00dfe seiner Liebe\u201c. \u201eIch bitte Gott um lange Jahre des Lebens, um zu leiden und zu b\u00fc\u00dfen, um Wiedergutmachung zu leisten. Ich bin zufrieden und ich feiere immer, weil ich es tun kann. Weder sterben noch heilen, sondern leben, um zu leiden. Im Leiden liegt meine Freude, das Leiden, das mit Jesus am Kreuz geopfert wird\u201c. \u201eIch opfere mich als Opfer mit Ihm, zur Heiligung der Priester, f\u00fcr die Menschen der ganzen Welt\u201c.<br><br><strong>2. Das Geheimnis<br><\/strong>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; In seinem grundlegenden Text zum Verst\u00e4ndnis der Geschichte von Don Andrea Beltrami stellt Don Giulio Barberis die Heiligkeit des jungen Salesianers in die N\u00e4he derjenigen von Don Bosco, dem Apostel der verlassenen Jugend. Aufgrund seines Rufs der Heiligkeit und der Wohlt\u00e4tigkeit spricht Don Barberis von Don Beltrami als einem \u201eleuchtenden hervorragenden Stern\u2026 der als gutes Beispiel so viel Licht ausstrahlte und uns durch seine Tugenden zum Guten ermutigte!\u201c. Es geht also darum, zu begreifen, was f\u00fcr ein vorbildliches Leben das ist und inwieweit es eine Ermutigung f\u00fcr diejenigen ist, die darauf schauen. Das Zeugnis von Don Barberis wird noch strenger, und in einer sehr k\u00fchnen Form erkl\u00e4rt er: \u201eIch bin seit \u00fcber 50 Jahren in der Frommen Salesianischen Gesellschaft; seit \u00fcber 25 Jahren bin ich Novizenmeister: Wie viele heilige Mitbr\u00fcder habe ich gekannt, wie viele gute junge M\u00e4nner sind in dieser Zeit unter mir gegangen! Wie viele auserw\u00e4hlte Blumen hat der Herr in den Garten der Salesianer im Paradies gepflanzt! Und doch, wenn ich meinen ganzen Gedanken aussprechen muss, obwohl ich keine Vergleiche anstellen will, ist meine \u00dcberzeugung, dass niemand unseren liebsten Don Andrea an Tugend und Heiligkeit \u00fcbertroffen hat\u201c. Und dabei bekr\u00e4ftigte er: \u201eIch bin \u00fcberzeugt, dass es eine au\u00dferordentliche Gnade ist, die Gott der von dem unvergleichlichen Don Bosco gegr\u00fcndeten Kongregation schenken wollte, damit wir, indem wir versuchen, ihn nachzuahmen, in der Kirche das Ziel erreichen, das der ehrw\u00fcrdige Don Bosco bei der Gr\u00fcndung der Kirche verfolgte\u201c. Diese Aussage, die von vielen geteilt wird, basiert sowohl auf einer gr\u00fcndlichen Kenntnis des Lebens der Heiligen als auch auf einer mehr als zehnj\u00e4hrigen Vertrautheit mit Don Beltrami.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Auf den ersten Blick scheint Beltramis Licht der Heiligkeit im Gegensatz zu der Heiligkeit Don Boscos zu stehen, die er widerspiegeln soll, aber bei sorgf\u00e4ltiger Lekt\u00fcre erkennt man einen geheimen Faden, auf dem die authentische salesianische Spiritualit\u00e4t gewoben ist. Es ist dieser verborgene, nicht sichtbare Teil, der dennoch das R\u00fcckgrat der spirituellen und apostolischen Physiognomie von Don Bosco und seinen J\u00fcngern bildet. Die Unruhe des \u201e<em>Da mihi animas<\/em>\u201c wird durch die Askese des \u201e<em>caetera tolle<\/em>\u201c gen\u00e4hrt; der vordere Teil des geheimnisvollen Charakters des ber\u00fchmten Traums von den zehn Diamanten mit den Edelsteinen des Glaubens, der Hoffnung, der N\u00e4chstenliebe, der Arbeit und der M\u00e4\u00dfigung verlangt, dass der hintere Teil denjenigen des Gehorsams, der Armut, des Lohns, der Keuschheit und des Fastens entspricht. Don Beltramis kurzes Leben ist voll von einer Botschaft, die den evangelischen Sauerteig darstellt, der alle f\u00fcr die salesianische Mission typischen pastoralen und erzieherischen Handlungen g\u00e4rt, und ohne den sich das apostolische Handeln in einem sterilen und ergebnislosen Aktivismus ersch\u00f6pfen w\u00fcrde. \u201eDas Leben von Don Beltrami, das er ganz und gar im Verborgenen in Gott verbracht hat, ganz und gar im Gebet, im Leiden, in der Dem\u00fctigung, im Opfer, ganz und gar in verborgener, aber best\u00e4ndiger Arbeit, in heldenhafter N\u00e4chstenliebe, wenn auch entsprechend seiner Verfassung auf einen kleinen Kreis beschr\u00e4nkt, erscheint mir alles in allem so bewundernswert, dass man sagen kann: Der Glaube hat schon immer Wunder gewirkt, er wirkt auch heute noch Wunder, und er wird sicherlich Wunder wirken, solange die Welt besteht\u201c.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Es ist die totale und bedingungslose Selbsthingabe an Gottes Plan, die den authentischen Radikalismus der evangelischen Nachfolge begr\u00fcndet, d.h. das, was die Grundlage einer Existenz ist, die als gro\u00dfz\u00fcgige Antwort auf einen Ruf gelebt wird. Der Geist, in dem Don Beltrami sein Leben lebte, kommt in dem Bericht eines seiner Gef\u00e4hrten gut zum Ausdruck, der ihn wegen seiner Krankheit bedauerte und von Beltrami mit den Worten unterbrochen wurde: \u201eLass es\u201c, sagte er, \u201eGott wei\u00df, was er tut; es liegt an jedem selbst, seinen Platz einzunehmen und darin ein wahrer Salesianer zu sein. Ihr anderen Gesunden arbeitet, ich Kranken leide und bete\u201c, so \u00fcberzeugt war er, dass er ein echter Nachahmer Don Boscos war.<br>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Nat\u00fcrlich ist es nicht leicht, ein solches Geheimnis, eine so wertvolle Perle, zu begreifen. Es war nicht leicht f\u00fcr Don Barberis, der ihn zehn Jahre lang ernsthaft als Seelsorger kannte; es war nicht leicht f\u00fcr die salesianische Tradition, die diese Figur allm\u00e4hlich an den Rand dr\u00e4ngte; und es ist auch nicht leicht f\u00fcr uns heute und f\u00fcr einen ganzen kulturellen und anthropologischen Kontext, der dazu neigt, die christliche Botschaft an den Rand zu dr\u00e4ngen, vor allem in ihrem Kern des Erl\u00f6sungswerks, das durch den Skandal der Erniedrigung, der Passion und des Kreuzes geht. \u201eDie Beschreibung der einzigartigen Tugenden eines Mannes, der immer eingeschlossen in einem religi\u00f6sen Haus lebte, und in seinen wichtigsten Jahren in einem kleinen Zimmer, ohne wegen seiner Krankheit auch nur die Treppe hinuntersteigen zu k\u00f6nnen, eines Mannes, der von solcher Bescheidenheit war, dass er sorgf\u00e4ltig alle Dokumente entsorgte, die seine Tugenden h\u00e4tten bekannt machen k\u00f6nnen, und der zu vermeiden suchte, dass auch nur ein Schatten seines hohen frommen Sinns nach au\u00dfen dringt; von einem, der sich denen, die es wollten, und denen, die es nicht wollten, durch die Erw\u00e4hnung seiner unz\u00e4hligen S\u00fcnden als gro\u00dfer S\u00fcnder darstellte, w\u00e4hrend er in jeder Schule und jedem Kolleg, in dem er gewesen war, stets als der Beste hochgehalten wurde, ist eine nicht nur schwierige, sondern fast unm\u00f6gliche Arbeit\u201c. Die Schwierigkeit, das tugendhafte Profil zu erfassen, h\u00e4ngt damit zusammen, dass diese Tugenden weder auff\u00e4llig waren noch durch besondere \u00e4u\u00dfere Fakten unterst\u00fctzt wurden, um Aufmerksamkeit zu erregen oder Bewunderung zu wecken.<\/p>\n\n\n\n<p><em><a href=\"https:\/\/www.donbosco.press\/de\/unsere-heiligen\/andrea-beltrami-und-sein-tugendhaftes-profil-2-2\/\">(fortsetzung)<\/a><\/em><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Der ehrw\u00fcrdige Don Andrea Beltrami (1870-1897) steht sinnbildlich f\u00fcr eine Dimension, die nicht nur&#8230;<\/p>\n","protected":false},"author":6,"featured_media":31036,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":9,"footnotes":""},"categories":[137],"tags":[2623,2555,1969,1957,2504,2023,2564,2617],"class_list":["post-31043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unsere-heiligen","tag-berufungen","tag-gott","tag-heilige","tag-salesianer","tag-charyzmat-salezjanski","tag-tugend","tag-wohltaetigkeit","tag-zeugen"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/31043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/comments?post=31043"}],"version-history":[{"count":1,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/31043\/revisions"}],"predecessor-version":[{"id":51676,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/31043\/revisions\/51676"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media\/31036"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media?parent=31043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/categories?post=31043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/tags?post=31043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}