{"id":28932,"date":"2024-06-20T07:19:01","date_gmt":"2024-06-20T07:19:01","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=28932"},"modified":"2024-06-20T07:19:18","modified_gmt":"2024-06-20T07:19:18","slug":"missionare-in-den-niederlanden","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/de\/missionen\/missionare-in-den-niederlanden\/","title":{"rendered":"Missionare in den Niederlanden"},"content":{"rendered":"\n<p><em><em>In der allgemeinen Vorstellung geht es bei den \u201eMissionen\u201c um den S\u00fcden der Welt, in Wirklichkeit liegt kein geographisches Kriterium zugrunde und Europa ist auch ein Ziel f\u00fcr Salesianer-Missionare: in diesem Artikel sprechen wir \u00fcber die Niederlande.<br\/><\/em><\/em><br\/><br\/>Als Don Bosco zwischen 1871 und 1872 von \u201eBarbaren\u201c und \u201eWilden\u201c tr\u00e4umte, wie es damals hie\u00df, von gro\u00dfer Statur und grimmigen Gesichtern, gekleidet in Tierfelle, die in einer ihm v\u00f6llig unbekannten Gegend spazieren gingen, mit Missionaren in der Ferne, in denen er seine Salesianer erkannte, konnte er die enorme Entwicklung der Salesianischen Kongregation in der Welt nicht voraussehen. F\u00fcnfunddrei\u00dfig Jahre sp\u00e4ter \u2013 18 Jahre nach seinem Tod \u2013 gr\u00fcnden die Salesianer ihre erste Provinz in Indien, und 153 Jahre sp\u00e4ter ist Indien das erste Land der Welt, was die Zahl der Salesianer betrifft. Was Don Bosco nicht ahnen konnte, ist, dass indische Salesianer nach Europa, insbesondere in die Niederlande, kommen w\u00fcrden, um als Missionare zu arbeiten und ihre Berufung zu leben und zu erfahren.<br\/><br\/>Wir treffen Don Biju Oledath sdb, geboren 1975 in Kurianad, Kerala, S\u00fcdindien. Er ist seit 1993 Salesianer und kam 1998 als Missionar in die Niederlande, nachdem er am Salesianer College in Sonada Philosophie studiert hatte. Nach seinem Praktikum schloss er sein Theologiestudium an der Katholischen Universit\u00e4t von Leuven (Belgien) ab. Im Jahr 2004 wurde er in Indien zum Priester geweiht und diente als junger Priester in der Pfarrei von Alapuzha, Kerala, bevor er im folgenden Jahr als Missionar in die Niederlande zur\u00fcckkehrte. Derzeit lebt und arbeitet er in der Salesianer-Gemeinschaft in Assel.<br\/><br\/>In Don Bijus Herzen keimte schon in jungen Jahren die Mission <em>ad gentes<\/em> und insbesondere der Wunsch, nach Afrika zu gehen, inspiriert von seinen indischen Mitbr\u00fcdern, die nach Kenia, Tansania und Uganda gingen. Dieser missionarische Traum wurde durch ihre Geschichten und all das Material, das sie schrieben, Briefe und Artikel \u00fcber die Arbeit der Salesianer in Afrika, gen\u00e4hrt. Seine Oberen waren jedoch der Meinung, dass er noch zu jung und noch nicht bereit f\u00fcr diesen Schritt sei, und auch seine Familie hielt es f\u00fcr zu gef\u00e4hrlich, ihn zu diesem Zeitpunkt zu verlassen. Don Biju erz\u00e4hlt uns: \u201eIm Nachhinein stimme ich ihnen zu: Ich musste erst meine Grundausbildung abschlie\u00dfen und ich wollte unbedingt Theologie an einer guten Universit\u00e4t studieren. Das w\u00e4re damals in diesen L\u00e4ndern nicht so einfach gewesen\u201c.<br\/><br\/>Aber wenn der missionarische Wunsch aufrichtig ist und von Gott kommt, kommt der Moment der Berufung immer: Die Berufung zum Salesianer-Missionar ist in der Tat eine Berufung im Rahmen der allgemeinen Berufung zum geweihten Leben f\u00fcr die Salesianer Don Boscos. So wurde Don Biju 1997 die Mission <em>ad gentes<\/em> in Europa, in den Niederlanden, angeboten, sicherlich ein ganz anderes Projekt als das Missionsleben in Afrika. Nach seinem Praktikum sollte er Theologie an der Katholischen Universit\u00e4t von Leuven (Belgien) studieren. \u201eIch musste einen Moment lang schlucken, aber ich war trotzdem froh, in ein neues Land aufbrechen zu k\u00f6nnen\u201c, gesteht Don Biju, der entschlossen war, die Welt um der jungen Menschen willen zu bereisen.<br\/><br\/>Es ist nicht selbstverst\u00e4ndlich, den Ort zu kennen, an den man als Missionar entsandt wird, vielleicht hat man etwas \u00fcber das Land oder eine Geschichte dar\u00fcber geh\u00f6rt. \u201eIch hatte schon von den Niederlanden geh\u00f6rt, ich wusste, dass das Land unter dem Meeresspiegel liegt, und ich hatte eine Geschichte \u00fcber ein Kind gelesen, das seinen Finger in einen Damm steckte, um eine \u00dcberschwemmung zu verhindern und so das Land zu retten. Ich machte mich sofort auf die Suche nach einem Weltatlas und hatte zun\u00e4chst einige Schwierigkeiten, das Land unter all den anderen gro\u00dfen europ\u00e4ischen L\u00e4ndern zu finden.\u201c Don Bijus Vater war dagegen, da er sich Sorgen wegen der Entfernung und der langen Reise machte, w\u00e4hrend seine Mutter ihn dr\u00e4ngte, seiner Berufung zu folgen und seinen Traum vom Gl\u00fcck zu verwirklichen.<br\/><br\/>Bevor er Europa erreichte, musste er lange warten, um ein Visum f\u00fcr die Niederlande zu erhalten. So wurde Don Biju dazu bestimmt, mit Stra\u00dfenkindern in Bangalore zu arbeiten. Mitte Dezember 1998, an einem kalten Wintertag, kam er schlie\u00dflich auf dem Amsterdamer Flughafen an, wo der Provinzial und zwei weitere Salesianer auf den indischen Missionar warteten. Der herzliche Empfang entsch\u00e4digte ihn f\u00fcr den Kulturschock, den er erlitten hatte, als er sich einem neuen Ort n\u00e4herte, der sich stark von Indien unterschied, wo es immer hei\u00df ist und viele Menschen auf der Stra\u00dfe leben. Die Enkulturation braucht Zeit, um sich daran zu gew\u00f6hnen, Dynamiken kennen zu lernen und zu verstehen, die zu Hause v\u00f6llig unbekannt sind.<br\/>Don Biju verbrachte sein erstes Jahr damit, die verschiedenen Salesianerh\u00e4user und -werke kennen zu lernen: \u201eIch habe gemerkt, dass es wirklich nette Leute gibt, und ich habe angefangen, mich an all diese neuen Eindr\u00fccke und Gewohnheiten zu gew\u00f6hnen. Die Niederlande sind nicht nur kalt und regnerisch, sondern auch sch\u00f6n, sonnig und warm. Die Salesianer waren sehr freundlich und gastfreundlich zu Don Biju und bem\u00fchten sich, dass er sich wohl und wie zu Hause f\u00fchlt. Die Art und Weise, wie die Niederl\u00e4nder ihren christlichen Glauben leben, unterscheidet sich nat\u00fcrlich sehr von der in Indien, und der Eindruck kann schockierend sein: gro\u00dfe Kirchen mit wenigen Menschen, meist \u00e4ltere Menschen, andere Lieder und Musik, ein bescheidenerer Stil. Au\u00dferdem, so Don Biju, \u201ehabe ich das Essen, die Familie, die Freunde und vor allem die N\u00e4he der jungen Salesianer in meinem Alter sehr vermisst.\u201c\u00a0 Aber je besser das Verst\u00e4ndnis f\u00fcr die Situation wird, desto mehr beginnen die Unterschiede Sinn zu machen und zu verstehen.<br\/><br\/>Um ein wirksamer Salesianer-Missionar in Europa zu sein, erfordert die Arbeit in einer s\u00e4kularisierten Gesellschaft oft Anpassungsf\u00e4higkeit, kulturelle Sensibilit\u00e4t und ein allm\u00e4hliches Verst\u00e4ndnis des lokalen Kontextes, das nicht von heute auf morgen erreicht werden kann. Diese Arbeit erfordert Geduld, Gebet, Studium und Reflexion, die dazu beitragen, den Glauben im Lichte einer neuen Kultur zu entdecken. Diese Offenheit erm\u00f6glicht den Missionaren einen sensiblen und respektvollen Dialog mit der neuen Kultur, wobei sie die Vielfalt und den Pluralismus der religi\u00f6sen Werte und Perspektiven anerkennen.<br\/>Die Missionare m\u00fcssen als M\u00e4nner des Gebets einen tief verwurzelten pers\u00f6nlichen Glauben und eine Spiritualit\u00e4t an dem Ort entwickeln, an dem sie sich befinden, und zwar angesichts der sinkenden Zahl von Religionszugeh\u00f6rigkeiten, des geringeren Interesses oder der geringeren Offenheit f\u00fcr spirituelle Fragen und des Mangels an neuen Berufungen zum religi\u00f6sen\/kirchlichen Leben.<br\/>Es besteht die gro\u00dfe Gefahr, sich in einer s\u00e4kularisierten Gesellschaft zu verlieren, in der Materialismus und Individualismus vorherrschen und das Interesse oder die Offenheit f\u00fcr spirituelle Fragen abnimmt. Wenn man nicht aufpasst, kann ein junger Missionar leicht in religi\u00f6se und spirituelle Skepsis und Gleichg\u00fcltigkeit verfallen. In all diesen Momenten ist es wichtig, einen Seelenf\u00fchrer zu haben, der einen zur richtigen Unterscheidung f\u00fchren kann.<br\/><br\/>Wie Don Biju wurden seit Beginn des neuen Jahrtausends etwa 150 Salesianer in ganz Europa ausgesandt, auf diesen Kontinent, der einer Re-Christianisierung bedarf und wo der katholische Glaube neu belebt und gest\u00e4rkt werden muss. Die Missionare sind ein Geschenk f\u00fcr die lokale Gemeinschaft, sowohl auf salesianischer als auch auf kirchlicher und gesellschaftlicher Ebene. Der Reichtum der kulturellen Vielfalt ist ein gegenseitiges Geschenk f\u00fcr diejenigen, die aufnehmen, und f\u00fcr diejenigen, die aufgenommen werden, und tr\u00e4gt dazu bei, Horizonte zu \u00f6ffnen, indem er ein \u201ekatholischeres\u201c, d.h. universelleres Gesicht der Kirche zeigt. Die Salesianer-Missionare bringen auch frischen Wind in einige Provinzen, die Schwierigkeiten haben, einen Generationswechsel zu vollziehen, bei dem die jungen Menschen immer weniger an einer Berufung zum geweihten Leben interessiert sind.<br\/><br\/>Trotz des Trends zur S\u00e4kularisierung gibt es in den Niederlanden Anzeichen f\u00fcr eine Wiederbelebung des spirituellen Interesses, insbesondere bei den j\u00fcngeren Generationen. In den letzten Jahren ist eine Offenheit gegen\u00fcber der Religiosit\u00e4t und ein R\u00fcckgang der antireligi\u00f6sen Gef\u00fchle zu beobachten. Dies \u00e4u\u00dfert sich in verschiedenen Formen, darunter alternative Formen des Kircheseins, die Erkundung alternativer spiritueller Praktiken, Achtsamkeit und die Neubewertung traditioneller religi\u00f6ser \u00dcberzeugungen. Es besteht ein zunehmender Bedarf, jungen Menschen zu helfen, da eine bedeutende Gruppe junger Menschen trotz des allgemeinen Wohlbefindens der Gesellschaft unter Einsamkeit und Depression leidet. Als Salesianer m\u00fcssen wir die Zeichen der Zeit erkennen, um den jungen Menschen nahe zu sein und ihnen zu helfen.<br\/><br\/>Wir sehen Zeichen der Hoffnung f\u00fcr die Kirche, die von den nach Europa einwandernden Christen und von den demografischen, kulturellen und lebensgeschichtlichen Ver\u00e4nderungen in vielen lokalen Gemeinschaften ausgehen. In der Salesianer-Gemeinschaft von Hassel kommen oft junge christliche Einwanderer aus dem Nahen Osten zusammen, die ihren lebendigen Glauben und ihre M\u00f6glichkeiten mitbringen und einen positiven Beitrag zu unserer Salesianer-Gemeinschaft leisten.<br\/>\u201eAll das gibt mir ein gro\u00dfartiges Gef\u00fchl und macht mir bewusst, wie gut es ist, hier arbeiten zu k\u00f6nnen, in einem f\u00fcr mich zun\u00e4chst fremden Land.\u201c<br\/><br\/>Lasst uns beten, dass der missionarische Eifer immer brennend bleiben m\u00f6ge und dass es nicht an Missionaren mangelt, die bereit sind, auf den Ruf Gottes zu h\u00f6ren, um sein Evangelium durch das einfache und aufrichtige Zeugnis des Lebens in alle Kontinente zu tragen.<br\/><br\/><br\/><em>von Marco Fulgaro<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In der allgemeinen Vorstellung geht es bei den \u201eMissionen\u201c um den S\u00fcden der Welt, in&#8230;<\/p>\n","protected":false},"author":1,"featured_media":28911,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":7,"footnotes":""},"categories":[143],"tags":[1849,1921,1891,1957,2504],"class_list":["post-28932","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-missionen","tag-interviews","tag-laender","tag-missionen","tag-salesianer","tag-charyzmat-salezjanski"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/28932","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/comments?post=28932"}],"version-history":[{"count":0,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/28932\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media\/28911"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media?parent=28932"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/categories?post=28932"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/tags?post=28932"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}