{"id":19884,"date":"2023-11-16T08:33:05","date_gmt":"2023-11-16T08:33:05","guid":{"rendered":"https:\/\/exciting-knuth.178-32-140-152.plesk.page\/?p=19884"},"modified":"2026-03-25T16:28:47","modified_gmt":"2026-03-25T16:28:47","slug":"die-salesianer-in-aserbaidschan-saemaenner-der-hoffnung","status":"publish","type":"post","link":"https:\/\/www.donbosco.press\/de\/missionen\/die-salesianer-in-aserbaidschan-saemaenner-der-hoffnung\/","title":{"rendered":"Die Salesianer in Aserbaidschan: S\u00e4m\u00e4nner der Hoffnung"},"content":{"rendered":"\n<p><em><em>Die Geschichte eines jungen Mannes, der sich f\u00fcr die Arbeit der einzigen Salesianer-Gemeinschaft in Aserbaidschan bedankt, die f\u00fcr viele junge Menschen in der Hauptstadt ein Bezugspunkt ist.<br><\/em><\/em><br>Aserbaidschan (offiziell Republik Aserbaidschan) ist ein Land in der Transkaukasusregion, das im Osten an das Kaspische Meer, im Norden an Russland, im Westen an Georgien und Armenien und im S\u00fcden an den Iran grenzt. Es hat rund 10 Millionen Einwohner, die die aserbaidschanische Sprache sprechen, die zur Familie der Turksprachen geh\u00f6rt. Der Hauptreichtum des Landes sind Erd\u00f6l und Erdgas. Es wurde 1918 unabh\u00e4ngig und war der erste s\u00e4kulare demokratische Staat mit einer muslimischen Mehrheit. Seine Unabh\u00e4ngigkeit w\u00e4hrte jedoch nur zwei Jahre, da es 1920 in die neu gegr\u00fcndete Sowjetunion eingegliedert wurde. Nach dem Zerfall des Sowjetimperiums erlangte es 1991 seine Unabh\u00e4ngigkeit zur\u00fcck. In dieser Zeit erkl\u00e4rte die haupts\u00e4chlich von Armeniern bewohnte Region Bergkarabach ihre Unabh\u00e4ngigkeit unter dem Namen Republik Artsakh, ein Ereignis, das zu mehreren Kriegen f\u00fchrte. Nach dem j\u00fcngsten Angriff Aserbaidschans am 19. September 2023, der zur Unterdr\u00fcckung der genannten Republik und zum Exodus fast aller armenischen Einwohner aus dieser Region nach Armenien f\u00fchrte, geriet die Region erneut in die internationalen Nachrichten.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Die Anwesenheit von Christen in dieser Region wird bereits in den ersten Jahrhunderten nach Christus erw\u00e4hnt. Im 4. Jahrhundert erkl\u00e4rte der kaukasische K\u00f6nig Urnayr das Christentum offiziell zur Staatsreligion, und so blieb es bis zum 8. Jahrhundert, als sich nach einem Krieg der Islam durchsetzte. Heute ist die Mehrheitsreligion der schiitisch gepr\u00e4gte Islam, und die Christen aller Konfessionen machen 2,6 % der Bev\u00f6lkerung aus.<br>Die Pr\u00e4senz der Katholiken im Land geht auf das Jahr 1882 zur\u00fcck, als eine Pfarrei gegr\u00fcndet wurde. 1915 wurde in der Hauptstadt Baku eine Kirche gebaut, die 1931 von den sowjetischen Kommunisten abgerissen wurde, wodurch die Gemeinde aufgel\u00f6st und der Pfarrer verhaftet wurde, der ein Jahr sp\u00e4ter in einem Zwangsarbeitslager starb.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"640\" src=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn-1024x640.jpg\" alt=\"\" class=\"wp-image-19874\" srcset=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn-1024x640.jpg 1024w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn-300x188.jpg 300w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn-768x480.jpg 768w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn-150x94.jpg 150w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn-696x435.jpg 696w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn-1068x668.jpg 1068w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn-672x420.jpg 672w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-3_tn.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Nach dem Fall des Kommunismus wurde die katholische Gemeinde von Baku 1997 wiedergegr\u00fcndet, und nach einem Besuch des Heiligen Papstes Johannes Paul II. in Aserbaidschan im Jahr 2002 wurde ein Grundst\u00fcck f\u00fcr den Bau einer neuen Kirche erworben, die der Unbefleckten Empf\u00e4ngnis geweiht und am 29. April 2007 eingeweiht wurde.<br><br>Die salesianische Pr\u00e4senz in Aserbaidschan wurde im Jubil\u00e4umsjahr 2000 in der Hauptstadt Baku, der gr\u00f6\u00dften Stadt des Landes mit mehr als 2 Millionen Einwohnern, er\u00f6ffnet.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Der Leiter des Salesianer-Hauses in Baku, Don Martin Bonk\u00e1lo, erz\u00e4hlt uns, dass die salesianische Mission in verschiedenen und immer neuen Kontexten verk\u00f6rpert wird, als Antwort auf die Herausforderungen und Bed\u00fcrfnisse der Jugend. Das Echo von Don Bosco ist auch in Aserbaidschan zu h\u00f6ren, in Zentralasien, einem Land mit muslimischer Mehrheit, das im letzten Jahrhundert das Sowjetregime erlebt hat.<br>Sieben Salesianer leben und arbeiten in diesem Haus, darunter f\u00fcnf Priester und zwei Koadjutoren, die der Slowakischen Ordensprovinz (SLK) angeh\u00f6ren und sich um die Pfarrei der Heiligen Maria und das Bildungszentrum \u201eMaryam\u201c k\u00fcmmern. Es handelt sich um ein Werk f\u00fcr die ganzheitliche Entwicklung junger Menschen: Evangelisierung, Katechese, Bildung und soziale Hilfe.<br>\u00dcberall im Land sind die Katholiken eine kleine Herde, die sich mit Mut und Hoffnung zu ihrem Glauben bekennt. Die Arbeit der Salesianer basiert daher auf dem Zeugnis der Liebe Gottes in verschiedenen Formen. Die Beziehungen zu den Menschen sind offen, klar und freundschaftlich: Dies beg\u00fcnstigt das Gedeihen der p\u00e4dagogischen Arbeit.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-1024x768.jpg\" alt=\"\" class=\"wp-image-19859\" srcset=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-1024x768.jpg 1024w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-300x225.jpg 300w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-768x576.jpg 768w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-150x112.jpg 150w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-696x522.jpg 696w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-560x420.jpg 560w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-80x60.jpg 80w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn-265x198.jpg 265w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-1_tn.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p>Junge Menschen sind wie alle anderen jungen Menschen auf der Welt, mit ihren \u00c4ngsten und Talenten. Ihre gr\u00f6\u00dfte Herausforderung besteht darin, eine gute Ausbildung zu erhalten, um ihren Lebensunterhalt zu verdienen. Die jungen Menschen suchen ein erzieherisches Umfeld und fachlich und menschlich kompetente Menschen, die ihnen den Weg zu vermitteln wissen, den sie gehen m\u00fcssen, um den Sinn des Lebens zu finden.<br>Die Salesianer haben sich verpflichtet, in die Zukunft zu blicken, ihre Pr\u00e4senz im Land zu bereichern, sie internationaler zu gestalten und dem von Don Bosco \u00fcbermittelten Charisma mit Freude und Begeisterung treu zu bleiben.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-1024x768.jpg\" alt=\"\" class=\"wp-image-19866\" srcset=\"https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-1024x768.jpg 1024w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-300x225.jpg 300w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-768x576.jpg 768w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-150x112.jpg 150w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-696x522.jpg 696w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-560x420.jpg 560w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-80x60.jpg 80w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn-265x198.jpg 265w, https:\/\/www.donbosco.press\/wp-content\/uploads\/2023\/11\/Salesiani-in-Azerbaigian-seminatori-di-speranza-2_tn.jpg 1067w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p>Shamil, ein ehemaliger Sch\u00fcler des Salesianer-Zentrums in Baku, erz\u00e4hlt: \u201eIch kam 2012 mit dem Maryam-Zentrum in Kontakt, und diese Begegnung erwies sich als grundlegend f\u00fcr den Rest meines Lebens. Damals hatte ich meinen Milit\u00e4rdienst absolviert und war dabei, meine Ausbildung an einem Computerinternat zu beenden. Ich musste mich beruflich weiterentwickeln, aber gleichzeitig brauchte ich dringend Freunde in der realen Welt! Ich kam aus der Provinz nach Baku und traf auf der Stra\u00dfe einen Freund, der mir vom Maryam-Zentrum erz\u00e4hlte. Also besuchten wir es gemeinsam, und von da an begann ein wunderbares Kapitel in meinem Leben. Vom ersten Tag an befand ich mich in einer anderen Welt, die nicht leicht zu erkl\u00e4ren ist, ich sage in meinem Herzen, dass es eine Insel ist.<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>Sie wurde f\u00fcr mich zu einer Insel der Menschlichkeit, in einer modernen Welt, die oft daran interessiert ist, die Menschen zu benutzen und sich nicht wirklich um sie zu k\u00fcmmern. Ohne dass ich es merkte, hatte das Programm im Jugendzentrum begonnen und ich war Teil eines Teams. Jemand spielte Volleyball, jemand Tischtennis, eine Gruppe von Jungen klimperte auf Gitarren&#8230;. Sp\u00e4ter sa\u00dfen wir in der Mensa, und jeder durfte ein Wort sagen, um seine Meinung \u00fcber den vergangenen Tag, seine Eindr\u00fccke oder neue Ideen zu \u00e4u\u00dfern. Ich war ein eher sch\u00fcchterner Typ, aber ich begann fr\u00f6hlich und ohne Schwierigkeiten oder Hemmungen \u00fcber die Ereignisse des Tages und allgemeine Themen zu sprechen. Unter den vielen Kursen des Zentrums entschied ich mich, mit dem Photoshop-Grafikkurs und dem Englischkurs zu beginnen. Als ich dann aus gesundheitlichen Gr\u00fcnden meinen Job aufgeben musste, verlor ich auch mein Dach \u00fcber dem Kopf. Die L\u00f6sung war, im Zentrum als Wachmann zu arbeiten, mit bestimmten Aufgaben und Verantwortlichkeiten. Ich war einen Monat lang in der Probezeit und bin froh, dass ich niemanden im Stich gelassen habe und ein neues Zuhause gefunden habe. Als Don Stefan 2014 mit der Entwicklung des Computernetzwerkprojekts der Cisco-Akademie im Zentrum begann, begann mein beruflicher Werdegang als Netzwerktechniker. Im gleichen Zeitraum konnte ich drei hauswirtschaftliche Berufe erlernen: Schwei\u00dfen, Elektrizit\u00e4t und Klempnerei. Im Jahr 2016 wurde ich offizieller Cisco-Ausbilder und bin nun seit sechs Jahren als Netzwerktechniker t\u00e4tig. Dieser Job hat es mir und meiner Familie erm\u00f6glicht, nach Jahren einer sehr prek\u00e4ren Lebenssituation wieder auf die Beine zu kommen. Neben meiner Arbeit gebe ich Kurse \u00fcber Computernetzwerke, bin Animateur geworden und helfe bei der Organisation von Sommercamps f\u00fcr Kinder. Ich kann Don Bosco nur dankbar sein f\u00fcr alles, was er mir im Leben gegeben hat\u201c.<br><br>Es gibt so viele Geschichten von jungen Menschen wie Shamil, denen es dank der Arbeit der Salesianer in Baku gelungen ist, ihr Leben umzukrempeln, und wir hoffen, dass diese Arbeit weiter gedeihen und fruchtbar sein wird.<br><br><br>Marco Fulgaro<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Geschichte eines jungen Mannes, der sich f\u00fcr die Arbeit der einzigen Salesianer-Gemeinschaft in Aserbaidschan&#8230;<\/p>\n","protected":false},"author":1,"featured_media":19855,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"iawp_total_views":8,"footnotes":""},"categories":[143],"tags":[1933,1993,1813,1891,1729,2504,2564,2617],"class_list":["post-19884","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-missionen","tag-arm","tag-hoffnung","tag-jugend","tag-missionen","tag-salesianerhaeuser","tag-charyzmat-salezjanski","tag-wohltaetigkeit","tag-zeugen"],"_links":{"self":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/19884","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/comments?post=19884"}],"version-history":[{"count":1,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/19884\/revisions"}],"predecessor-version":[{"id":51056,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/posts\/19884\/revisions\/51056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media\/19855"}],"wp:attachment":[{"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/media?parent=19884"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/categories?post=19884"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.donbosco.press\/de\/wp-json\/wp\/v2\/tags?post=19884"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}